{"id":12631,"date":"2014-07-10T10:31:38","date_gmt":"2014-07-10T13:31:38","guid":{"rendered":"http:\/\/www.blogdotarugao.com.br\/v1\/?p=12631"},"modified":"2014-07-08T16:33:06","modified_gmt":"2014-07-08T19:33:06","slug":"caes-defendem-crianca-de-apanhar-da-mae-e-video-bomba-na-internet","status":"publish","type":"post","link":"https:\/\/www.blogdotarugao.com.br\/v1\/2014\/07\/10\/caes-defendem-crianca-de-apanhar-da-mae-e-video-bomba-na-internet\/","title":{"rendered":"C\u00e3es defendem crian\u00e7a de apanhar da m\u00e3e e v\u00eddeo bomba na internet"},"content":{"rendered":"<p>Um v\u00eddeo hil\u00e1rio mostra como os c\u00e3es realmente tem amor a seus donos, sejam eles do tamanho que forem.<\/p>\n<p>No clipe publicado no YouTube, uma m\u00e3e aparece tentando dar uma li\u00e7\u00e3o no filho pequeno, que foge com medo de apanhar.<\/p>\n<p>A m\u00e3e tenta dar chineladas na crian\u00e7a, que, sem sa\u00edda, fica prestes a ser agredida, mas neste momento seus c\u00e3es a defendem.<\/p>\n<p>Os c\u00e3es come\u00e7am a intervir na poss\u00edvel chinelada da m\u00e3e ao filho, e at\u00e9 sobem na cama para impedi-la.<\/p>\n<p><img loading=\"lazy\" title=\"C\u00e3es defendem crian\u00e7a da m\u00e3e\" alt=\"C\u00e3es defendem crian\u00e7a da m\u00e3e\" src=\"http:\/\/www.gadoo.com.br\/wp-content\/uploads\/2014\/07\/315.jpg?ea4186\" width=\"599\" height=\"285\" \/><\/p>\n<p>C\u00e3es foram filmados intervindo em poss\u00edvel chinelada de m\u00e3e em filho, e v\u00eddeo se tornou viral na internet.<\/p>\n<p>Assista ao v\u00eddeo abaixo:<\/p>\n<p><iframe loading=\"lazy\" src=\"http:\/\/www.youtube.com\/embed\/KcakUthQ160?version=3&amp;rel=1&amp;fs=1&amp;showsearch=0&amp;showinfo=1&amp;iv_load_policy=1&amp;wmode=transparent\" height=\"380\" width=\"620\" frameborder=\"0\"><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Um v\u00eddeo hil\u00e1rio mostra como os c\u00e3es realmente tem amor a seus donos, sejam eles do tamanho que forem. No clipe publicado no YouTube, uma m\u00e3e aparece tentando dar uma li\u00e7\u00e3o no filho pequeno, que foge com medo de apanhar. A m\u00e3e tenta dar chineladas na crian\u00e7a, que, sem sa\u00edda, fica prestes a ser agredida, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_links_to":"","_links_to_target":""},"categories":[24,1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/posts\/12631"}],"collection":[{"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/comments?post=12631"}],"version-history":[{"count":1,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/posts\/12631\/revisions"}],"predecessor-version":[{"id":12632,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/posts\/12631\/revisions\/12632"}],"wp:attachment":[{"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/media?parent=12631"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/categories?post=12631"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/tags?post=12631"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}