{"id":13008,"date":"2014-07-15T09:08:34","date_gmt":"2014-07-15T12:08:34","guid":{"rendered":"http:\/\/www.blogdotarugao.com.br\/v1\/?p=13008"},"modified":"2014-07-15T09:08:34","modified_gmt":"2014-07-15T12:08:34","slug":"traficante-e-preso-e-confessa-mortes-de-soldado-da-pm-e-delegado","status":"publish","type":"post","link":"https:\/\/www.blogdotarugao.com.br\/v1\/2014\/07\/15\/traficante-e-preso-e-confessa-mortes-de-soldado-da-pm-e-delegado\/","title":{"rendered":"Traficante \u00e9 preso e confessa mortes de soldado da PM e delegado"},"content":{"rendered":"<p>Arma roubada do delegado foi usada para matar PM<\/p>\n<p>O traficante Roque Soares de Melo Filho, 30 anos,\u00a0<a title=\"Opens external link in new window\" href=\"http:\/\/www.correio24horas.com.br\/detalhe\/noticia\/apos-um-mes-internado-morre-pm-baleado-durante-troca-de-tiros-em-tancredo-neves\/?cHash=391352b2f712357a30d6fbd6818af7f7\" target=\"_blank\">foi preso pela morte do soldado PM Hamilton Gomes de Jesus, no final de maio, em Tancredo Neves<\/a>. Ele tamb\u00e9m \u00e9 respons\u00e1vel pela\u00a0<a title=\"Opens external link in new window\" href=\"http:\/\/www.correio24horas.com.br\/detalhe\/noticia\/delegado-morto-em-assalto-desarticulou-quadrilha-de-roubo-de-carro\/\" target=\"_blank\">morte do delegado Eduardo Rafael de Santana Lima, 35 anos, em novembro de 2012, no bairro do Barbalho<\/a>. Segundo a Pol\u00edcia Civil, a pistola ponto 40 roubada do delegado foi usada no crime contra o PM.<\/p>\n<p>Roque foi preso na quinta-feira (10) na avenida Paralela. A arma foi apreendida na resid\u00eancia da irm\u00e3 dele, no Alto do Cabrito. A pol\u00edcia montou uma opera\u00e7\u00e3o para prender o traficante &#8211; barreiras foram montadas para interceptar o criminoso, que ia se encontrar a companheira em uma moto. Ele foi preso e encaminhado ao Departamento de Homic\u00eddios e Prote\u00e7\u00e3o \u00e0 Pessoa (DHPP).<\/p>\n<p>&nbsp;<\/p>\n<table>\n<thead>\n<tr>\n<th scope=\"col\"><img loading=\"lazy\" alt=\"\" src=\"http:\/\/w3.c24hsttc.net\/uploads\/RTEmagicC_galego2.jpg.jpg\" width=\"441\" height=\"329\" \/><\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<td>Traficante foi preso em opera\u00e7\u00e3o especial (Foto: SSP\/BA)<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>Roque chegou a apresentar uma identidade falsa, com nome de Uelton Melo da Silva, mas foi reconhecido por policiais como um dos respons\u00e1veis pela morte do soldado Hamilton. Ele \u00e9 foragido da cadeia de Ibicu\u00ed. Em depoimento, Roque confessou a participa\u00e7\u00e3o na morte do PM e do delegado Eduardo Rafael, que era da Delegacia de Repress\u00e3o a Furtos e Roubos de Ve\u00edculos (DRFRV).<\/p>\n<p>No depoimento, Roque ainda revelou onde poderiam estar outros envolvidos no crime. Em Jau\u00e1, no Litoral Norte, houve troca de tiros com um grupo de traficantes e Juelton Reis dos Santos morreu no confronto. No Alto do Cabrito, houve outro confronto e um traficante conhecido na regi\u00e3o como Chinha tamb\u00e9m foi morto.<!--more--><\/p>\n<p>Na casa em que Juelton estava, a pol\u00edcia encontrou drogas e um rev\u00f3lver calibre 38 de numera\u00e7\u00e3o raspada.<\/p>\n<p>Os dois suspeitos mortos pela pol\u00edcia tamb\u00e9m tinha envolvimento nas mortes do PM e do delegado, segundo a investiga\u00e7\u00e3o. Um quarto envolvido na morte do delegado teria sido morto ainda em 2012 por traficantes. A pol\u00edcia n\u00e3o divulgou o nome deste \u00faltimo suspeito.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Arma roubada do delegado foi usada para matar PM O traficante Roque Soares de Melo Filho, 30 anos,\u00a0foi preso pela morte do soldado PM Hamilton Gomes de Jesus, no final de maio, em Tancredo Neves. Ele tamb\u00e9m \u00e9 respons\u00e1vel pela\u00a0morte do delegado Eduardo Rafael de Santana Lima, 35 anos, em novembro de 2012, no bairro [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_links_to":"","_links_to_target":""},"categories":[1,8],"tags":[],"_links":{"self":[{"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/posts\/13008"}],"collection":[{"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/comments?post=13008"}],"version-history":[{"count":1,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/posts\/13008\/revisions"}],"predecessor-version":[{"id":13009,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/posts\/13008\/revisions\/13009"}],"wp:attachment":[{"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/media?parent=13008"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/categories?post=13008"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/tags?post=13008"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}