{"id":15699,"date":"2014-09-01T19:58:44","date_gmt":"2014-09-01T22:58:44","guid":{"rendered":"http:\/\/www.blogdotarugao.com.br\/v1\/?p=15699"},"modified":"2014-09-01T19:58:44","modified_gmt":"2014-09-01T22:58:44","slug":"liderancas-da-base-governista-criticam-pt-e-declaram-apoio-a-souto","status":"publish","type":"post","link":"https:\/\/www.blogdotarugao.com.br\/v1\/2014\/09\/01\/liderancas-da-base-governista-criticam-pt-e-declaram-apoio-a-souto\/","title":{"rendered":"Lideran\u00e7as da base governista criticam PT e declaram apoio \u00e0 Souto"},"content":{"rendered":"<p><img loading=\"lazy\" style=\"color: #444444;\" src=\"http:\/\/www.bocaonews.com.br\/ckfinder\/userfiles\/fotos_e_imagens\/POLITICA\/BAHIA\/ELEI%C3%87%C3%95ES%202014\/001_Paulo%20Souto_Manoel%20Vitorino_foto%20Valter%20Pontes_Coperphoto.jpg\" alt=\"\" width=\"584\" height=\"364\" \/><span style=\"color: #444444;\">Em reuni\u00e3o na tarde desta segunda-feira (1), lideran\u00e7as e pol\u00edticos da base governista criticaram a administra\u00e7\u00e3o petista e declararam apoio ao candidato ao governo do estado pela coliga\u00e7\u00e3o &#8220;Unidos pela Bahia, Paulo Souto (DEM).<\/span><br style=\"color: #444444;\" \/><br style=\"color: #444444;\" \/><span style=\"color: #444444;\">Para lideran\u00e7as de Manoel Vitorino, Conde, Jita\u00fana, Gongogi, Jeremoabo, Ubaitaba, Itua\u00e7u, Barra da Estiva, Uiba\u00ed, Itamaraju, Camamu, Ribeira do Pombal, Nilo Pe\u00e7anha, Itapitanga, Barro Alto, Valente e Cocos, o governo Jaques Wagner deixou a desejar.<\/span><br style=\"color: #444444;\" \/><br style=\"color: #444444;\" \/><span style=\"color: #444444;\">De acordo com o ex-prefeito de Manoel Vitorino, Heleno Vilar (PTB), o povo baiano precisa de homens de trabalho e atitude, como Paulo Souto e Geddel. &#8220;Nossa regi\u00e3o recebia aten\u00e7\u00e3o do governo na \u00e9poca de Souto&#8221;, disse. Para a vereadora do munic\u00edpio, Marlene Costa (PCdoB), Souto tem promessas realiz\u00e1veis, nas quais ela pode confiar. &#8220;Acredito nas metas para a Bahia estabelecidas por este grupo, e n\u00e3o concordo com o plano de governo do PT&#8221;, assinalou.<\/span><br style=\"color: #444444;\" \/><br style=\"color: #444444;\" \/><span style=\"color: #444444;\">Conforme o vereador Ailton Nascimento (PCdoB), o PT frustrou a popula\u00e7\u00e3o de Manoel Vitorino. &#8220;Souto \u00e9 o mais preparado. Ele, sim, trabalhou pelo agricultor, o pequeno produtor. Eu sou presidente do Sindicato dos Trabalhadores Rurais da cidade, que tem quatro mil e quinhentos s\u00f3cios, e ningu\u00e9m tem apoio do governo. S\u00f3 nos procuram nas elei\u00e7\u00f5es, na hora de votar&#8221;, afirmou Nascimento, com o assentimento dos vereadores Antonio Ven\u00e2ncio (PR) e Marcelo Vilar (PTB).<\/span><!--more--><\/p>\n<p><br style=\"color: #444444;\" \/><span style=\"color: #444444;\">Para a lideran\u00e7a de Conde, Wilson Martins, o PT \u00e9 \u00e1rvore que n\u00e3o d\u00e1 mais fruto. &#8220;Estamos cansados de tantos desmandos na Bahia&#8221;, criticou, ao lado do ex-prefeito Jos\u00e9 Vieira Leite do Carmo e dos l\u00edderes Zez\u00e9 Lins, Antonio Carlos Batista e Geraldo Faria. &#8220;A Bahia est\u00e1 precisando de gente que saiba e goste de trabalhar. Souto \u00e9 s\u00e9rio e din\u00e2mico. E Geddel ser\u00e1 um grande representante do povo no Senado&#8221;, assinalou o ex-prefeito de Jita\u00fana, Ed\u00edsio, acompanhado dos vereadores Chico, Carlito e Anselmo.<\/span><br style=\"color: #444444;\" \/><br style=\"color: #444444;\" \/><span style=\"color: #444444;\">&#8220;A Bahia precisa de renova\u00e7\u00e3o&#8221;, disse a lideran\u00e7a pol\u00edtica de Gongogi, Ka\u00e7ulo (PTC), que reafirmou o apoio \u00e0 chapa oposicionista junto com os vereadores Adriano Mendon\u00e7a (PHC), Mois\u00e9s Jesus da Silva (PP) e Neto Quirino (PT do B). &#8220;Acredito na pol\u00edtica acolhedora de Souto, que prioriza o progresso e valoriza as potencialidades regionais, trabalhando para superar as dificuldades de cada localidade&#8221;, afirmou o tamb\u00e9m vereador Beto Leite (PCdoB).<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Em reuni\u00e3o na tarde desta segunda-feira (1), lideran\u00e7as e pol\u00edticos da base governista criticaram a administra\u00e7\u00e3o petista e declararam apoio ao candidato ao governo do estado pela coliga\u00e7\u00e3o &#8220;Unidos pela Bahia, Paulo Souto (DEM).Para lideran\u00e7as de Manoel Vitorino, Conde, Jita\u00fana, Gongogi, Jeremoabo, Ubaitaba, Itua\u00e7u, Barra da Estiva, Uiba\u00ed, Itamaraju, Camamu, Ribeira do Pombal, Nilo Pe\u00e7anha, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_links_to":"","_links_to_target":""},"categories":[14,6,21,29,1,7],"tags":[],"_links":{"self":[{"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/posts\/15699"}],"collection":[{"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/comments?post=15699"}],"version-history":[{"count":2,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/posts\/15699\/revisions"}],"predecessor-version":[{"id":15701,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/posts\/15699\/revisions\/15701"}],"wp:attachment":[{"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/media?parent=15699"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/categories?post=15699"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/tags?post=15699"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}