{"id":15989,"date":"2014-09-09T11:04:31","date_gmt":"2014-09-09T14:04:31","guid":{"rendered":"http:\/\/www.blogdotarugao.com.br\/v1\/?p=15989"},"modified":"2014-09-09T11:04:31","modified_gmt":"2014-09-09T14:04:31","slug":"campanha-de-rui-ainda-tenta-afastar-na-justica-acm-neto-de-propaganda-de-souto","status":"publish","type":"post","link":"https:\/\/www.blogdotarugao.com.br\/v1\/2014\/09\/09\/campanha-de-rui-ainda-tenta-afastar-na-justica-acm-neto-de-propaganda-de-souto\/","title":{"rendered":"Campanha de Rui ainda tenta afastar na justi\u00e7a ACM Neto de propaganda de Souto"},"content":{"rendered":"<p style=\"color: #444444;\"><img loading=\"lazy\" title=\"Reprodu\u00e7\u00e3o\" src=\"http:\/\/www.bocaonews.com.br\/ckfinder\/userfiles\/fotos_e_imagens\/paulo%20e%20ACM%20Neto.jpg\" alt=\"\" width=\"470\" height=\"262\" \/><\/p>\n<p><span style=\"color: #444444;\">O corpo jur\u00eddico da coliga\u00e7\u00e3o \u201cPra Bahia Mudar Mais\u201d, liderada pelo candidato ao governo da Bahia pelo PT, Rui Costa, ainda tenta uma ofensiva junto ao Tribunal Regional Eleitoral (TRE-BA) para vetar a imagem do prefeito de Salvador, ACM Neto (DEM), nas propagandas eleitorais na TV do postulante democrata, Paulo Souto.<\/p>\n<p>Na \u00faltima sexta-feira (5), o advogado alagoano Adriano Soares da Costa, que integra a equipe de juristas da campanha petista, afirmou que entraria com uma A\u00e7\u00e3o de Investiga\u00e7\u00e3o Judicial Eleitoral (Aije) j\u00e1 que, segundo o advogado, \u201cde modo expl\u00edcito&#8221;, o gestor soteropolitano passou a mostrar ter &#8220;simbiose&#8221; com Paulo Souto. &#8220;Um \u00e9 o outro; o outro \u00e9 o um\u201d, postou em sua p\u00e1gina do Facebook.<\/p>\n<p>Para o especialista em Legisla\u00e7\u00e3o Eleitoral, a tese que poder\u00e1 beneficiar a campanha que defende \u00e9 que a veicula\u00e7\u00e3o de propaganda institucional da prefeitura de Salvador na TV aberta beneficia o candidato oposicionista. \u201cAgora, \u00e9 a propaganda eleitoral quem diz escancaradamente. Amanh\u00e3, entro com a Aije: usando a fala de Neto e Souto: s\u00e3o um s\u00f3 e mesmo projeto, numa simbiose que pretende mostrar que votar no Souto \u00e9 votar em Neto; e vice-versa\u201d, defendeu.<\/span><\/p>\n<p style=\"color: #444444;\">\n<p><img loading=\"lazy\" src=\"http:\/\/www.bocaonews.com.br\/ckfinder\/userfiles\/fotos_e_imagens\/asdddda.jpg\" alt=\"\" width=\"482\" height=\"467\" \/><\/p>\n<p><br style=\"color: #444444;\" \/><span style=\"color: #444444;\">Entretanto, para o advogado da coliga\u00e7\u00e3o \u201cUnidos pela Bahia\u201d, Ademir Ismerim, neste per\u00edodo, apenas propagandas institucionais de \u00f3rg\u00e3os que disputam as elei\u00e7\u00f5es, como os governos federais e estaduais, est\u00e3o vetadas. \u201cA prefeitura n\u00e3o est\u00e1 proibida. Al\u00e9m disso, a lei diz que qualquer filiado ao partido pode aparecer na propaganda do DEM, assim como Lula aparece na de Rui Costa\u201d, rebateu.<\/p>\n<p>Para Ismerim, a campanha petista faz \u201cpirotecnia\u201d e deveria se preocupar com \u201ccoisas mais s\u00e9rias\u201d. \u201cA apari\u00e7\u00e3o de ACM Neto est\u00e1 incomodando eles\u201d, opinou.<\/p>\n<p>Em contato com o Tribunal Regional Eleitoral (TRE-BA), o \u00f3rg\u00e3o afirmou que ainda n\u00e3o recebeu at\u00e9 o momento nenhum pedido de uma nova a\u00e7\u00e3o de investiga\u00e7\u00e3o. No in\u00edcio de agosto, a campanha petista entrou com uma Aije que responsabilizaria o prefeito ACM Neto por abuso de poder pol\u00edtico, ao aparecer nas inser\u00e7\u00f5es de Souto. A Justi\u00e7a Eleitoral negou recurso, mas ainda n\u00e3o julgou o m\u00e9rito. A Corte ainda analisar\u00e1 se, de fato, houve abuso de poder pol\u00edtico com o uso da propaganda institucional da capital baiana em favor de Paulo Souto.\u00a0<\/span><!--more--><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O corpo jur\u00eddico da coliga\u00e7\u00e3o \u201cPra Bahia Mudar Mais\u201d, liderada pelo candidato ao governo da Bahia pelo PT, Rui Costa, ainda tenta uma ofensiva junto ao Tribunal Regional Eleitoral (TRE-BA) para vetar a imagem do prefeito de Salvador, ACM Neto (DEM), nas propagandas eleitorais na TV do postulante democrata, Paulo Souto. Na \u00faltima sexta-feira (5), [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_links_to":"","_links_to_target":""},"categories":[6,29,1,7],"tags":[],"_links":{"self":[{"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/posts\/15989"}],"collection":[{"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/comments?post=15989"}],"version-history":[{"count":1,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/posts\/15989\/revisions"}],"predecessor-version":[{"id":15990,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/posts\/15989\/revisions\/15990"}],"wp:attachment":[{"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/media?parent=15989"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/categories?post=15989"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/tags?post=15989"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}