{"id":17528,"date":"2014-10-10T10:47:45","date_gmt":"2014-10-10T13:47:45","guid":{"rendered":"http:\/\/www.blogdotarugao.com.br\/v1\/?p=17528"},"modified":"2014-10-10T10:47:45","modified_gmt":"2014-10-10T13:47:45","slug":"loira-bandida-e-presa-por-envolvimento-em-assalto","status":"publish","type":"post","link":"https:\/\/www.blogdotarugao.com.br\/v1\/2014\/10\/10\/loira-bandida-e-presa-por-envolvimento-em-assalto\/","title":{"rendered":"Loira bandida \u00e9 presa por envolvimento em assalto"},"content":{"rendered":"<div class=\"align-center\" style=\"color: #000000;\">\n<div class=\"imgNoticia clear\"><img title=\"Loira bandida \u00e9 presa por envolvimento em assalto em Feira de Santana\" src=\"http:\/\/www.bahianoticias.com.br\/fotos\/principal_noticias\/161614\/xIMAGEM_NOTICIA_5.jpg.pagespeed.ic.7trJqwDPfj.jpg\" alt=\"Loira bandida \u00e9 presa por envolvimento em assalto em Feira de Santana\" data-pagespeed-onload=\"pagespeed.CriticalImages.checkImageForCriticality(this);\" data-pagespeed-loaded=\"1\" \/><\/p>\n<div class=\"tooltip-text\" style=\"font-weight: bold; color: #ffffff;\">Foto: Reprodu\u00e7\u00e3o<\/div>\n<\/div>\n<div class=\"clear\"><\/div>\n<\/div>\n<div class=\"editor clear\" style=\"color: #444444;\">Uma jovem de 25 anos foi presa em flagrante acusada de envolvimento em um assalto e encaminhada para o Conjunto Penal de Feira de Santana na noite de quarta-feira (8). Raissa do Carmo Marques Menezes e um adolescente de 17 anos foram capturados por policiais militares ap\u00f3s uma persegui\u00e7\u00e3o iniciada no bairro Santo Ant\u00f4nio dos Prazeres. Os suspeitos foram localizados depois que a v\u00edtima acionou a Central de Opera\u00e7\u00f5es da PM e informou sobre o roubo. Ela conduzia um ve\u00edculo Fiat Punto vermelho, durante a persegui\u00e7\u00e3o. O adolescente, segundo a pol\u00edcia, anunciava o assalto com um rev\u00f3lver calibre 32. Com eles foram encontrados uma bolsa e v\u00e1rios celulares e documentos.<\/div>\n<p><!--more--><\/p>\n<div class=\"editor clear\" style=\"color: #444444;\">Informa\u00e7\u00f5es Acorda Cidade.<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Foto: Reprodu\u00e7\u00e3o Uma jovem de 25 anos foi presa em flagrante acusada de envolvimento em um assalto e encaminhada para o Conjunto Penal de Feira de Santana na noite de quarta-feira (8). Raissa do Carmo Marques Menezes e um adolescente de 17 anos foram capturados por policiais militares ap\u00f3s uma persegui\u00e7\u00e3o iniciada no bairro Santo [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_links_to":"","_links_to_target":""},"categories":[14,6,21,1,8],"tags":[],"_links":{"self":[{"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/posts\/17528"}],"collection":[{"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/comments?post=17528"}],"version-history":[{"count":1,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/posts\/17528\/revisions"}],"predecessor-version":[{"id":17529,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/posts\/17528\/revisions\/17529"}],"wp:attachment":[{"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/media?parent=17528"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/categories?post=17528"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/tags?post=17528"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}