{"id":17537,"date":"2014-10-10T20:35:17","date_gmt":"2014-10-10T23:35:17","guid":{"rendered":"http:\/\/www.blogdotarugao.com.br\/v1\/?p=17537"},"modified":"2014-10-10T20:38:04","modified_gmt":"2014-10-10T23:38:04","slug":"tse-acata-pedido-de-liminar-de-herzem-gusmao-e-suspende-cassacao-do-registro-de-candidatura","status":"publish","type":"post","link":"https:\/\/www.blogdotarugao.com.br\/v1\/2014\/10\/10\/tse-acata-pedido-de-liminar-de-herzem-gusmao-e-suspende-cassacao-do-registro-de-candidatura\/","title":{"rendered":"TSE acata pedido de liminar de Herzem Gusm\u00e3o e suspende cassa\u00e7\u00e3o do registro de candidatura"},"content":{"rendered":"<p style=\"color: #000000;\"><img class=\"aligncenter\" src=\"http:\/\/www.tribunadaconquista.com.br\/v1\/wp-content\/uploads\/2014\/08\/foto-herzem31.jpg\" alt=\"foto herzem3\" \/><\/p>\n<p style=\"color: #000000;\">O Tribunal Superior Eleitoral (TSE) acatou o pedido de liminar suspensiva da cassa\u00e7\u00e3o do registro de candidatura do candidato Herzem Gusm\u00e3o (PMDB). A decis\u00e3o da Ministra Luciana L\u00f3ssio coloca o pol\u00edtico entre os 63 deputados estaduais eleitos na Bahia, nas elei\u00e7\u00f5es 2014.<\/p>\n<p style=\"color: #000000;\">A decis\u00e3o foi divulgada no in\u00edcio da noite desta sexta-feira (10). Confira abaixo a decis\u00e3o da relatora:<\/p>\n<p style=\"color: #000000;\"><strong><em>\u201cA liminar deve ser deferida, pois a leitura do ac\u00f3rd\u00e3o regional est\u00e1 a indicar a necessidade de a quest\u00e3o ser detidamente analisada nesta inst\u00e2ncia, sobretudo para que se chegue a uma conclus\u00e3o segura sobre a gravidade da conduta descrita nos autos, sem a qual n\u00e3o h\u00e1 falar na inelegibilidade decorrente do disposto no inciso XIV do artigo 22 da Lei Complementar n. 64\/90.<\/em><\/strong><\/p>\n<p style=\"color: #000000;\"><strong><em>Ante o exposto e com suped\u00e2neo no art. 26-C da LC n. 64\/90, defiro a liminar, para suspender os efeitos do ac\u00f3rd\u00e3o n. 669\/2014 do TRE\/BA, at\u00e9 ulterior delibera\u00e7\u00e3o do Tribunal Superior Eleitoral.\u201d<\/em><\/strong><\/p>\n<p style=\"color: #000000;\"><img class=\"aligncenter\" src=\"https:\/\/fbcdn-sphotos-f-a.akamaihd.net\/hphotos-ak-xpa1\/v\/t1.0-9\/1011268_601425369983740_5553417374434034583_n.png?oh=e83f05307646eeedebf485df94c321a4&amp;oe=54AB8D73&amp;__gda__=1420453454_62c185fa277bf03ccc7cab059949ad70\" alt=\"\" \/><\/p>\n<p style=\"color: #000000;\">Ao receber a not\u00edcia, Herzem afirmou que esta \u00e9 uma vit\u00f3ria da democracia: \u201cA decis\u00e3o da Justi\u00e7a corresponde ao que j\u00e1 vinha sendo divulgado nos \u00faltimos meses por nossa campanha. Eu sempre acreditei na Justi\u00e7a e acredito que, da mesma forma que alcan\u00e7amos esta liminar, teremos uma decis\u00e3o favor\u00e1vel e correta dos processos que meus inimigos pol\u00edticos est\u00e3o movendo contra mim.\u201d. Herzem fez quest\u00e3o de salientar que \u201cnunca cometi nenhum ato irregular, para sofrer tal persegui\u00e7\u00e3o. Meu \u00fanico defeito, se \u00e9 que isso \u00e9 defeito, foi sempre defender minha terra e lutar contra o sil\u00eancio da omiss\u00e3o que impera entre nossos atuais representantes.\u201d<\/p>\n<p style=\"color: #000000;\">Com a decis\u00e3o, o Tribunal Regional Eleitoral da Bahia (TRE-BA) ter\u00e1 que refazer os c\u00e1lculos para definir a nova composi\u00e7\u00e3o da Assembleia Legislativa da Bahia nos pr\u00f3ximos quatro anos. Herzem conquistou 40. 876 votos, o que o credencia a ocupar a 24\u00ba cadeira da coliga\u00e7\u00e3o \u201cUnidos para uma Bahia Melhor\u201d.<\/p>\n<p style=\"color: #000000;\"><img class=\"aligncenter\" src=\"http:\/\/static.blogdaresenhageral.com.br\/wp-content\/uploads\/2014\/10\/DSC_2349.jpg?150b87\" alt=\"\" \/><\/p>\n<p style=\"color: #000000;\"><em><strong>Ascom Hezem Gusm\u00e3o<\/strong><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Tribunal Superior Eleitoral (TSE) acatou o pedido de liminar suspensiva da cassa\u00e7\u00e3o do registro de candidatura do candidato Herzem Gusm\u00e3o (PMDB). A decis\u00e3o da Ministra Luciana L\u00f3ssio coloca o pol\u00edtico entre os 63 deputados estaduais eleitos na Bahia, nas elei\u00e7\u00f5es 2014. A decis\u00e3o foi divulgada no in\u00edcio da noite desta sexta-feira (10). Confira abaixo [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_links_to":"","_links_to_target":""},"categories":[6,21,29,7],"tags":[],"_links":{"self":[{"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/posts\/17537"}],"collection":[{"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/comments?post=17537"}],"version-history":[{"count":3,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/posts\/17537\/revisions"}],"predecessor-version":[{"id":17540,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/posts\/17537\/revisions\/17540"}],"wp:attachment":[{"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/media?parent=17537"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/categories?post=17537"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/tags?post=17537"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}