{"id":18811,"date":"2014-11-09T15:55:44","date_gmt":"2014-11-09T18:55:44","guid":{"rendered":"http:\/\/www.blogdotarugao.com.br\/v1\/?p=18811"},"modified":"2014-11-09T15:55:44","modified_gmt":"2014-11-09T18:55:44","slug":"tecnica-que-ressuscita-mortos-pode-comecar-a-ser-feita-em-humanos","status":"publish","type":"post","link":"https:\/\/www.blogdotarugao.com.br\/v1\/2014\/11\/09\/tecnica-que-ressuscita-mortos-pode-comecar-a-ser-feita-em-humanos\/","title":{"rendered":"T\u00e9cnica que &#8220;ressuscita&#8221; mortos pode come\u00e7ar a ser feita em humanos"},"content":{"rendered":"<div class=\"media_box full-dimensions460x305\" style=\"color: #000000;\">\n<div class=\"edges\"><\/div>\n<div class=\"edges\"><\/div>\n<div class=\"edges\"><\/div>\n<div class=\"edges\"><\/div>\n<div class=\"edges\"><a href=\"http:\/\/www.blogdotarugao.com.br\/v1\/wp-content\/uploads\/2014\/11\/ressussitar.png\"><span style=\"color: #000000;\">Resfriamento do corpo poder\u00e1 dar tempo para m\u00e9dicos corrigirem ferimentos graves<\/span><img loading=\"lazy\" class=\"aligncenter size-full wp-image-18812\" src=\"http:\/\/www.blogdotarugao.com.br\/v1\/wp-content\/uploads\/2014\/11\/ressussitar.png\" alt=\"ressussitar\" width=\"460\" height=\"305\" srcset=\"https:\/\/www.blogdotarugao.com.br\/v1\/wp-content\/uploads\/2014\/11\/ressussitar.png 460w, https:\/\/www.blogdotarugao.com.br\/v1\/wp-content\/uploads\/2014\/11\/ressussitar-300x198.png 300w\" sizes=\"(max-width: 460px) 100vw, 460px\" \/><\/a><\/div>\n<div class=\"content_image\"><span class=\"legend_box  \">Com resfriamento, atividade celular do corpo chega a quase zero<\/span><\/div>\n<\/div>\n<p style=\"color: #000000;\">M\u00e9dicos da Universidade de Maryland, nos Estados Unidos, desenvolveram uma t\u00e9cnica chamada de \u201canima\u00e7\u00e3o suspensa\u201d que poderia salvar vida de pessoas que sofrem traumas graves no corpo, como ferimentos de balas ou cortes profundos. A informa\u00e7\u00e3o \u00e9 do Daily Mail desta sexta-feira (7).<\/p>\n<p style=\"color: #000000;\">Na t\u00e9cnica, todo o sangue do paciente \u00e9 retirado e substituido por um soro gelado, que resfria o corpo a cerca de 10\u00b0C e para a atividade celular.<\/p>\n<p style=\"color: #000000;\">Depois de resolver o o problema do paciente, o sangue volta a ser bombeado, reaquecendo lentamente o sistema. Quando a temperatura do sangue chega a 30\u00baC, o cora\u00e7\u00e3o volta a bater.<\/p>\n<p style=\"color: #000000;\">Segundo Peter Rhee, um dos l\u00edderes do procedimento revolucion\u00e1rio, explica que quando o corpo est\u00e1 em sua temperatura normal, as c\u00e9lulas precisam de um forte suprimento de oxig\u00eanio, o que significa que se o cora\u00e7\u00e3o parar de bater, a pessoa vai morrer rapidamente.<\/p>\n<p style=\"color: #000000;\">\u2015 No entanto, se a temperatura do corpo foi reduzida, \u00e9 necess\u00e1rio menos de oxig\u00eanio e isso pode dar mais tempo aos m\u00e9dicos para agirem.<\/p>\n<p style=\"color: #000000;\">Segundo informa\u00e7\u00f5es da BBC Brasil, o procedimento j\u00e1 foi testado com animais. Os animais submetidos a esse teste tiveram poucos efeitos colaterais ao despertar. De acordo com outro cientista envolvido na pesquisa Samuel Tisherman, eles ficam um pouco grogue por um tempo, mas no dia seguinte j\u00e1 est\u00e3o bem&#8221;.<\/p>\n<p style=\"color: #000000;\">Ainda de acordo com a BBC Brasil, Tisherman causou um frisson quando anunciou que est\u00e1 pronto para fazer testes com humanos. As primeiras cobaias seriam v\u00edtimas de armas de fogo em Pittsburgh, na Pensilv\u00e2nia. Nesse casos, s\u00e3o pacientes cujos cora\u00e7\u00f5es j\u00e1 pararam de bater e que n\u00e3o teriam mais chances de sobreviver, pelas t\u00e9cnicas convencionais.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Resfriamento do corpo poder\u00e1 dar tempo para m\u00e9dicos corrigirem ferimentos graves Com resfriamento, atividade celular do corpo chega a quase zero M\u00e9dicos da Universidade de Maryland, nos Estados Unidos, desenvolveram uma t\u00e9cnica chamada de \u201canima\u00e7\u00e3o suspensa\u201d que poderia salvar vida de pessoas que sofrem traumas graves no corpo, como ferimentos de balas ou cortes profundos. [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_links_to":"","_links_to_target":""},"categories":[17,1,12],"tags":[],"_links":{"self":[{"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/posts\/18811"}],"collection":[{"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/comments?post=18811"}],"version-history":[{"count":1,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/posts\/18811\/revisions"}],"predecessor-version":[{"id":18813,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/posts\/18811\/revisions\/18813"}],"wp:attachment":[{"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/media?parent=18811"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/categories?post=18811"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/tags?post=18811"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}