{"id":18814,"date":"2014-11-09T16:04:59","date_gmt":"2014-11-09T19:04:59","guid":{"rendered":"http:\/\/www.blogdotarugao.com.br\/v1\/?p=18814"},"modified":"2014-11-09T16:04:59","modified_gmt":"2014-11-09T19:04:59","slug":"ex-gala-da-globo-eduardo-tornaghi-trabalha-na-rua-e-diz-sentir-falta-da-tv","status":"publish","type":"post","link":"https:\/\/www.blogdotarugao.com.br\/v1\/2014\/11\/09\/ex-gala-da-globo-eduardo-tornaghi-trabalha-na-rua-e-diz-sentir-falta-da-tv\/","title":{"rendered":"Ex-gal\u00e3 da Globo, Eduardo Tornaghi trabalha na rua e diz sentir falta da TV"},"content":{"rendered":"<div class=\"imagem-representativa imagem-615x300\">\n<ul style=\"font-weight: inherit; font-style: inherit;\">\n<li style=\"font-weight: inherit; font-style: inherit;\"><img loading=\"lazy\" class=\"imagem\" style=\"font-weight: inherit; font-style: inherit;\" title=\"Reprodu\u00e7\u00e3o\/Caras.com.br\" src=\"http:\/\/imguol.com\/c\/entretenimento\/2014\/11\/09\/9nov2014---eduardo-tornaghi-1415553191874_615x300.jpg\" alt=\"Ex-gal\u00e3 da Globo disse que sente muita falta da TV\" width=\"600\" height=\"300\" \/>\n<p style=\"font-weight: bold; font-style: inherit;\">Ex-gal\u00e3 da Globo disse que sente muita falta da TV<\/p>\n<\/li>\n<\/ul>\n<\/div>\n<p>O ex-gal\u00e3 Eduardo Tornaghi, que ficou famoso em novelas da Globo na d\u00e9cada de 80, disse sentir muita falta da TV, mas n\u00e3o falou sobre a pretens\u00e3o de voltar. Atualmente, o ator trabalha nas ruas da zona sul do Rio de Janeiro, onde vive com a esposa e os filhos.<\/p>\n<p>&#8220;Ah, sinto muita falta. Televis\u00e3o \u00e9 uma droga. D\u00e1 s\u00edndrome de abstin\u00eancia e tudo&#8221;,\u00a0disse o ator, sob gargalhadas, em entrevista exibida pelo &#8220;Domingo Show&#8221;, da TV Record, na tarde deste domingo (9). &#8220;N\u00e3o me achava bonito. Eu achava que tinha um rosto meio feminino. Os olhos azuis foram o meu ganha p\u00e3o&#8221;, acrescentou.<\/p>\n<p>Ap\u00f3s destratar um casal de idosas, que eram as suas f\u00e3s, Tornaghi disse ter parado e pensado em rela\u00e7\u00e3o ao futuro. O ator decidiu, ent\u00e3o, recusar um contrato da Globo e viajar pelo Brasil (interior do Rio Grande do Sul, Mato Grosso e Acre). &#8220;Teve uma hora que eu percebi que quem tem tudo, n\u00e3o tem nada&#8221;, contou.<\/p>\n<p>&#8220;A minha sa\u00edda da televis\u00e3o \u00e9 porque a gente busca realiza\u00e7\u00e3o na vida. A felicidade da gente n\u00e3o est\u00e1 em nada fora, est\u00e1 no lado de dentro da gente. \u00c9 muito legal ser famoso, trabalhar na televis\u00e3o, mas o pre\u00e7o acaba sendo muito caro&#8221;, avaliou o veterano. &#8220;[As pessoas me] reconhecem. Hoje em dia de uma tamanho bem palat\u00e1vel. Quando reconhecem, isso demonstra para mim que eu fui um artista de verdade. Significa que voc\u00ea fez arte de verdade&#8221;, afirmou.<\/p>\n<p>Luiza Tom\u00e9, que foi namorada de Tornaghi, falou ao programa sobre o rela\u00e7\u00e3o e o in\u00edcio do namoro entre os dois. &#8220;Eu o conheci em uma grava\u00e7\u00e3o, no comecinho da minha carreira. Um dia, me chamaram para fazer uma cena com esse rapaz. Eu o achava muito lindo. Me disseram &#8216;voc\u00ea vai fazer a namorada dele&#8217;. Eu confesso que, ali, me senti perdidamente apaixonada por ele, como homem. Ele foi um grande amor da minha vida.<\/p>\n<p>&#8220;Namoramos 7 anos. Fui muito feliz [ao lado dele], mas terminou porque o tempo nos transforma. Est\u00e1vamos em movimentos diferentes&#8221;, confessou Luiza Tom\u00e9.<\/p>\n<p>O ex-gal\u00e3 participou de 22 de novelas, dentre elas, &#8220;A Gata Comeu&#8221; e &#8220;Dancin&#8217;Days&#8221;. Tornaghi ficou afastado da TV por quase duas d\u00e9cadas, tendo voltado em uma participa\u00e7\u00e3o na s\u00e9rie &#8220;Carga Pesada&#8221;, em 2006, na Globo, e em &#8220;Uma Rosa com Amor&#8221;, do SBT, em 2010.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ex-gal\u00e3 da Globo disse que sente muita falta da TV O ex-gal\u00e3 Eduardo Tornaghi, que ficou famoso em novelas da Globo na d\u00e9cada de 80, disse sentir muita falta da TV, mas n\u00e3o falou sobre a pretens\u00e3o de voltar. Atualmente, o ator trabalha nas ruas da zona sul do Rio de Janeiro, onde vive com [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_links_to":"","_links_to_target":""},"categories":[21,1,34],"tags":[],"_links":{"self":[{"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/posts\/18814"}],"collection":[{"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/comments?post=18814"}],"version-history":[{"count":1,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/posts\/18814\/revisions"}],"predecessor-version":[{"id":18815,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/posts\/18814\/revisions\/18815"}],"wp:attachment":[{"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/media?parent=18814"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/categories?post=18814"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/tags?post=18814"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}