{"id":19407,"date":"2014-11-20T09:25:58","date_gmt":"2014-11-20T12:25:58","guid":{"rendered":"http:\/\/www.blogdotarugao.com.br\/v1\/?p=19407"},"modified":"2014-11-20T16:32:32","modified_gmt":"2014-11-20T19:32:32","slug":"mais-um-grave-acidente-na-avenida-da-morte-mototaxista-fratura-femo-em-dois-lugares-e-passageira-sofre-varias-escoriacaoes","status":"publish","type":"post","link":"https:\/\/www.blogdotarugao.com.br\/v1\/2014\/11\/20\/mais-um-grave-acidente-na-avenida-da-morte-mototaxista-fratura-femo-em-dois-lugares-e-passageira-sofre-varias-escoriacaoes\/","title":{"rendered":"MAIS UM GRAVE ACIDENTE NA AVENIDA DA MORTE: MOTOTAXISTA FRATURA F\u00caMUR EM DOIS LUGARES E PASSAGEIRA SOFRE V\u00c1RIAS ESCORIA\u00c7\u00d5ES"},"content":{"rendered":"<p><img loading=\"lazy\" src=\"https:\/\/fbcdn-sphotos-h-a.akamaihd.net\/hphotos-ak-xap1\/v\/t1.0-9\/1609932_603771303084310_7368721339100809115_n.jpg?oh=a756e6329b36097ae4e7ae63f9193192&amp;oe=54D5F737&amp;__gda__=1428009342_4ef32a3de94739305b131f228b7cbf1a\" alt=\"\" width=\"575\" height=\"431\" \/><\/p>\n<p>Na manh\u00e3 desta quinta-feira (20) por volta de 08:20 horas, mais um grave acidente foi registrado na Avenida J\u00falio Jos\u00e9 Rodrigues &#8220;Avenida da Morte&#8221;, segundo populares, um ve\u00edculo Renalt Duster placa de Vit\u00f3ria da Conquista e um Mototaxista da Rodo-T\u00e1xi Moto Service \u00a0seguiam sentido rodovi\u00e1ria\/Vilas.<\/p>\n<p><img loading=\"lazy\" src=\"https:\/\/scontent-b-gru.xx.fbcdn.net\/hphotos-xpa1\/v\/t1.0-9\/10685736_603771466417627_5409958531506721688_n.jpg?oh=ac57aeeae2ff5ceac37d07921eb76004&amp;oe=5515010B\" alt=\"\" width=\"575\" height=\"431\" \/><\/p>\n<p>No impacto da colis\u00e3o, o Mototaxista Anderson silva Carvalho de 34 anos<span style=\"color: #555555;\">,<\/span>\u00a0 e a passageira Renata dos Santos \u00a0Correia tamb\u00e9m de 34 anos e moradora da cidade de Caatiba <span style=\"color: #555555;\">,<\/span>\u00a0foram lan\u00e7ados ao ch\u00e3o, na queda a passageira sofreu algumas escoria\u00e7\u00f5es. J\u00e1 o Mototaxista, tomou uma forte pancada no joelho e existe uma suspeita de fraturas no f\u00eamur.<\/p>\n<p><img loading=\"lazy\" src=\"http:\/\/www.blogdotarugao.com.br\/v1\/wp-content\/uploads\/2014\/11\/acidente1.jpg\" alt=\"acidente1\" width=\"580\" height=\"435\" \/><\/p>\n<p>Agentes da COMUTRAN esteveram no local, sinalizaram a \u00e1rea do acidente, organizaram o tr\u00e2nsito e ajudaram nos primeiros socorros.<\/p>\n<p><img loading=\"lazy\" src=\"https:\/\/fbcdn-sphotos-f-a.akamaihd.net\/hphotos-ak-xfp1\/v\/t1.0-9\/10801524_603771533084287_6327292686154753917_n.jpg?oh=9bd312a82a329f567fc73bce575c6680&amp;oe=5514E05B&amp;__gda__=1427381202_0371d3701af6e8ee82654d3db70bf225\" alt=\"\" width=\"580\" height=\"435\" \/><\/p>\n<p><img loading=\"lazy\" src=\"https:\/\/fbcdn-sphotos-c-a.akamaihd.net\/hphotos-ak-xaf1\/v\/t1.0-9\/1454888_603771649750942_8869751399785531990_n.jpg?oh=7cb72cf95b6caff2b46b8e46da5a84b3&amp;oe=5516728C&amp;__gda__=1423293170_a78c4727856c0bf44d489cbc7030ce11\" alt=\"\" width=\"581\" height=\"435\" \/><\/p>\n<p><img loading=\"lazy\" src=\"https:\/\/fbcdn-sphotos-f-a.akamaihd.net\/hphotos-ak-xfp1\/v\/t1.0-9\/1424540_603771709750936_8272868373473822259_n.jpg?oh=c46e93940356c5eb54a3e4c948e64f38&amp;oe=551C79B2&amp;__gda__=1428084521_38be0c338dbece175b5706ef87880fad\" alt=\"\" width=\"585\" height=\"439\" \/><\/p>\n<p>O SAMU 192 foi acionado, conversou com os feridos e prestou os primeiros socorros, as v\u00edtimas foram imobilizadas e levadas ao Hospital Cristo Redentor\/Funda\u00e7\u00e3o Jos\u00e9 Silveira.<img loading=\"lazy\" src=\"https:\/\/fbcdn-sphotos-b-a.akamaihd.net\/hphotos-ak-xpf1\/v\/t1.0-9\/1506069_603771806417593_6339599730158179734_n.jpg?oh=54b639c03a5337cadefbe514b0013046&amp;oe=551B8E9C&amp;__gda__=1423763549_e5f6fba998c19934117f971b8567a3f9\" alt=\"\" width=\"589\" height=\"442\" \/><\/p>\n<p><img loading=\"lazy\" src=\"https:\/\/fbcdn-sphotos-h-a.akamaihd.net\/hphotos-ak-xpa1\/v\/t1.0-9\/10568942_603771896417584_3262650745564038193_n.jpg?oh=f2e45d6789f51b238fb7dcd487585b38&amp;oe=54D1E304&amp;__gda__=1427250364_5ca6c84cbc023260064d8dfe09372c96\" alt=\"\" width=\"590\" height=\"442\" \/><\/p>\n<p>O Renalt Duster e a Moto Yamaha est\u00e3o no p\u00e1tio do Complexo Policcial a disposi\u00e7\u00e3o da Per\u00edcia.<\/p>\n<p><strong>Por Eliomar Barreira<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Na manh\u00e3 desta quinta-feira (20) por volta de 08:20 horas, mais um grave acidente foi registrado na Avenida J\u00falio Jos\u00e9 Rodrigues &#8220;Avenida da Morte&#8221;, segundo populares, um ve\u00edculo Renalt Duster placa de Vit\u00f3ria da Conquista e um Mototaxista da Rodo-T\u00e1xi Moto Service \u00a0seguiam sentido rodovi\u00e1ria\/Vilas. No impacto da colis\u00e3o, o Mototaxista Anderson silva Carvalho de [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_links_to":"","_links_to_target":""},"categories":[28,2,1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/posts\/19407"}],"collection":[{"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/comments?post=19407"}],"version-history":[{"count":12,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/posts\/19407\/revisions"}],"predecessor-version":[{"id":19446,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/posts\/19407\/revisions\/19446"}],"wp:attachment":[{"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/media?parent=19407"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/categories?post=19407"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/tags?post=19407"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}