{"id":19695,"date":"2014-11-26T06:21:55","date_gmt":"2014-11-26T09:21:55","guid":{"rendered":"http:\/\/www.blogdotarugao.com.br\/v1\/?p=19695"},"modified":"2014-11-25T19:25:10","modified_gmt":"2014-11-25T22:25:10","slug":"novo-sac-de-itabuna-sera-inaugurado-em-dezembro","status":"publish","type":"post","link":"https:\/\/www.blogdotarugao.com.br\/v1\/2014\/11\/26\/novo-sac-de-itabuna-sera-inaugurado-em-dezembro\/","title":{"rendered":"Novo SAC de Itabuna ser\u00e1 inaugurado em dezembro"},"content":{"rendered":"<p><a href=\"http:\/\/www.blogdotarugao.com.br\/v1\/wp-content\/uploads\/2014\/11\/SAC.jpg\" class=\"gallery_colorbox\"><img loading=\"lazy\" class=\"aligncenter  wp-image-19696\" src=\"http:\/\/www.blogdotarugao.com.br\/v1\/wp-content\/uploads\/2014\/11\/SAC.jpg\"  alt=\"SAC\" width=\"544\" height=\"364\" \/><\/a>O novo SAC de Itabuna ser\u00e1 inaugurado em dezembro, ap\u00f3s a conclus\u00e3o dos ajustes t\u00e9cnicos, conforme assegurou ao Pimenta o governador eleito da Bahia, Rui Costa, por meio do Twitter. \u201cFaltam alguns detalhes para a inaugura\u00e7\u00e3o. At\u00e9 o final do ano a popula\u00e7\u00e3o ter\u00e1 o servi\u00e7o \u00e0 disposi\u00e7\u00e3o\u201d, disse ele.<\/p>\n<p>A unidade itabunense do SAC funcionar\u00e1 no piso superior do Shopping Jequitib\u00e1, na Avenida Aziz Maron (Beira-Rio). As obras come\u00e7aram primeiro semestre deste ano. A parte f\u00edsica est\u00e1 pronta h\u00e1 mais de 30 dias. O governador Jaques Wagner teria anunciado a inaugura\u00e7\u00e3o para outubro, mas houve atraso no cronograma.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O novo SAC de Itabuna ser\u00e1 inaugurado em dezembro, ap\u00f3s a conclus\u00e3o dos ajustes t\u00e9cnicos, conforme assegurou ao Pimenta o governador eleito da Bahia, Rui Costa, por meio do Twitter. \u201cFaltam alguns detalhes para a inaugura\u00e7\u00e3o. At\u00e9 o final do ano a popula\u00e7\u00e3o ter\u00e1 o servi\u00e7o \u00e0 disposi\u00e7\u00e3o\u201d, disse ele. A unidade itabunense do SAC [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_links_to":"","_links_to_target":""},"categories":[6,30,1,7],"tags":[],"_links":{"self":[{"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/posts\/19695"}],"collection":[{"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/comments?post=19695"}],"version-history":[{"count":1,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/posts\/19695\/revisions"}],"predecessor-version":[{"id":19697,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/posts\/19695\/revisions\/19697"}],"wp:attachment":[{"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/media?parent=19695"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/categories?post=19695"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/tags?post=19695"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}