{"id":35474,"date":"2015-07-07T07:29:04","date_gmt":"2015-07-07T10:29:04","guid":{"rendered":"http:\/\/www.blogdotarugao.com.br\/v1\/?p=35474"},"modified":"2015-07-07T07:37:36","modified_gmt":"2015-07-07T10:37:36","slug":"assista-neymar-e-filmado-in-agua-por-amigos-em-festa-junina","status":"publish","type":"post","link":"https:\/\/www.blogdotarugao.com.br\/v1\/2015\/07\/07\/assista-neymar-e-filmado-in-agua-por-amigos-em-festa-junina\/","title":{"rendered":"Assista: Neymar \u00e9 filmado \u201cIn \u00c1gua\u201d por amigos em festa junina"},"content":{"rendered":"<section class=\"interna\">\n<article class=\"clearfix\">\n<div class=\"editor clearfix\">\n<p><a href=\"http:\/\/www.blogdotarugao.com.br\/v1\/wp-content\/uploads\/2015\/07\/neymar.jpg\" class=\"gallery_colorbox\"><img loading=\"lazy\" class=\"alignleft  wp-image-35475\" src=\"http:\/\/www.blogdotarugao.com.br\/v1\/wp-content\/uploads\/2015\/07\/neymar.jpg\"  alt=\"neymar\" width=\"582\" height=\"728\" srcset=\"https:\/\/www.blogdotarugao.com.br\/v1\/wp-content\/uploads\/2015\/07\/neymar.jpg 640w, https:\/\/www.blogdotarugao.com.br\/v1\/wp-content\/uploads\/2015\/07\/neymar-240x300.jpg 240w\" sizes=\"(max-width: 582px) 100vw, 582px\" \/><\/a><\/p>\n<h3 style=\"text-align: justify;\">Ap\u00f3s a disputa da Copa Am\u00e9rica, o craque do Barcelona, Neymar est\u00e1 curtindo as f\u00e9rias com toda anima\u00e7\u00e3o. O fim de semana do jogador brasileiro foi bastante animado. Um v\u00eddeo que circula nesta segunda-feira (6) nas redes sociais mostra Neymar \u201cem alta\u201d cambaleante em um final de festa junina na casa dele em Guaruj\u00e1. Uma amiga dele diz: \u201cN\u00e3o consegue parar em p\u00e9\u201d, disse.<\/h3>\n<h3 style=\"text-align: justify;\">Assista:<\/h3>\n<p align=\"center\"><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/Vid4_YwET5U\" width=\"582\" height=\"436\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<\/div>\n<\/article>\n<\/section>\n","protected":false},"excerpt":{"rendered":"<p>Ap\u00f3s a disputa da Copa Am\u00e9rica, o craque do Barcelona, Neymar est\u00e1 curtindo as f\u00e9rias com toda anima\u00e7\u00e3o. O fim de semana do jogador brasileiro foi bastante animado. Um v\u00eddeo que circula nesta segunda-feira (6) nas redes sociais mostra Neymar \u201cem alta\u201d cambaleante em um final de festa junina na casa dele em Guaruj\u00e1. Uma [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_links_to":"","_links_to_target":""},"categories":[14,21,70,9],"tags":[],"_links":{"self":[{"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/posts\/35474"}],"collection":[{"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/comments?post=35474"}],"version-history":[{"count":2,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/posts\/35474\/revisions"}],"predecessor-version":[{"id":35477,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/posts\/35474\/revisions\/35477"}],"wp:attachment":[{"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/media?parent=35474"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/categories?post=35474"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/tags?post=35474"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}