{"id":36761,"date":"2015-07-20T23:01:48","date_gmt":"2015-07-21T02:01:48","guid":{"rendered":"http:\/\/www.blogdotarugao.com.br\/v1\/?p=36761"},"modified":"2015-07-20T23:01:48","modified_gmt":"2015-07-21T02:01:48","slug":"contran-decide-tornar-obrigatorio-uso-do-simulador-em-todos-os-estados","status":"publish","type":"post","link":"https:\/\/www.blogdotarugao.com.br\/v1\/2015\/07\/20\/contran-decide-tornar-obrigatorio-uso-do-simulador-em-todos-os-estados\/","title":{"rendered":"Contran decide tornar obrigat\u00f3rio uso do simulador em todos os Estados"},"content":{"rendered":"<h3 style=\"text-align: justify;\"><a href=\"http:\/\/www.blogdotarugao.com.br\/v1\/wp-content\/uploads\/2015\/07\/simulador.jpg\" class=\"gallery_colorbox\"><img loading=\"lazy\" class=\"alignleft  wp-image-36763\" src=\"http:\/\/www.blogdotarugao.com.br\/v1\/wp-content\/uploads\/2015\/07\/simulador.jpg\"  alt=\"simulador\" width=\"580\" height=\"326\" srcset=\"https:\/\/www.blogdotarugao.com.br\/v1\/wp-content\/uploads\/2015\/07\/simulador.jpg 640w, https:\/\/www.blogdotarugao.com.br\/v1\/wp-content\/uploads\/2015\/07\/simulador-300x169.jpg 300w\" sizes=\"(max-width: 580px) 100vw, 580px\" \/><\/a><\/h3>\n<h3 style=\"text-align: justify;\">O Conselho Nacional de Tr\u00e2nsito (Contran), \u00f3rg\u00e3o do Minist\u00e9rio das Cidades, decidiu tornar obrigat\u00f3ria a utiliza\u00e7\u00e3o do simulador de dire\u00e7\u00e3o veicular nos centros de forma\u00e7\u00e3o de condutores (CFCs). O pedido da volta da obrigatoriedade partiu dos Detrans de todo o pa\u00eds. A Resolu\u00e7\u00e3o N\u00ba543\/2015 sobre tema foi publicada no Di\u00e1rio Oficial da Uni\u00e3o de hoje, dia 20. At\u00e9 agora, somente os Estados do Rio Grande do Sul, Acre, Para\u00edba e Alagoas exigem as aulas nos simuladores. Os candidatos \u00e0 obten\u00e7\u00e3o da Carteira Nacional de Habilita\u00e7\u00e3o ou aqueles motoristas que ir\u00e3o mudar de categoria, ser\u00e3o obrigados a fazer, no m\u00ednimo, cinco horas\/aula, de simula\u00e7\u00e3o, sendo uma com conte\u00fado noturno. As aulas dever\u00e3o ocorrer ap\u00f3s o aluno ter feito o curso te\u00f3rico e antes de iniciar a pr\u00e1tica nas ruas. Inicialmente a determina\u00e7\u00e3o vale para os que v\u00e3o dirigir carros de passeios, na categoria B. Numa segunda etapa, ser\u00e1 obrigat\u00f3rio o uso do simulador para quem dirigir ve\u00edculos comerciais, caminh\u00e3o, \u00f4nibus e motos. Segundo o presidente do Contran, Alberto Angerami, a maior preocupa\u00e7\u00e3o \u00e9 com a seguran\u00e7a no tr\u00e2nsito. &#8220;J\u00e1 tivemos bons resultados nos Estados que aplicaram a medida, principalmente no Rio Grande do Sul, onde foi registrada redu\u00e7\u00e3o do n\u00famero de acidentes ap\u00f3s a obrigatoriedade do simulador\u201d, explicou.<\/h3>\n","protected":false},"excerpt":{"rendered":"<p>O Conselho Nacional de Tr\u00e2nsito (Contran), \u00f3rg\u00e3o do Minist\u00e9rio das Cidades, decidiu tornar obrigat\u00f3ria a utiliza\u00e7\u00e3o do simulador de dire\u00e7\u00e3o veicular nos centros de forma\u00e7\u00e3o de condutores (CFCs). O pedido da volta da obrigatoriedade partiu dos Detrans de todo o pa\u00eds. A Resolu\u00e7\u00e3o N\u00ba543\/2015 sobre tema foi publicada no Di\u00e1rio Oficial da Uni\u00e3o de hoje, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_links_to":"","_links_to_target":""},"categories":[5],"tags":[],"_links":{"self":[{"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/posts\/36761"}],"collection":[{"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/comments?post=36761"}],"version-history":[{"count":1,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/posts\/36761\/revisions"}],"predecessor-version":[{"id":36764,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/posts\/36761\/revisions\/36764"}],"wp:attachment":[{"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/media?parent=36761"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/categories?post=36761"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/tags?post=36761"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}