{"id":40670,"date":"2015-09-05T22:56:43","date_gmt":"2015-09-06T01:56:43","guid":{"rendered":"http:\/\/www.blogdotarugao.com.br\/v1\/?p=40670"},"modified":"2015-09-05T09:00:54","modified_gmt":"2015-09-05T12:00:54","slug":"cresce-numero-de-homens-que-retiram-as-mamas-para-evitar-cancer","status":"publish","type":"post","link":"https:\/\/www.blogdotarugao.com.br\/v1\/2015\/09\/05\/cresce-numero-de-homens-que-retiram-as-mamas-para-evitar-cancer\/","title":{"rendered":"Cresce n\u00famero de homens que retiram as mamas para evitar c\u00e2ncer"},"content":{"rendered":"<p>&nbsp;<\/p>\n<div id=\"attachment_40671\" style=\"width: 595px\" class=\"wp-caption alignleft\"><img aria-describedby=\"caption-attachment-40671\" loading=\"lazy\" class=\"wp-image-40671\" src=\"http:\/\/www.blogdotarugao.com.br\/v1\/wp-content\/uploads\/2015\/09\/MAMA-DE-HOMEM.jpeg\" alt=\"MAMA DE HOMEM\" width=\"585\" height=\"439\" srcset=\"https:\/\/www.blogdotarugao.com.br\/v1\/wp-content\/uploads\/2015\/09\/MAMA-DE-HOMEM.jpeg 690w, https:\/\/www.blogdotarugao.com.br\/v1\/wp-content\/uploads\/2015\/09\/MAMA-DE-HOMEM-300x225.jpeg 300w\" sizes=\"(max-width: 585px) 100vw, 585px\" \/><p id=\"caption-attachment-40671\" class=\"wp-caption-text\"><\/h1>\n<h2>De acordo com os pesquisadores, a dupla mastectomia s\u00f3 \u00e9 recomendada para uma pequena propor\u00e7\u00e3o de homens e a taxa observada no estudo supera essa propor\u00e7\u00e3o<\/h2>\n<p><\/p><\/div>\n<h3>De acordo com novo estudo, o \u00edndice de homens optam pela dupla mastectomia preventiva para evitar c\u00e2ncer de mama aumentou de 3% para 5,6%<\/h3>\n<h3 style=\"text-align: justify;\">O n\u00famero de homens americanos com c\u00e2ncer de mama que optam pela dupla mastectomia aumentou de 3%, em 2004, para 5,6% em 2011. \u00c9 o que diz um estudo publicado na \u00faltima edi\u00e7\u00e3o da revista cient\u00edfica <em>JAMA Surgery.<\/em><\/h3>\n<h3 style=\"text-align: justify;\">A pesquisa, conduzida pela Sociedade Americana de C\u00e2ncer e o Instituto Dana Faber para o C\u00e2ncer, incluiu dados de 6 332 homens. Embora os pesquisadores n\u00e3o saibam afirmar os motivos dessa tend\u00eancia, eles acreditam que seja uma combina\u00e7\u00e3o de fatores: garantir a preven\u00e7\u00e3o m\u00e1xima para evitar o surgimento da doen\u00e7a, o aumento da disponibilidade de testes gen\u00e9ticos e o &#8220;efeito Angelina Jolie&#8221;, que retirou as mamas de forma preventiva.<\/h3>\n<h3 style=\"text-align: justify;\">De acordo com os autores, o mesmo padr\u00e3o de comportamento j\u00e1 havia sido observado em mulheres. Eles ressaltam, contudo, que esse tipo de procedimento &#8211; retirar uma mama que est\u00e1 saud\u00e1vel &#8211; nem sempre \u00e9 necess\u00e1rio.<\/h3>\n<h3 style=\"text-align: justify;\">&#8220;A opera\u00e7\u00e3o s\u00f3 \u00e9 recomendada para uma pequena propor\u00e7\u00e3o de homens (que tem a muta\u00e7\u00e3o no gene BRCA) e a taxa observada no estudo \u00e9 maior que essa propor\u00e7\u00e3o. Al\u00e9m disso, h\u00e1 uma falta de evid\u00eancias que sugerem que tais mastectomias ajudam os pacientes a viver mais tempo&#8221;, afirmou Ahmedin Jemal, vice presidente de vigil\u00e2ncia e servi\u00e7os pesquisa de sa\u00fade da Sociedade Americana de C\u00e2ncer e principal autor do estudo, ao site especializado <em>Live Science<\/em>.<\/h3>\n<p><!--more--><\/p>\n<h3 style=\"text-align: justify;\"><\/h3>\n<h3 style=\"text-align: justify;\">Os pesquisadores descobriram que, em m\u00e9dia, os homens que optaram pelo procedimento, eram mais jovens do que aqueles que n\u00e3o o fizeram. A taxa de dupla mastectomia tamb\u00e9m foi diminuindo conforme a idade dos pacientes aumentava.<\/h3>\n<h3 style=\"text-align: justify;\">De acordo com a Sociedade Americana de C\u00e2ncer, o tumor de mama \u00e9 100 vezes mais comum em mulheres do que em homens, mas n\u00e3o \u00e9 exclusivo delas como o c\u00e2ncer de ov\u00e1rio. Nos Estados Unidos, s\u00e3o estimados cerca de 2 350 novos casos de c\u00e2ncer de mama em homens, em 2015.<\/h3>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; De acordo com novo estudo, o \u00edndice de homens optam pela dupla mastectomia preventiva para evitar c\u00e2ncer de mama aumentou de 3% para 5,6% O n\u00famero de homens americanos com c\u00e2ncer de mama que optam pela dupla mastectomia aumentou de 3%, em 2004, para 5,6% em 2011. \u00c9 o que diz um estudo publicado [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_links_to":"","_links_to_target":""},"categories":[70,1,12],"tags":[],"_links":{"self":[{"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/posts\/40670"}],"collection":[{"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/comments?post=40670"}],"version-history":[{"count":1,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/posts\/40670\/revisions"}],"predecessor-version":[{"id":40672,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/posts\/40670\/revisions\/40672"}],"wp:attachment":[{"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/media?parent=40670"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/categories?post=40670"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/tags?post=40670"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}