{"id":40883,"date":"2015-09-07T19:59:30","date_gmt":"2015-09-07T22:59:30","guid":{"rendered":"http:\/\/www.blogdotarugao.com.br\/v1\/?p=40883"},"modified":"2015-09-07T19:59:30","modified_gmt":"2015-09-07T22:59:30","slug":"dupla-sertaneja-e-detida-em-show-por-suspeita-de-apologia-as-drogas","status":"publish","type":"post","link":"https:\/\/www.blogdotarugao.com.br\/v1\/2015\/09\/07\/dupla-sertaneja-e-detida-em-show-por-suspeita-de-apologia-as-drogas\/","title":{"rendered":"Dupla sertaneja \u00e9 detida em show por suspeita de apologia \u00e0s drogas"},"content":{"rendered":"<h3 style=\"text-align: justify;\"><img loading=\"lazy\" class=\"alignleft  wp-image-40884\" src=\"http:\/\/www.blogdotarugao.com.br\/v1\/wp-content\/uploads\/2015\/09\/set.jpg\" alt=\"set\" width=\"581\" height=\"436\" \/><\/h3>\n<h3 style=\"text-align: justify;\">A dupla sertaneja Junior e Gustavo foi detida pela Pol\u00edcia Militar (PM) na madrugada desta segunda-feira (7) durante um show na Exposi\u00e7\u00e3o Agropecu\u00e1ria de <a class=\"premium-tip\" href=\"http:\/\/g1.globo.com\/rj\/regiao-serrana\/cidade\/macuco.html\">Macuco<\/a>, na Regi\u00e3o Serrana do Rio. Segundo informa\u00e7\u00f5es da PM, a apresenta\u00e7\u00e3o foi interrompida porque os cantores estavam fazendo apologia \u00e0s drogas com m\u00fasicas de funk. Eles foram levados em viaturas da pol\u00edcia para a 154\u00aa Delegacia de Pol\u00edcia em Cordeiro, onde prestaram depoimento e foram liberados. Quando os m\u00fasicos entraram na viatura, houve gritaria e vaias \u00e0 a\u00e7\u00e3o da PM.<\/h3>\n<h3 style=\"text-align: justify;\">\u201cN\u00e3o \u00e9 a primeira vez que essa dupla \u00e9 autuada. A primeira foi em <a class=\"premium-tip\" href=\"http:\/\/g1.globo.com\/rj\/regiao-serrana\/cidade\/nova-friburgo.html\">Nova Friburgo<\/a> durante um show no anivers\u00e1rio da cidade, no ano passado. Eles querem &#8216;inflamar&#8217; a popula\u00e7\u00e3o cantando esse tipo de m\u00fasica\u201d, afirmou o coronel Carlos Eduardo Hespanha, comandante da Pol\u00edcia Militar na regi\u00e3o.<\/h3>\n<h3 style=\"text-align: justify;\">Junior, cantor da dupla, confirmou ao <strong>G1<\/strong> que este foi o segundo incidente: \u201cS\u00f3 tivemos problema por cantar funk em show duas vezes. Uma em Nova Friburgo e agora em Macuco, cidades cobertas pelo mesmo batalh\u00e3o\u201d.<\/h3>\n<h3 style=\"text-align: justify;\">Segundo a assessoria de imprensa dos cantores, o som foi interrompido no momento em que a dupla cantava um &#8216;pout pourri&#8217; com quatro funks antigos: Rap da Felicidade, Rap do Silva, Rap do Salgueiro e Rap da Estrada da Posse.<\/h3>\n","protected":false},"excerpt":{"rendered":"<p>A dupla sertaneja Junior e Gustavo foi detida pela Pol\u00edcia Militar (PM) na madrugada desta segunda-feira (7) durante um show na Exposi\u00e7\u00e3o Agropecu\u00e1ria de Macuco, na Regi\u00e3o Serrana do Rio. Segundo informa\u00e7\u00f5es da PM, a apresenta\u00e7\u00e3o foi interrompida porque os cantores estavam fazendo apologia \u00e0s drogas com m\u00fasicas de funk. Eles foram levados em viaturas [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_links_to":"","_links_to_target":""},"categories":[5],"tags":[],"_links":{"self":[{"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/posts\/40883"}],"collection":[{"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/comments?post=40883"}],"version-history":[{"count":1,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/posts\/40883\/revisions"}],"predecessor-version":[{"id":40885,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/posts\/40883\/revisions\/40885"}],"wp:attachment":[{"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/media?parent=40883"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/categories?post=40883"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/tags?post=40883"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}