{"id":41711,"date":"2015-09-17T12:57:18","date_gmt":"2015-09-17T15:57:18","guid":{"rendered":"http:\/\/www.blogdotarugao.com.br\/v1\/?p=41711"},"modified":"2015-09-17T12:58:54","modified_gmt":"2015-09-17T15:58:54","slug":"japones-fisga-peixe-que-teria-sido-afetado-pelo-acidente-em-fukushima","status":"publish","type":"post","link":"https:\/\/www.blogdotarugao.com.br\/v1\/2015\/09\/17\/japones-fisga-peixe-que-teria-sido-afetado-pelo-acidente-em-fukushima\/","title":{"rendered":"Japon\u00eas fisga peixe que teria sido afetado pelo acidente em Fukushima"},"content":{"rendered":"<p><img loading=\"lazy\" class=\"alignleft  wp-image-41712\" src=\"http:\/\/www.blogdotarugao.com.br\/v1\/wp-content\/uploads\/2015\/09\/peixe-mutante.jpg\" alt=\"peixe mutante\" width=\"586\" height=\"427\" srcset=\"https:\/\/www.blogdotarugao.com.br\/v1\/wp-content\/uploads\/2015\/09\/peixe-mutante.jpg 944w, https:\/\/www.blogdotarugao.com.br\/v1\/wp-content\/uploads\/2015\/09\/peixe-mutante-300x219.jpg 300w\" sizes=\"(max-width: 586px) 100vw, 586px\" \/><\/p>\n<h3 style=\"text-align: justify;\"><span style=\"font-size: 16px; line-height: 1.5;\"><br \/>\nSegundo o Telegraph, os peixes wolffish medem at\u00e9 1 metro de comprimento, mas o encontrado pelo japon\u00eas aparenta ter pouco mais de 2 metros. Para alguns, o tamanho anormal pode ser efeito do acidente nuclear na<\/span><strong style=\"font-size: 16px; line-height: 1.5;\">Usina de Fukushima<\/strong><span style=\"font-size: 16px; line-height: 1.5;\">. No entanto, n\u00e3o h\u00e1 qualquer dado que relacione os fatos.<\/span>O japon\u00eas Hiroshi Hirasaka fisgou um peixe monstruoso nas \u00e1guas de Hokkaido, a segunda maior ilha japonesa e despertou a curiosidade sobre o tamanho incomum do animal.<\/h3>\n<h3 style=\"text-align: justify;\">Em sua conta no <strong>Twitter<\/strong>, o japon\u00eas, que \u00e9 conhecido por ca\u00e7ar e comer animais ex\u00f3ticos, postou as fotos do animal e disse que ap\u00f3s fisg\u00e1-lo, ele e a equipe ainda encontraram outros quatro peixes do mesmo comprimento\u00a0na regi\u00e3o.<\/h3>\n<h3 style=\"text-align: justify;\">Geralmente, esses animais raramente s\u00e3o vistos, pois vivem em \u00e1guas profundas dos oceanos Pac\u00edfico e Atl\u00e2ntico e dificilmente saem \u00e0 superf\u00edcie.<\/h3>\n<p><img loading=\"lazy\" class=\"\" title=\"\" src=\"http:\/\/images.redetv.uol.com.br\/public\/jornalismo\/redetvinoticias\/20150917090513YFSEkcI4ur.jpg\" alt=\"\" width=\"580\" height=\"406\" border=\"0\" \/><\/p>\n<p><img loading=\"lazy\" class=\"\" title=\"\" src=\"http:\/\/images.redetv.uol.com.br\/public\/jornalismo\/redetvinoticias\/20150917090509KXjKy3JH50.jpg\" alt=\"\" width=\"581\" height=\"378\" border=\"0\" \/><\/p>\n<p><img loading=\"lazy\" class=\"\" title=\"\" src=\"http:\/\/images.redetv.uol.com.br\/public\/jornalismo\/redetvinoticias\/20150917090504xdTG0T53aX.jpg\" alt=\"\" width=\"582\" height=\"437\" border=\"0\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Segundo o Telegraph, os peixes wolffish medem at\u00e9 1 metro de comprimento, mas o encontrado pelo japon\u00eas aparenta ter pouco mais de 2 metros. Para alguns, o tamanho anormal pode ser efeito do acidente nuclear naUsina de Fukushima. No entanto, n\u00e3o h\u00e1 qualquer dado que relacione os fatos.O japon\u00eas Hiroshi Hirasaka fisgou um peixe monstruoso [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_links_to":"","_links_to_target":""},"categories":[70,24,1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/posts\/41711"}],"collection":[{"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/comments?post=41711"}],"version-history":[{"count":4,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/posts\/41711\/revisions"}],"predecessor-version":[{"id":41716,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/posts\/41711\/revisions\/41716"}],"wp:attachment":[{"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/media?parent=41711"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/categories?post=41711"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/tags?post=41711"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}