{"id":42299,"date":"2015-09-25T21:18:48","date_gmt":"2015-09-26T00:18:48","guid":{"rendered":"http:\/\/www.blogdotarugao.com.br\/v1\/?p=42299"},"modified":"2015-09-25T21:45:00","modified_gmt":"2015-09-26T00:45:00","slug":"nota-de-esclarecimento-dr-rubem-moreira","status":"publish","type":"post","link":"https:\/\/www.blogdotarugao.com.br\/v1\/2015\/09\/25\/nota-de-esclarecimento-dr-rubem-moreira\/","title":{"rendered":"Nota de Esclarecimento: Dr. Rubem Moreira"},"content":{"rendered":"<h3 style=\"text-align: justify;\"><img loading=\"lazy\" class=\"alignleft  wp-image-42301\" src=\"http:\/\/www.blogdotarugao.com.br\/v1\/wp-content\/uploads\/2015\/09\/rubens.jpg\" alt=\"rubens\" width=\"581\" height=\"827\" srcset=\"https:\/\/www.blogdotarugao.com.br\/v1\/wp-content\/uploads\/2015\/09\/rubens.jpg 243w, https:\/\/www.blogdotarugao.com.br\/v1\/wp-content\/uploads\/2015\/09\/rubens-211x300.jpg 211w\" sizes=\"(max-width: 581px) 100vw, 581px\" \/>Por respeito a dor que atinge a todos envolvidos, em especial \u00e0 fam\u00edlia da paciente, venho a publico prestar este esclarecimentos. Ate agora, vinha tratando o caso com a discri\u00e7\u00e3o que deve existir sobre toda atua\u00e7\u00e3o do profissional de sa\u00fade.<\/h3>\n<h3 style=\"text-align: justify;\">Sou pai de 3 filhos, nascido em Itapetinga e tenho quase 40 anos de profiss\u00e3o. Realizo partos durante todo este tempo e tenho amor \u00e0 medicina.<\/h3>\n<h3 style=\"text-align: justify;\">H\u00e1 alguns dias fui chamado ao hospital para atender uma gestante que tinha entrado em trabalho de parto dias entes previsto. Mesmo tendo realizado junto com toda a equipe m\u00e9dica os procedimentos e esfor\u00e7os necess\u00e1rios, n\u00e3o pude evitar que a crian\u00e7a viesse a \u00f3bito. A partir da\u00ed, procurei a fam\u00edlia para inform\u00e1-los e alert\u00e1-los dos riscos que a gestante corria, bem como todas as medidas que poderiam ser requeridas.<\/h3>\n<h3 style=\"text-align: justify;\">Tenho consci\u00eancia que para aqueles que desconhecem as raz\u00f5es e circunst\u00e2ncia que indicaram um procedimento t\u00e3o extremo sobressai o choque e a dor da fam\u00edlia enlutada. Apesar de extremo, este procedimento \u00e9 existente, \u00e9 previsto na literatura m\u00e9dica e indicado quando \u00e9 absolutamente necess\u00e1rio para salvar vidas da gestante.<\/h3>\n<h3 style=\"text-align: justify;\">Deus \u00e9 testemunha que fizemos o poss\u00edvel para salvar a crian\u00e7a e que na impossibilidade disto, tentamos ao m\u00e1ximo reduzir os impactos desta perda para sua fam\u00edlia. O que foi feito era um recurso indispens\u00e1vel e que nos permitiu salvar a gestante.<\/h3>\n<h3 style=\"text-align: justify;\">Por mais que nos esforcemos, nem sempre \u00e9 permitido a n\u00f3s profissionais de sa\u00fade evitar a dor e o sofrimento daqueles a quem nos prestamos a atender.<\/h3>\n<h3 style=\"text-align: justify;\">Deixo aqui meus sentimento \u00e0 fam\u00edlia.<\/h3>\n","protected":false},"excerpt":{"rendered":"<p>Por respeito a dor que atinge a todos envolvidos, em especial \u00e0 fam\u00edlia da paciente, venho a publico prestar este esclarecimentos. Ate agora, vinha tratando o caso com a discri\u00e7\u00e3o que deve existir sobre toda atua\u00e7\u00e3o do profissional de sa\u00fade. Sou pai de 3 filhos, nascido em Itapetinga e tenho quase 40 anos de profiss\u00e3o. [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_links_to":"","_links_to_target":""},"categories":[6,1,12],"tags":[],"_links":{"self":[{"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/posts\/42299"}],"collection":[{"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/comments?post=42299"}],"version-history":[{"count":3,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/posts\/42299\/revisions"}],"predecessor-version":[{"id":42304,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/posts\/42299\/revisions\/42304"}],"wp:attachment":[{"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/media?parent=42299"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/categories?post=42299"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/tags?post=42299"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}