{"id":42446,"date":"2015-09-27T13:18:19","date_gmt":"2015-09-27T16:18:19","guid":{"rendered":"http:\/\/www.blogdotarugao.com.br\/v1\/?p=42446"},"modified":"2015-09-27T13:18:19","modified_gmt":"2015-09-27T16:18:19","slug":"advogados-da-operacao-lava-jato-preparam-ofensiva-contra-moro","status":"publish","type":"post","link":"https:\/\/www.blogdotarugao.com.br\/v1\/2015\/09\/27\/advogados-da-operacao-lava-jato-preparam-ofensiva-contra-moro\/","title":{"rendered":"Advogados da Opera\u00e7\u00e3o Lava Jato preparam ofensiva contra Moro"},"content":{"rendered":"<h3 style=\"text-align: justify;\"><img loading=\"lazy\" class=\"alignleft  wp-image-35725\" src=\"http:\/\/www.blogdotarugao.com.br\/v1\/wp-content\/uploads\/2015\/07\/sergio-moro1.jpg\" alt=\"sergio moro1\" width=\"585\" height=\"323\" srcset=\"https:\/\/www.blogdotarugao.com.br\/v1\/wp-content\/uploads\/2015\/07\/sergio-moro1.jpg 765w, https:\/\/www.blogdotarugao.com.br\/v1\/wp-content\/uploads\/2015\/07\/sergio-moro1-300x166.jpg 300w\" sizes=\"(max-width: 585px) 100vw, 585px\" \/>A decis\u00e3o do Supremo Tribunal Federal (STF) de fatiar os processos da Opera\u00e7\u00e3o Lava Jato deve provocar uma onda de contesta\u00e7\u00e3o por parte das defesas de suspeitos sob o argumento de que seus casos n\u00e3o t\u00eam rela\u00e7\u00e3o direta com as investiga\u00e7\u00f5es da Petrobras, segundo a Folha apurou junto a cinco advogados que atuam no caso. Nenhum dos defensores ouvidos pela reportagem acha que ser\u00e1 o fim da Lava Jato, nem ousa prever o que pode ocorrer com as investiga\u00e7\u00f5es da opera\u00e7\u00e3o<\/h3>\n<h3 style=\"text-align: justify;\">Na quarta-feira (23), o STF tirou da Justi\u00e7a Federal no Paran\u00e1 uma a\u00e7\u00e3o que envolve uma empresa de S\u00e3o Paulo, a Consist, investigada sob suspeita de desviar recursos do Minist\u00e9rio do Planejamento e distribu\u00ed-los a parlamentares do PT. Os processos que envolvem a estatal Eletronuclear, investigada sob suspeita de receber propina pela obra da usina nuclear de Angra 3, e os do ex-deputado Andr\u00e9 Vargas e do publicit\u00e1rio Ricardo Hoffmann, que envolvem contratos do Minist\u00e9rio da Sa\u00fade e da Caixa Econ\u00f4mica Federal, s\u00e3o os com maior potencial de sofrer mudan\u00e7as a partir da decis\u00e3o do Supremo.<\/h3>\n<p><!--more--><\/p>\n<h3 style=\"text-align: justify;\">As defesas de Fl\u00e1vio Barra, executivo da Andrade Gutierrez, e do almirante Othon Pinheiro da Silva, presidente licenciado da Eletronuclear, v\u00e3o protocolar no STF uma figura jur\u00eddica chamada reclama\u00e7\u00e3o para tentar tirar o caso do juiz federal Sergio Moro, de acordo com informa\u00e7\u00f5es publicadas pelo jornal Folha.<\/h3>\n<h3 style=\"text-align: justify;\">Segundo o jornal, o advogado Elton Pinto, que defende o almirante, afirma que o processo penal sobre corrup\u00e7\u00e3o em Angra 3 deve ser desmembrado por n\u00e3o ter rela\u00e7\u00e3o direta com a as apura\u00e7\u00f5es da Petrobras. Na \u00faltima segunda (21), antes da decis\u00e3o do STF que fatiou a Lava Jato, Pinto apresentou um pedido judicial para tirar o caso da Justi\u00e7a Federal no Parar\u00e1, questionando a compet\u00eancia jurisdicional do juiz Sergio Moro para apreciar a a\u00e7\u00e3o sobre os supostos crimes ocorridos no Rio.<\/h3>\n<h3 style=\"text-align: justify;\"><\/h3>\n<h3 style=\"text-align: justify;\">Moro ainda n\u00e3o se pronunciou sobre o pedido e marcou audi\u00eancias do caso para outubro \u2013o que indica, segundo o advogado, que o magistrado se julga competente para permanecer julgando o processo. &#8220;O que eu n\u00e3o entendo \u00e9 o interesse de ele [Moro] permanecer com o caso da Eletronuclear, que n\u00e3o tem nada a ver com Petrobras. A reclama\u00e7\u00e3o ao Supremo \u00e9 cab\u00edvel porque se trata de situa\u00e7\u00e3o an\u00e1loga \u00e0 da decis\u00e3o desta semana&#8221;, disse.<\/h3>\n<h3 style=\"text-align: justify;\"><\/h3>\n<h3 style=\"text-align: justify;\">O advogado Roberto Telhada, que defende Barra, diz que, no caso de Angra 3, os \u00f3rg\u00e3os do governo j\u00e1 reconheceram que o cartel que atuou nessa obra \u00e9 completamente diferente daquele que atuava na Petrobras. Por essa raz\u00e3o, segundo ele, o juiz Moro n\u00e3o \u00e9 competente para julgar essa a\u00e7\u00e3o, mas a Justi\u00e7a do Rio de Janeiro, onde fica a sede da Eletronuclear. O caso de Barra tem um ingrediente extra: um dos supostos beneficiados pela propina seria o senador Edison Lob\u00e3o (PMDB-MA), que nega o suborno. Se essa vers\u00e3o for confirmada, o caso teria que ser julgado pelo Supremo.<\/h3>\n<h3 style=\"text-align: justify;\"><\/h3>\n<h3 style=\"text-align: justify;\">Telhada diz que a decis\u00e3o do STF coloca em xeque todas as decis\u00f5es de Moro que n\u00e3o envolvem a Petrobras. &#8220;Se o juiz \u00e9 incompetente para julgar a\u00e7\u00f5es que n\u00e3o sejam da Petrobras, o que ele j\u00e1 fez nessas a\u00e7\u00f5es n\u00e3o vale nada. Isso \u00e9 o que est\u00e1 na lei. N\u00e3o \u00e9 opini\u00e3o pessoal.&#8221;<\/h3>\n<h3 style=\"text-align: justify;\"><\/h3>\n<h3 style=\"text-align: justify;\">Parte dos advogados, por\u00e9m, n\u00e3o pretende usar de imediato a recente decis\u00e3o da corte m\u00e1xima do pa\u00eds.<\/h3>\n","protected":false},"excerpt":{"rendered":"<p>A decis\u00e3o do Supremo Tribunal Federal (STF) de fatiar os processos da Opera\u00e7\u00e3o Lava Jato deve provocar uma onda de contesta\u00e7\u00e3o por parte das defesas de suspeitos sob o argumento de que seus casos n\u00e3o t\u00eam rela\u00e7\u00e3o direta com as investiga\u00e7\u00f5es da Petrobras, segundo a Folha apurou junto a cinco advogados que atuam no caso. [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_links_to":"","_links_to_target":""},"categories":[70,18,1,8,7],"tags":[],"_links":{"self":[{"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/posts\/42446"}],"collection":[{"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/comments?post=42446"}],"version-history":[{"count":1,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/posts\/42446\/revisions"}],"predecessor-version":[{"id":42447,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/posts\/42446\/revisions\/42447"}],"wp:attachment":[{"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/media?parent=42446"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/categories?post=42446"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/tags?post=42446"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}