{"id":42735,"date":"2015-09-30T14:05:01","date_gmt":"2015-09-30T17:05:01","guid":{"rendered":"http:\/\/www.blogdotarugao.com.br\/v1\/?p=42735"},"modified":"2015-09-30T14:05:01","modified_gmt":"2015-09-30T17:05:01","slug":"vem-ai-1o-congresso-de-jovens-mergulhados-na-graca","status":"publish","type":"post","link":"https:\/\/www.blogdotarugao.com.br\/v1\/2015\/09\/30\/vem-ai-1o-congresso-de-jovens-mergulhados-na-graca\/","title":{"rendered":"VEM AI! 1\u00ba CONGRESSO DE JOVENS MERGULHADOS NA GRA\u00c7A"},"content":{"rendered":"<h3 style=\"text-align: justify;\"><img loading=\"lazy\" class=\"alignleft  wp-image-42736\" src=\"http:\/\/www.blogdotarugao.com.br\/v1\/wp-content\/uploads\/2015\/09\/jovens.jpg\" alt=\"jovens\" width=\"585\" height=\"439\" srcset=\"https:\/\/www.blogdotarugao.com.br\/v1\/wp-content\/uploads\/2015\/09\/jovens.jpg 640w, https:\/\/www.blogdotarugao.com.br\/v1\/wp-content\/uploads\/2015\/09\/jovens-300x225.jpg 300w\" sizes=\"(max-width: 585px) 100vw, 585px\" \/>A rede de jovens Mergulhados na gra\u00e7a,da comunidade voz do deserto,convida voc\u00ea nos dias 30 e 31 de outubro,01 e 02 de novembro, ser\u00e3o dias poderosos na presen\u00e7a de Deus, onde teremos a presen\u00e7a do pastor Jos\u00e9 Roberto da igreja evang\u00e9lica Verbo da Vida de Guaratinguet\u00e1 SP, e outros convidados de Salvador BA, participa\u00e7\u00e3o da Banda Voz do Deserto. Tamb\u00e9m estar\u00e1 acontecendo oficinas de dan\u00e7a afro, tran\u00e7as de cabelo, massagem e acupuntura.<img loading=\"lazy\" class=\"alignleft  wp-image-42737\" src=\"http:\/\/www.blogdotarugao.com.br\/v1\/wp-content\/uploads\/2015\/09\/jovens1.jpg\" alt=\"jovens1\" width=\"586\" height=\"397\" srcset=\"https:\/\/www.blogdotarugao.com.br\/v1\/wp-content\/uploads\/2015\/09\/jovens1.jpg 720w, https:\/\/www.blogdotarugao.com.br\/v1\/wp-content\/uploads\/2015\/09\/jovens1-300x203.jpg 300w\" sizes=\"(max-width: 586px) 100vw, 586px\" \/><\/h3>\n","protected":false},"excerpt":{"rendered":"<p>A rede de jovens Mergulhados na gra\u00e7a,da comunidade voz do deserto,convida voc\u00ea nos dias 30 e 31 de outubro,01 e 02 de novembro, ser\u00e3o dias poderosos na presen\u00e7a de Deus, onde teremos a presen\u00e7a do pastor Jos\u00e9 Roberto da igreja evang\u00e9lica Verbo da Vida de Guaratinguet\u00e1 SP, e outros convidados de Salvador BA, participa\u00e7\u00e3o da [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_links_to":"","_links_to_target":""},"categories":[6,21,70,33,2,1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/posts\/42735"}],"collection":[{"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/comments?post=42735"}],"version-history":[{"count":1,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/posts\/42735\/revisions"}],"predecessor-version":[{"id":42738,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/posts\/42735\/revisions\/42738"}],"wp:attachment":[{"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/media?parent=42735"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/categories?post=42735"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/tags?post=42735"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}