{"id":43763,"date":"2015-10-17T21:21:26","date_gmt":"2015-10-18T00:21:26","guid":{"rendered":"http:\/\/www.blogdotarugao.com.br\/v1\/?p=43763"},"modified":"2015-10-18T10:07:32","modified_gmt":"2015-10-18T13:07:32","slug":"chimbinha-dizpara-amigos-que-esta-sendo-vitima-de-trabalho-espiritual","status":"publish","type":"post","link":"https:\/\/www.blogdotarugao.com.br\/v1\/2015\/10\/17\/chimbinha-dizpara-amigos-que-esta-sendo-vitima-de-trabalho-espiritual\/","title":{"rendered":"CHIMBINHA DIZ PARA AMIGOS QUE EST\u00c1 SENDO V\u00cdTIMA DE &#8220;TRABALHO ESPIRITUAL&#8221;"},"content":{"rendered":"<h3 style=\"text-align: justify;\"><img loading=\"lazy\" class=\"  wp-image-43764 alignleft\" src=\"http:\/\/www.blogdotarugao.com.br\/v1\/wp-content\/uploads\/2015\/10\/CHIMBAS.jpg\" alt=\"CHIMBAS\" width=\"584\" height=\"338\" srcset=\"https:\/\/www.blogdotarugao.com.br\/v1\/wp-content\/uploads\/2015\/10\/CHIMBAS.jpg 650w, https:\/\/www.blogdotarugao.com.br\/v1\/wp-content\/uploads\/2015\/10\/CHIMBAS-300x173.jpg 300w\" sizes=\"(max-width: 584px) 100vw, 584px\" \/>Desde que anunciaram o fim do casamento de 18 anos em agosto deste ano,\u00a0<a href=\"http:\/\/www.redetv.uol.com.br\/tvfama\/busca\/?q=joelma\" target=\"_blank\"><strong>Joelma<\/strong><\/a> e <a href=\"http:\/\/www.redetv.uol.com.br\/tvfama\/busca\/?q=chimbinha\" target=\"_blank\"><strong>Chimbinha<\/strong><\/a>, da banda <strong>Calypso<\/strong>, n\u00e3o param de acumular pol\u00eamicas.<br \/>\nNeste s\u00e1bado (17), a coluna Retratos da Vida, do jornal Extra, anunciou mais um cap\u00edtulo dessa longa novela. Segundo a publica\u00e7\u00e3o, Chimbinha teria confidenciado a amigos pr\u00f3ximos que acredita estar sendo v\u00edtima de algum &#8216;trabalho espiritual&#8217;, uma vez que sua vida &#8216;virou de pernas para o ar&#8217; ap\u00f3s o div\u00f3rcio com a cantora.<\/h3>\n<p>Ainda de acordo com o jornal, o m\u00fasico n\u00e3o acusa a ex-mulher Joelma como respons\u00e1vel, mas algu\u00e9m ligado a ela. Chimbinha chegou a declarar em entrevistas que a cantora poderia estar sendo manipulada por sua guia espiritual.<\/p>\n<p><strong>Relembre<\/strong><\/p>\n<p><!--more--><\/p>\n<h3 style=\"text-align: justify;\">Chimbinha e Joelma anunciaram a separa\u00e7\u00e3o em agosto, ap\u00f3s 18 anos de casamento. O cantor desmascarado ap\u00f3s ter\u00a0tra\u00eddo a mulher chegou a anunciar que n\u00e3o deixaria a banda, que tem a agenda de show lotada at\u00e9 o final do ano.<\/h3>\n<h3 style=\"text-align: justify;\">Em setembro, a Justi\u00e7a do Par\u00e1 determinou que Chimbinha permanecesse a pelo menos 100 metro de dist\u00e2ncia da ex-mulher, ap\u00f3s Joelma registrar Boletim de Ocorr\u00eancia contra ele se dizendo amea\u00e7ada. Recentemente, eles voltaram a fazer show juntos, mas acabou em confus\u00e3o.<\/h3>\n<h3 style=\"text-align: justify;\">O \u00faltimo desintendimento de que se ouviu falar entre os m\u00fasicos diz respeito ao filho Yago, de 19 anos, que chegou a divulgar um v\u00eddeo afirmando que n\u00e3o est\u00e1 impedindo de ver o pai, ap\u00f3s o pr\u00f3prio Chimbinha ter revelado esta proibi\u00e7\u00e3o em entrevistas a programas de TV.<\/h3>\n<h3 style=\"text-align: justify;\">Outro ponto de disc\u00f3rdia entre o ex-casal \u00e9 a divis\u00e3o dos direitos da banda Calypso. Joelma havia divulgado que det\u00e9m 60% do grupo, contra 40% do m\u00fasico.<\/h3>\n","protected":false},"excerpt":{"rendered":"<p>Desde que anunciaram o fim do casamento de 18 anos em agosto deste ano,\u00a0Joelma e Chimbinha, da banda Calypso, n\u00e3o param de acumular pol\u00eamicas. Neste s\u00e1bado (17), a coluna Retratos da Vida, do jornal Extra, anunciou mais um cap\u00edtulo dessa longa novela. Segundo a publica\u00e7\u00e3o, Chimbinha teria confidenciado a amigos pr\u00f3ximos que acredita estar sendo [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_links_to":"","_links_to_target":""},"categories":[14,81,21,33,1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/posts\/43763"}],"collection":[{"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/comments?post=43763"}],"version-history":[{"count":2,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/posts\/43763\/revisions"}],"predecessor-version":[{"id":43778,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/posts\/43763\/revisions\/43778"}],"wp:attachment":[{"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/media?parent=43763"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/categories?post=43763"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/tags?post=43763"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}