{"id":43803,"date":"2015-10-18T22:55:46","date_gmt":"2015-10-19T01:55:46","guid":{"rendered":"http:\/\/www.blogdotarugao.com.br\/v1\/?p=43803"},"modified":"2015-10-18T22:55:46","modified_gmt":"2015-10-19T01:55:46","slug":"mais-uma-de-dilma-dilma-atrasa-repasse-de-r-29-bi-para-escolas","status":"publish","type":"post","link":"https:\/\/www.blogdotarugao.com.br\/v1\/2015\/10\/18\/mais-uma-de-dilma-dilma-atrasa-repasse-de-r-29-bi-para-escolas\/","title":{"rendered":"Mais uma de Dilma : Dilma atrasa repasse de R$ 2,9 bi para escolas"},"content":{"rendered":"<h3 style=\"text-align: justify;\"><img loading=\"lazy\" class=\"alignright  wp-image-43804\" src=\"http:\/\/www.blogdotarugao.com.br\/v1\/wp-content\/uploads\/2015\/10\/Dilma-BBB-300x168.jpg\" alt=\"Dilma-BBB-300x168\" width=\"589\" height=\"330\" \/><\/h3>\n<h3 style=\"text-align: justify;\">No ano em que escolheu o slogan \u201cP\u00e1tria Educadora\u201d, a gest\u00e3o Dilma Rousseff ainda n\u00e3o repassou R$ 2,9 bilh\u00f5es previstos a escolas p\u00fablicas de educa\u00e7\u00e3o infantil e de ensinos fundamental e m\u00e9dio de todo o Pa\u00eds. Al\u00e9m de custear pequenos reparos e compra de materiais, a verba do Programa Dinheiro Direto na Escola (PDDE) \u00e9 usada em a\u00e7\u00f5es pedag\u00f3gicas, como oficinas das escolas de tempo integral.<\/h3>\n<h3 style=\"text-align: justify;\">O governo federal diz que o recurso ser\u00e1 pago entre este m\u00eas e o pr\u00f3ximo e afirma tamb\u00e9m que a iniciativa ser\u00e1 reestruturada. Criado em 1995, o PDDE envia recursos para conselhos escolares ou associa\u00e7\u00f5es de pais e mestres, o que d\u00e1 mais autonomia nos gastos. O programa \u00e9 dividido no m\u00f3dulo b\u00e1sico, para pequenas compras e obras, e em 11 a\u00e7\u00f5es agregadas \u2013 de incentivo \u00e0 cultura, esporte ou de ensino integral, por exemplo.<\/h3>\n","protected":false},"excerpt":{"rendered":"<p>No ano em que escolheu o slogan \u201cP\u00e1tria Educadora\u201d, a gest\u00e3o Dilma Rousseff ainda n\u00e3o repassou R$ 2,9 bilh\u00f5es previstos a escolas p\u00fablicas de educa\u00e7\u00e3o infantil e de ensinos fundamental e m\u00e9dio de todo o Pa\u00eds. Al\u00e9m de custear pequenos reparos e compra de materiais, a verba do Programa Dinheiro Direto na Escola (PDDE) \u00e9 [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_links_to":"","_links_to_target":""},"categories":[5],"tags":[],"_links":{"self":[{"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/posts\/43803"}],"collection":[{"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/comments?post=43803"}],"version-history":[{"count":1,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/posts\/43803\/revisions"}],"predecessor-version":[{"id":43805,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/posts\/43803\/revisions\/43805"}],"wp:attachment":[{"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/media?parent=43803"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/categories?post=43803"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/tags?post=43803"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}