{"id":44819,"date":"2015-11-06T15:20:48","date_gmt":"2015-11-06T18:20:48","guid":{"rendered":"http:\/\/www.blogdotarugao.com.br\/v1\/?p=44819"},"modified":"2015-11-06T15:37:29","modified_gmt":"2015-11-06T18:37:29","slug":"itapetinga-alifer-comete-suicidio-no-quintas-do-morumbi","status":"publish","type":"post","link":"https:\/\/www.blogdotarugao.com.br\/v1\/2015\/11\/06\/itapetinga-alifer-comete-suicidio-no-quintas-do-morumbi\/","title":{"rendered":"ITAPETINGA: ALIFER COMETE SUIC\u00cdDIO NO QUINTAS DO MORUMBI"},"content":{"rendered":"<p><img loading=\"lazy\" class=\"  wp-image-44820 alignleft\" src=\"http:\/\/www.blogdotarugao.com.br\/v1\/wp-content\/uploads\/2015\/11\/Alfer.jpg\" alt=\"Alfer\" width=\"585\" height=\"926\" srcset=\"https:\/\/www.blogdotarugao.com.br\/v1\/wp-content\/uploads\/2015\/11\/Alfer.jpg 402w, https:\/\/www.blogdotarugao.com.br\/v1\/wp-content\/uploads\/2015\/11\/Alfer-190x300.jpg 190w\" sizes=\"(max-width: 585px) 100vw, 585px\" \/><\/p>\n<h3 style=\"text-align: justify;\">Na noite desta quinta-feira (05) por volta de 22:00hs, uma not\u00edcia triste tomou conta do bairro Quintas do Morumbi. O jovem Alifer Santos Pires de 18 anos, acabou dando cabo da sua pr\u00f3pria vida. Ele foi encontrado em um dos c\u00f4modos da casa (quarto), onde o mesmo amarrou o len\u00e7ol no telhado e acabou se suicidando, se enforcando.<\/h3>\n<h3 style=\"text-align: justify;\">Os familiares de Alifer, achavam que ele estava dormindo, mas infelizmente a m\u00e3e dele, foi at\u00e9 o quarto e se deparou com a triste situa\u00e7\u00e3o. O corpo do Jovem foi encaminhado para o IML de Vit\u00f3ria da Conquista.<\/h3>\n<h3 style=\"text-align: justify;\">Alifer \u00e9 morador da rua Camilo Brito no Quintsas do Morumbi, familiares sofrem com o acontecido.<\/h3>\n","protected":false},"excerpt":{"rendered":"<p>Na noite desta quinta-feira (05) por volta de 22:00hs, uma not\u00edcia triste tomou conta do bairro Quintas do Morumbi. O jovem Alifer Santos Pires de 18 anos, acabou dando cabo da sua pr\u00f3pria vida. Ele foi encontrado em um dos c\u00f4modos da casa (quarto), onde o mesmo amarrou o len\u00e7ol no telhado e acabou se [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_links_to":"","_links_to_target":""},"categories":[6,2,1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/posts\/44819"}],"collection":[{"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/comments?post=44819"}],"version-history":[{"count":3,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/posts\/44819\/revisions"}],"predecessor-version":[{"id":44823,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/posts\/44819\/revisions\/44823"}],"wp:attachment":[{"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/media?parent=44819"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/categories?post=44819"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/tags?post=44819"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}