{"id":45124,"date":"2015-11-11T12:59:56","date_gmt":"2015-11-11T15:59:56","guid":{"rendered":"http:\/\/www.blogdotarugao.com.br\/v1\/?p=45124"},"modified":"2015-11-11T12:59:56","modified_gmt":"2015-11-11T15:59:56","slug":"prefeitura-abre-vagas-em-concurso-publico-com-salarios-que-chegam-a-r-3-mil","status":"publish","type":"post","link":"https:\/\/www.blogdotarugao.com.br\/v1\/2015\/11\/11\/prefeitura-abre-vagas-em-concurso-publico-com-salarios-que-chegam-a-r-3-mil\/","title":{"rendered":"Prefeitura abre vagas em concurso p\u00fablico com sal\u00e1rios que chegam a R$ 3 mil"},"content":{"rendered":"<h3><img loading=\"lazy\" class=\" wp-image-23708 alignleft\" src=\"http:\/\/www.blogdotarugao.com.br\/v1\/wp-content\/uploads\/2015\/01\/concursob.jpg\" alt=\"concursob\" width=\"585\" height=\"439\" srcset=\"https:\/\/www.blogdotarugao.com.br\/v1\/wp-content\/uploads\/2015\/01\/concursob.jpg 485w, https:\/\/www.blogdotarugao.com.br\/v1\/wp-content\/uploads\/2015\/01\/concursob-300x225.jpg 300w\" sizes=\"(max-width: 585px) 100vw, 585px\" \/>As inscri\u00e7\u00f5es seguem at\u00e9 o dia 9 de dezembro de 2015 e podem ser feitas presencialmente ou pela internet<\/h3>\n<h3 class=\"bodytext\" style=\"text-align: justify;\">O Servi\u00e7o Aut\u00f4nomo de \u00c1gua e Esgoto (SAAE) de Correntina, na Bahia, est\u00e1 com inscri\u00e7\u00f5es abertas para 12 vagas, al\u00e9m de forma\u00e7\u00e3o de cadastro reserva em Concurso P\u00fablico. A jornada de trabalho \u00e9 de 40h semanais e os sal\u00e1rios variam de R$ 881,00 a R$ 3.651,00 mensais. <b><a class=\"external-link-new-window\" title=\"Opens external link in new window\" href=\"https:\/\/site.pciconcursos.com.br\/arquivo\/1337006.pdf\" target=\"https:\/\/site.pciconcursos.com.br\/arquivo\/1337006.pdf\">Veja edital<\/a><\/b>.<\/p>\n<p>As oportunidades s\u00e3o: Auxiliar de Servi\u00e7os Gerais (2); Agente de Portaria (1); Operador Pequeno Sistema (1); Pedreiro (1); Motorista (1); Encanador (1); Leiturista (2); Auxiliar de Administra\u00e7\u00e3o (2); Operador de Eta (1) e T\u00e9cnico de Contabilidade. Tamb\u00e9m ser\u00e1 feito cadastro reserva.<\/p>\n<p>As inscri\u00e7\u00f5es seguem at\u00e9 o dia 9 de dezembro de 2015 e podem ser feitas presencialmente ou pela internet. De forma presencial o candidato deve ir at\u00e9 a rua Manoel Greg\u00f3cio, n\u00ba 151, Correntina, das 8h \u00e0s 12h e das 14h \u00e0s 17h30. Online \u00e9 preciso acessar o <b><a class=\"external-link-new-window\" title=\"Opens external link in new window\" href=\"http:\/\/www.magnusconcursos.com.br\/\" target=\"www.magnusconcursos.com.br\">site<\/a><\/b>. N\u00e3o esque\u00e7a que a inscri\u00e7\u00e3o pela internet s\u00f3 ser\u00e1 validada ap\u00f3s o recolhimento da taxa de inscri\u00e7\u00e3o.<\/p>\n<p>Os candidatos passam por tr\u00eas categorias de provas, a primeira \u00e9 a objetiva de m\u00faltipla escolha, a segunda \u00e9 a pr\u00e1tica e a \u00faltima a de t\u00edtulos. A avalia\u00e7\u00e3o objetiva est\u00e1 prevista para o dia 10 de janeiro de 2016 e a pr\u00e1tica para duas semanas depois, dia 24 de janeiro de 2016.<\/h3>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>As inscri\u00e7\u00f5es seguem at\u00e9 o dia 9 de dezembro de 2015 e podem ser feitas presencialmente ou pela internet O Servi\u00e7o Aut\u00f4nomo de \u00c1gua e Esgoto (SAAE) de Correntina, na Bahia, est\u00e1 com inscri\u00e7\u00f5es abertas para 12 vagas, al\u00e9m de forma\u00e7\u00e3o de cadastro reserva em Concurso P\u00fablico. A jornada de trabalho \u00e9 de 40h semanais [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_links_to":"","_links_to_target":""},"categories":[6,70,1,36],"tags":[],"_links":{"self":[{"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/posts\/45124"}],"collection":[{"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/comments?post=45124"}],"version-history":[{"count":0,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/posts\/45124\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/media?parent=45124"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/categories?post=45124"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/tags?post=45124"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}