{"id":46699,"date":"2015-12-07T11:26:52","date_gmt":"2015-12-07T14:26:52","guid":{"rendered":"http:\/\/www.blogdotarugao.com.br\/v1\/?p=46699"},"modified":"2015-12-07T11:27:12","modified_gmt":"2015-12-07T14:27:12","slug":"adolescente-de-15-anos-e-arrastada-por-correnteza-e-morre-na-zona-rural-de-brumado","status":"publish","type":"post","link":"https:\/\/www.blogdotarugao.com.br\/v1\/2015\/12\/07\/adolescente-de-15-anos-e-arrastada-por-correnteza-e-morre-na-zona-rural-de-brumado\/","title":{"rendered":"Adolescente de 15 anos \u00e9 arrastada por correnteza e morre na zona rural"},"content":{"rendered":"<h3 style=\"text-align: justify;\"><strong><img loading=\"lazy\" class=\"  wp-image-46700 alignleft\" src=\"http:\/\/www.blogdotarugao.com.br\/v1\/wp-content\/uploads\/2015\/12\/Garota.jpg\" alt=\"Garota\" width=\"584\" height=\"438\" srcset=\"https:\/\/www.blogdotarugao.com.br\/v1\/wp-content\/uploads\/2015\/12\/Garota.jpg 600w, https:\/\/www.blogdotarugao.com.br\/v1\/wp-content\/uploads\/2015\/12\/Garota-300x225.jpg 300w\" sizes=\"(max-width: 584px) 100vw, 584px\" \/>Carro em que a fam\u00edlia estava foi colhido por uma correnteza, que surgiu de repente. A garota n\u00e3o conseguiu sair a tempo do ve\u00edculo.<\/strong><\/h3>\n<h3 style=\"text-align: justify;\">A chuva da tarde deste domingo (6), foi intensa em algumas localidades da zona rural do munic\u00edpio e provocou uma forte correnteza em um riacho, situado na comunidade do S\u00edtio S\u00e3o Jos\u00e9, em Brumado.O ve\u00edculo que seu pai conduzia foi pego de surpresa e n\u00e3o conseguiu vencer a enchente. O carro foi arrastado bruscamente pela correnteza, provocando uma grande trag\u00e9dia, onde a adolescente Paula Cristina Alves de Souza, 15 anos, se encontrava com a fam\u00edlia e acabou morrendo. A v\u00edtima era uma estudante exemplar, sendo reconhecida pelo seu talento e dedica\u00e7\u00e3o aos estudos, o incidente acabou tirando a vida prematuramente da jovem adolescente, que tinha um futuro promissor.<\/h3>\n","protected":false},"excerpt":{"rendered":"<p>Carro em que a fam\u00edlia estava foi colhido por uma correnteza, que surgiu de repente. A garota n\u00e3o conseguiu sair a tempo do ve\u00edculo. A chuva da tarde deste domingo (6), foi intensa em algumas localidades da zona rural do munic\u00edpio e provocou uma forte correnteza em um riacho, situado na comunidade do S\u00edtio S\u00e3o [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_links_to":"","_links_to_target":""},"categories":[6,70,1,3],"tags":[],"_links":{"self":[{"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/posts\/46699"}],"collection":[{"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/comments?post=46699"}],"version-history":[{"count":2,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/posts\/46699\/revisions"}],"predecessor-version":[{"id":46702,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/posts\/46699\/revisions\/46702"}],"wp:attachment":[{"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/media?parent=46699"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/categories?post=46699"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/tags?post=46699"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}