{"id":46788,"date":"2015-12-08T23:30:57","date_gmt":"2015-12-09T02:30:57","guid":{"rendered":"http:\/\/www.blogdotarugao.com.br\/v1\/?p=46788"},"modified":"2015-12-08T23:30:57","modified_gmt":"2015-12-09T02:30:57","slug":"papa-francisco-da-inicio-ao-jubileu-diante-de-50-mil-de-fieis-no-vaticano","status":"publish","type":"post","link":"https:\/\/www.blogdotarugao.com.br\/v1\/2015\/12\/08\/papa-francisco-da-inicio-ao-jubileu-diante-de-50-mil-de-fieis-no-vaticano\/","title":{"rendered":"Papa Francisco d\u00e1 in\u00edcio ao Jubileu diante de 50 mil de fi\u00e9is no Vaticano"},"content":{"rendered":"<h3 style=\"text-align: justify;\"><img loading=\"lazy\" class=\"aligncenter  wp-image-46789\" src=\"http:\/\/www.blogdotarugao.com.br\/v1\/wp-content\/uploads\/2015\/12\/papa.jpg\" alt=\"papa\" width=\"580\" height=\"325\" \/><\/h3>\n<h3 style=\"text-align: justify;\">O papa Francisco deu in\u00edcio nesta ter\u00e7a-feira (8), no Vaticano, ao Jubileu Extraordin\u00e1rio da Miseric\u00f3rdia, ano sagrado para os cat\u00f3licos.<\/h3>\n<h3 style=\"text-align: justify;\">Diante de cerca de 50 mil fi\u00e9is, o pont\u00edfice celebrou uma missa e abriu a Porta Santa da bas\u00edlica de S\u00e3o Pedro, rito que marca o come\u00e7o do Jubileu.<\/h3>\n<h3 style=\"text-align: justify;\">Pela porta, que geralmente permanece fechada, Francisco entrou na bas\u00edlica, seguido pelo papa em\u00e9rito Bento 16. \u00c9 a primeira vez na hist\u00f3ria que dois pont\u00edfices inauguram um Jubileu.<\/h3>\n<h3 style=\"text-align: justify;\">Com o ato simb\u00f3lico, Francisco fez um apelo \u00e0 Igreja para que se &#8220;abra ao mundo&#8221;, respeite o pr\u00f3prio &#8220;impulso mission\u00e1rio&#8221; de ser &#8220;samaritano&#8221;.<img loading=\"lazy\" class=\"aligncenter  wp-image-46790\" src=\"http:\/\/www.blogdotarugao.com.br\/v1\/wp-content\/uploads\/2015\/12\/papa2.jpg\" alt=\"papa2\" width=\"581\" height=\"428\" \/><\/h3>\n<h3 style=\"text-align: justify;\">&#8220;Devemos antepor a miseric\u00f3rdia ao julgamento, e em qualquer ocasi\u00e3o o julgamento de Deus se dar\u00e1 sob a luz de seu perd\u00e3o&#8221;, disse o papa.<\/h3>\n<h3 style=\"text-align: justify;\">A cerim\u00f4nia foi marcada por um <a href=\"http:\/\/www1.folha.uol.com.br\/mundo\/2015\/12\/1716004-roma-reforca-seguranca-para-o-jubileu-que-comeca-nesta-terca.shtml\">forte esquema de seguran\u00e7a<\/a>. Desde o in\u00edcio da manh\u00e3, a pol\u00edcia revistou peregrinos, jornalistas, diplomatas e at\u00e9 padres que entravam na \u00e1rea, em controles colocados a v\u00e1rias quadras da Pra\u00e7a S\u00e3o Pedro.<\/h3>\n<h3 style=\"text-align: justify;\">O espa\u00e7o a\u00e9reo sobre a maior parte de Roma foi fechado e as autoridades proibiram o transporte de gasolina, g\u00e1s, armas, explosivos e fogos de artif\u00edcio.<\/h3>\n<h3 style=\"text-align: justify;\">Durante a missa, Francisco pediu aos fi\u00e9is que deixem &#8220;de lado todo o medo e pavor&#8221;. &#8220;Em vez disso, vamos experimentar a alegria do encontro com a gra\u00e7a que transforma todas as coisas&#8221;, acrescentou.<\/h3>\n","protected":false},"excerpt":{"rendered":"<p>O papa Francisco deu in\u00edcio nesta ter\u00e7a-feira (8), no Vaticano, ao Jubileu Extraordin\u00e1rio da Miseric\u00f3rdia, ano sagrado para os cat\u00f3licos. Diante de cerca de 50 mil fi\u00e9is, o pont\u00edfice celebrou uma missa e abriu a Porta Santa da bas\u00edlica de S\u00e3o Pedro, rito que marca o come\u00e7o do Jubileu. Pela porta, que geralmente permanece fechada, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_links_to":"","_links_to_target":""},"categories":[5],"tags":[],"_links":{"self":[{"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/posts\/46788"}],"collection":[{"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/comments?post=46788"}],"version-history":[{"count":1,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/posts\/46788\/revisions"}],"predecessor-version":[{"id":46791,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/posts\/46788\/revisions\/46791"}],"wp:attachment":[{"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/media?parent=46788"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/categories?post=46788"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/tags?post=46788"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}