{"id":46900,"date":"2015-12-10T21:47:53","date_gmt":"2015-12-11T00:47:53","guid":{"rendered":"http:\/\/www.blogdotarugao.com.br\/v1\/?p=46900"},"modified":"2015-12-10T21:47:53","modified_gmt":"2015-12-11T00:47:53","slug":"brasil-lutador-de-jiu-jitsu-pega-23-anos-de-cadeia-por-tortura-e-morte-do-filho-de-2-anos","status":"publish","type":"post","link":"https:\/\/www.blogdotarugao.com.br\/v1\/2015\/12\/10\/brasil-lutador-de-jiu-jitsu-pega-23-anos-de-cadeia-por-tortura-e-morte-do-filho-de-2-anos\/","title":{"rendered":"Brasil: Lutador de Jiu-J\u00edtsu pega 23 anos de cadeia por tortura e morte do filho de 2 anos"},"content":{"rendered":"<h3 style=\"text-align: justify;\"><strong>A m\u00e3e do menino recebeu pena de 9 anos, mas vai recorrer em liberdade. Segundo den\u00fancia em Vinhedo, pai torturou o filho; ele vai recorrer.<\/strong><img loading=\"lazy\" class=\"aligncenter  wp-image-46901\" src=\"http:\/\/www.blogdotarugao.com.br\/v1\/wp-content\/uploads\/2015\/12\/lutador-3.jpg\" alt=\"lutador-3\" width=\"581\" height=\"305\" srcset=\"https:\/\/www.blogdotarugao.com.br\/v1\/wp-content\/uploads\/2015\/12\/lutador-3.jpg 1200w, https:\/\/www.blogdotarugao.com.br\/v1\/wp-content\/uploads\/2015\/12\/lutador-3-300x158.jpg 300w, https:\/\/www.blogdotarugao.com.br\/v1\/wp-content\/uploads\/2015\/12\/lutador-3-1024x538.jpg 1024w\" sizes=\"(max-width: 581px) 100vw, 581px\" \/>A Justi\u00e7a de Vinhedo (SP) condenou o lutador de jiu-j\u00edtsu Tiago Ahmar de Moraes, de 27 anos, a 23 anos e quatro meses de deten\u00e7\u00e3o em regime fechado pela morte do filho dele Yago Vinicius de Moraes, de 2 anos, ocorrida em julho de 2014.<\/h3>\n<h3 class=\"wp-caption alignright\" style=\"text-align: justify; width: 379px;\"><img loading=\"lazy\" class=\"\" src=\"http:\/\/i.imgur.com\/cQUB0tG.png\" alt=\"\" width=\"369\" height=\"245\" \/><\/h3>\n<p class=\"wp-caption-text\">Thiago Ahmar Moraes foi condenado a 23 anos e 4 meses de pris\u00e3o<\/p>\n<h3 style=\"text-align: justify;\">Segundo o Minist\u00e9rio P\u00fablico, a v\u00edtima foi torturada pelo pai. O advogado dele, Aryldo de Oliveira de Paula, disse que vai recorrer da decis\u00e3o.<\/h3>\n<h3 style=\"text-align: justify;\">A m\u00e3e da crian\u00e7a, Cristiana dos Santos Costa, recebeu a pena de nove anos e quatro meses, mas poder\u00e1 recorrer em liberdade. Os defensores dela ainda n\u00e3o foram notificados e n\u00e3o v\u00e3o comentar a senten\u00e7a. Sobre o fato de a m\u00e3e recorrer em liberdade, a ju\u00edza Euzy Lopes Feij\u00f3 Liberati escreveu: \u201ctendo em vista n\u00e3o haver ind\u00edcios de que v\u00e1 atentar contra a ordem p\u00fablica ou, ao menos por ora, que comprometer\u00e1 a aplica\u00e7\u00e3o da lei penal\u201d.Ela respondeu ao processo por omiss\u00e3o.<\/h3>\n<h3 style=\"text-align: justify;\"><span id=\"more-84713\"><\/span>J\u00e1 em rela\u00e7\u00e3o ao pai, a ju\u00edza relatou: \u201c<em>O regime de cumprimento da pena, para o r\u00e9u, ser\u00e1 o fechado, n\u00e3o somente pela quantidade da pena, mas tamb\u00e9m por seu antecedente e sua personalidade perigosa e agressiva\u201d<\/em>. Moraes est\u00e1 preso em Trememb\u00e9 (SP), onde permanecer\u00e1, segundo sua defesa.<\/h3>\n<p><!--more--><\/p>\n<p><strong>\u201cViol\u00eancia tem um car\u00e1ter pedag\u00f3gico\u201d<\/strong><\/p>\n<div class=\"wp-caption alignright\" style=\"width: 354px;\"><img loading=\"lazy\" class=\"\" src=\"http:\/\/s2.glbimg.com\/60XAJbXZwq0-dS7KuoaDh9ddONE=\/300x225\/s.glbimg.com\/jo\/g1\/f\/original\/2015\/12\/10\/vinhedo.jpg\" alt=\"\" width=\"344\" height=\"258\" \/><\/p>\n<h3 class=\"wp-caption-text\" style=\"text-align: justify;\">Pais do menino Yago quando procuravam atendimento m\u00e9dico<\/h3>\n<\/div>\n<h3 style=\"text-align: justify;\">Tiago Moraes foi preso em agosto de 2014 e ao chegar na Delegacia de Vinhedo, onde o caso foi investigado, negou torturar o filho, mas admitiu que em alguns momentos usava da viol\u00eancia para educar. \u201cA viol\u00eancia tem um car\u00e1ter pedag\u00f3gico, e algumas vezes eu tive que usar desse recurso para educar, mas sempre soube o limite, porque eu sabia que era muito mais forte que ele\u201d, chegou a dizer.<\/h3>\n<h3 style=\"text-align: justify;\"><strong>Torturas<\/strong><\/h3>\n<h3 style=\"text-align: justify;\">O MP entendeu que a morte de Yago foi decorrente de torturas sofridas pela crian\u00e7a desde janeiro de 2014, quando o casal passou a morar junto, e ofereceu a den\u00fancia. J\u00e1 a Pol\u00edcia Civil indiciou o pai por homic\u00eddio qualificado e s\u00f3 depois, quando finalizou o inqu\u00e9rito, houve o indiciamento por tortura. Cristiana foi denunciada pelo Minist\u00e9rio P\u00fablico\u00a0 por ter se omitido ao longo dos meses. Os pais chegaram, no per\u00edodo de inqu\u00e9rito, a dizer que as les\u00f5es na crian\u00e7a foram decorrentes a uma queda de um brinquedo em um parquinho, mas os investigadores desconfiaram desta vers\u00e3o.<\/h3>\n<p><img loading=\"lazy\" class=\" aligncenter\" src=\"http:\/\/img.r7.com\/images\/2014\/08\/14\/5mke3ymi6q_8ls6oqtxsb_file?dimensions=780x536&amp;no_crop=true\" alt=\"\" width=\"543\" height=\"407\" \/><\/p>\n<h3 style=\"text-align: justify;\"><strong>Laudos<\/strong><\/h3>\n<h3 style=\"text-align: justify;\">A Promotoria\u00a0 afirmou que o laudo do Instituto M\u00e9dico Legal (IML) apontou que a causa da morte de Yago foi traumatismo craniano,\u00a0 mas que no documento n\u00e3o constam outras les\u00f5es sofridas pela crian\u00e7a. Segundo o promotor Rog\u00e9rio Sanches, o prontu\u00e1rio da entrada do menino na Unidade de Pronto Atendimento (UPA) e tomografias feitas no HC da Unicamp indicam que ele sofreu m\u00faltiplas les\u00f5es pelo corpo e les\u00f5es de rim e f\u00edgado. O advogado de defesa de Tiago Moraes afirmou que os laudos da per\u00edcia n\u00e3o s\u00e3o conclusivos e que um contra-laudo comprovou que os ferimentos s\u00e3o compat\u00edveis com uma queda de um brinquedo.<\/h3>\n","protected":false},"excerpt":{"rendered":"<p>A m\u00e3e do menino recebeu pena de 9 anos, mas vai recorrer em liberdade. Segundo den\u00fancia em Vinhedo, pai torturou o filho; ele vai recorrer.A Justi\u00e7a de Vinhedo (SP) condenou o lutador de jiu-j\u00edtsu Tiago Ahmar de Moraes, de 27 anos, a 23 anos e quatro meses de deten\u00e7\u00e3o em regime fechado pela morte do [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_links_to":"","_links_to_target":""},"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/posts\/46900"}],"collection":[{"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/comments?post=46900"}],"version-history":[{"count":1,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/posts\/46900\/revisions"}],"predecessor-version":[{"id":46902,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/posts\/46900\/revisions\/46902"}],"wp:attachment":[{"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/media?parent=46900"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/categories?post=46900"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/tags?post=46900"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}