{"id":62572,"date":"2016-06-14T19:30:58","date_gmt":"2016-06-14T22:30:58","guid":{"rendered":"http:\/\/www.blogdotarugao.com.br\/v1\/?p=62572"},"modified":"2016-06-14T19:30:58","modified_gmt":"2016-06-14T22:30:58","slug":"homem-e-preso-por-torturar-a-mae-com-uma-faca","status":"publish","type":"post","link":"https:\/\/www.blogdotarugao.com.br\/v1\/2016\/06\/14\/homem-e-preso-por-torturar-a-mae-com-uma-faca\/","title":{"rendered":"Homem \u00e9 preso por torturar a m\u00e3e com uma faca"},"content":{"rendered":"<h3 style=\"text-align: justify;\"><img loading=\"lazy\" class=\"  wp-image-62573 alignleft\" src=\"http:\/\/www.blogdotarugao.com.br\/v1\/wp-content\/uploads\/2016\/06\/amea\u00e7ou-a-m\u00e3e.jpg\" alt=\"amea\u00e7ou a m\u00e3e\" width=\"584\" height=\"438\" srcset=\"https:\/\/www.blogdotarugao.com.br\/v1\/wp-content\/uploads\/2016\/06\/amea\u00e7ou-a-m\u00e3e.jpg 800w, https:\/\/www.blogdotarugao.com.br\/v1\/wp-content\/uploads\/2016\/06\/amea\u00e7ou-a-m\u00e3e-300x225.jpg 300w\" sizes=\"(max-width: 584px) 100vw, 584px\" \/>Em Laje, o usu\u00e1rio de drogas Pedro Moreira, de 26 anos, queria dinheiro para comprar drogas, a mas a mulher se negou a dar<\/h3>\n<h3 style=\"text-align: justify;\">Investigadores da Delegacia Territorial (DT), de Laje (BA), prenderam Pedro Miranda Moreira, de 26 anos, que agrediu e torturou a pr\u00f3pria m\u00e3e, a lavradora Maria Ant\u00f4nia de Miranda, 49.<\/h3>\n<h3 style=\"text-align: justify;\">De acordo com a v\u00edtima, que compareceu \u00e0 delegacia para registrar queixa, o filho estava sob efeito de drogas quando a jogou no ch\u00e3o, deu socos e pontap\u00e9s e depois, sentado sobre seu corpo, come\u00e7ou a fazer cortes com uma faca do tipo peixeira nas m\u00e3os e pernas dela.<\/h3>\n<h3 style=\"text-align: justify;\">Maria Ant\u00f4nia, que \u00e9 vi\u00fava e reside com o \u00fanico filho, disse que Pedro fez isso tudo foi porque ela se negou a dar dinheiro para que comprasse mais drogas.<\/h3>\n<h3 style=\"text-align: justify;\">Autuado em flagrante por les\u00e3o corporal, ele est\u00e1 custodiado na DT\/Laje \u00e0 disposi\u00e7\u00e3o da Justi\u00e7a.<\/h3>\n","protected":false},"excerpt":{"rendered":"<p>Em Laje, o usu\u00e1rio de drogas Pedro Moreira, de 26 anos, queria dinheiro para comprar drogas, a mas a mulher se negou a dar Investigadores da Delegacia Territorial (DT), de Laje (BA), prenderam Pedro Miranda Moreira, de 26 anos, que agrediu e torturou a pr\u00f3pria m\u00e3e, a lavradora Maria Ant\u00f4nia de Miranda, 49. De acordo [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_links_to":"","_links_to_target":""},"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/posts\/62572"}],"collection":[{"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/comments?post=62572"}],"version-history":[{"count":0,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/posts\/62572\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/media?parent=62572"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/categories?post=62572"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/tags?post=62572"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}