{"id":62849,"date":"2016-06-18T09:32:31","date_gmt":"2016-06-18T12:32:31","guid":{"rendered":"http:\/\/www.blogdotarugao.com.br\/v1\/?p=62849"},"modified":"2016-06-18T09:32:31","modified_gmt":"2016-06-18T12:32:31","slug":"caso-jessica-americo-francisco-vai-responder-por-homicidio-qualificado-define-justica","status":"publish","type":"post","link":"https:\/\/www.blogdotarugao.com.br\/v1\/2016\/06\/18\/caso-jessica-americo-francisco-vai-responder-por-homicidio-qualificado-define-justica\/","title":{"rendered":"Caso J\u00e9ssica: Am\u00e9rico Francisco vai responder por homic\u00eddio qualificado, define Justi\u00e7a"},"content":{"rendered":"<h3 style=\"text-align: justify;\"><img loading=\"lazy\" class=\"  wp-image-62850 alignleft\" src=\"http:\/\/www.blogdotarugao.com.br\/v1\/wp-content\/uploads\/2016\/06\/am\u00e9rico-1.jpg\" alt=\"am\u00e9rico-1\" width=\"587\" height=\"439\" srcset=\"https:\/\/www.blogdotarugao.com.br\/v1\/wp-content\/uploads\/2016\/06\/am\u00e9rico-1.jpg 543w, https:\/\/www.blogdotarugao.com.br\/v1\/wp-content\/uploads\/2016\/06\/am\u00e9rico-1-300x224.jpg 300w\" sizes=\"(max-width: 587px) 100vw, 587px\" \/>Am\u00e9rico Francisco Vinhas Neto, de 24 anos, vai responder pelo crime de homic\u00eddio qualificado. Esta \u00e9 a decis\u00e3o da Justi\u00e7a ap\u00f3s analisar a natureza do crime que ele cometeu contra J\u00e9ssica da Silva Nascimento. Essa defini\u00e7\u00e3o foi uma solicita\u00e7\u00e3o do Minist\u00e9rio P\u00fablico Estadual como condi\u00e7\u00e3o para o andamento do processo.<\/h3>\n<h3 style=\"text-align: justify;\">Com a decis\u00e3o da ju\u00edza Julliane Nogueira Santana Rios, da Vara da Viol\u00eancia Dom\u00e9stica contra a Mulher, o caso foi remetido para a Vara do J\u00fari. A defesa de \u00a0Am\u00e9rico alega que ele cometeu o crime por estar sob o feito de \u00e1lcool e drogas.<\/h3>\n<h3 style=\"text-align: justify;\">O estudante de engenharia civil est\u00e1 foragido desde o dia 6 de maio, quando teve a pris\u00e3o preventiva decretada.<\/h3>\n<h3 style=\"text-align: justify;\">Ap\u00f3s ser agredida por Am\u00e9rico, J\u00e9ssica foi encaminhada para o Hospital Regional de Vit\u00f3ria da Conquista, onde permaneceu internada por 16 dias em coma na UTI da unidade. Neste per\u00edodo, ela perdeu o beb\u00ea que esperava de apenas quatro meses de gesta\u00e7\u00e3o. No dia 10 de maio J\u00e9ssica n\u00e3o resistiu \u00e0s complica\u00e7\u00f5es do quadro cl\u00ednico e acabou falecendo. Ela deixou um filho de quatro anos.<\/h3>\n<p><!--more--><\/p>\n<h3 style=\"text-align: justify;\">A fam\u00edlia de J\u00e9ssica comemorou a decis\u00e3o da Justi\u00e7a, por n\u00e3o concordar com o delegado que investigou o caso e tipificou o crime como sendo apenas les\u00e3o corporal seguida de morte. Am\u00e9rico poder\u00e1 ser condenado at\u00e9 30 anos de pris\u00e3o.<\/h3>\n<h3 style=\"text-align: justify;\">Fonte: Blog da Gente<\/h3>\n","protected":false},"excerpt":{"rendered":"<p>Am\u00e9rico Francisco Vinhas Neto, de 24 anos, vai responder pelo crime de homic\u00eddio qualificado. Esta \u00e9 a decis\u00e3o da Justi\u00e7a ap\u00f3s analisar a natureza do crime que ele cometeu contra J\u00e9ssica da Silva Nascimento. Essa defini\u00e7\u00e3o foi uma solicita\u00e7\u00e3o do Minist\u00e9rio P\u00fablico Estadual como condi\u00e7\u00e3o para o andamento do processo. Com a decis\u00e3o da ju\u00edza [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_links_to":"","_links_to_target":""},"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/posts\/62849"}],"collection":[{"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/comments?post=62849"}],"version-history":[{"count":1,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/posts\/62849\/revisions"}],"predecessor-version":[{"id":62851,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/posts\/62849\/revisions\/62851"}],"wp:attachment":[{"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/media?parent=62849"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/categories?post=62849"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/tags?post=62849"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}