{"id":66232,"date":"2016-08-04T00:38:21","date_gmt":"2016-08-04T03:38:21","guid":{"rendered":"http:\/\/www.blogdotarugao.com.br\/v1\/?p=66232"},"modified":"2016-08-04T00:38:21","modified_gmt":"2016-08-04T03:38:21","slug":"homem-e-executado-com-mais-de-dez-tiros-dentro-do-proprio-veiculo","status":"publish","type":"post","link":"https:\/\/www.blogdotarugao.com.br\/v1\/2016\/08\/04\/homem-e-executado-com-mais-de-dez-tiros-dentro-do-proprio-veiculo\/","title":{"rendered":"Homem \u00e9 executado com mais de dez tiros dentro do pr\u00f3prio ve\u00edculo"},"content":{"rendered":"<h3 style=\"text-align: justify;\"><img loading=\"lazy\" class=\"  wp-image-66233 alignleft\" src=\"http:\/\/www.blogdotarugao.com.br\/v1\/wp-content\/uploads\/2016\/08\/morto-em-c.jpg\" alt=\"morto em c\" width=\"584\" height=\"344\" srcset=\"https:\/\/www.blogdotarugao.com.br\/v1\/wp-content\/uploads\/2016\/08\/morto-em-c.jpg 613w, https:\/\/www.blogdotarugao.com.br\/v1\/wp-content\/uploads\/2016\/08\/morto-em-c-300x177.jpg 300w\" sizes=\"(max-width: 584px) 100vw, 584px\" \/>Mais uma morte violenta foi registrada em Vit\u00f3ria da Conquista na noite nesta quarta-feira (3). O crime aconteceu por volta das 19:30h, no Bairro Senhorinha Cairo.<img loading=\"lazy\" class=\" alignleft\" src=\"https:\/\/3.bp.blogspot.com\/-GrjHOZTVlz8\/V6Kx7RUJmqI\/AAAAAAABb3g\/rqadjh0YALg1zI4fDQOmqZZLcXgXI4gagCLcB\/s640\/Itambagora%2B4.JPG\" alt=\"\" width=\"584\" height=\"387\" \/><\/h3>\n<h3 style=\"text-align: justify;\">De acordo com informa\u00e7\u00f5es, dois indiv\u00edduos a bordo de um veiculo de carroceria de cor preta, executou com mais de 5 tiros o dono de um ferro velho, identificado como Jainilton Coelho de Oliveira, de 25 anos. O mesmo j\u00e1 tinha passagem pela Pol\u00edcia.<img loading=\"lazy\" class=\" alignleft\" src=\"https:\/\/4.bp.blogspot.com\/-IGsLs0pkmMY\/V6KyD6V-cgI\/AAAAAAABb3k\/cQ5PaKhsOqwss-uhp6wD114K1PSHKz5RwCEw\/s640\/9GpRN4o.jpg\" alt=\"\" width=\"584\" height=\"311\" \/><\/h3>\n<h3 style=\"text-align: justify;\">No local algumas testemunhas relataram ter ouvido diversos tiros. Jainilton foi executado dentro do seu carro e n\u00e3o teve tempo de tentar fugir.<\/h3>\n<h3 style=\"text-align: justify;\">Uma Guarni\u00e7\u00e3o da 78\u00ba esteve no local a fim de localizar os atiradores, mas, sem sucesso. Agentes do Departamento de Pol\u00edcia T\u00e9cnica estiveram no local e removeram o corpo de Jainilton para o Instituto M\u00e9dico Legal (IML).<\/h3>\n<h3 style=\"text-align: justify;\">Esse \u00e9 o primeiro homic\u00eddio registrado no m\u00eas de Agosto, com a soma de 116 no ano em Vit\u00f3ria da Conquista. Fonte: Blog do L\u00e9o Santos<\/h3>\n","protected":false},"excerpt":{"rendered":"<p>Mais uma morte violenta foi registrada em Vit\u00f3ria da Conquista na noite nesta quarta-feira (3). O crime aconteceu por volta das 19:30h, no Bairro Senhorinha Cairo. De acordo com informa\u00e7\u00f5es, dois indiv\u00edduos a bordo de um veiculo de carroceria de cor preta, executou com mais de 5 tiros o dono de um ferro velho, identificado [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_links_to":"","_links_to_target":""},"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/posts\/66232"}],"collection":[{"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/comments?post=66232"}],"version-history":[{"count":1,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/posts\/66232\/revisions"}],"predecessor-version":[{"id":66234,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/posts\/66232\/revisions\/66234"}],"wp:attachment":[{"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/media?parent=66232"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/categories?post=66232"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/tags?post=66232"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}