{"id":66995,"date":"2016-08-21T07:40:17","date_gmt":"2016-08-21T10:40:17","guid":{"rendered":"http:\/\/www.blogdotarugao.com.br\/v1\/?p=66995"},"modified":"2016-08-21T07:40:17","modified_gmt":"2016-08-21T10:40:17","slug":"neymar-desabafa-apos-ouro-olimpico-agora-vao-ter-que-me-engolir","status":"publish","type":"post","link":"https:\/\/www.blogdotarugao.com.br\/v1\/2016\/08\/21\/neymar-desabafa-apos-ouro-olimpico-agora-vao-ter-que-me-engolir\/","title":{"rendered":"Neymar desabafa ap\u00f3s ouro ol\u00edmpico: &#8216;Agora v\u00e3o ter que me engolir&#8217;"},"content":{"rendered":"<h3 style=\"text-align: justify;\"><strong><img loading=\"lazy\" class=\"  wp-image-66996 alignleft\" src=\"http:\/\/www.blogdotarugao.com.br\/v1\/wp-content\/uploads\/2016\/08\/NEYMAR.png\" alt=\"NEYMAR\" width=\"585\" height=\"431\" srcset=\"https:\/\/www.blogdotarugao.com.br\/v1\/wp-content\/uploads\/2016\/08\/NEYMAR.png 380w, https:\/\/www.blogdotarugao.com.br\/v1\/wp-content\/uploads\/2016\/08\/NEYMAR-300x221.png 300w\" sizes=\"(max-width: 585px) 100vw, 585px\" \/>O craque Neymar foi o destaque do Brasil na conquista do ouro ol\u00edmpico na noite deste s\u00e1bado (20), no Maracan\u00e3. O atacante marcou o gol brasileiro no empate por 1 a 1, e converteu p\u00eanalti decisivo, que deu o t\u00edtulo ao time comandado por Rog\u00e9rio Micale. Ao fim da partida, ele celebrou a conquista. <\/strong><\/h3>\n<h3 style=\"text-align: justify;\"><strong>\u201cTenho muita coisa para falar. Mas ainda n\u00e3o encontrei palavras. Vou esperar acalmar. S\u00f3 quero agradecer a Deus, minha fam\u00edlia, meus amigos e companheiros. Tivemos momentos dif\u00edceis no in\u00edcio. Fomos criticados e respondemos com o futebol\u201d, disse o camisa 10 em entrevista \u00e0 TV Globo. <\/strong><\/h3>\n<h3 style=\"text-align: justify;\"><strong>Finalizando o discurso, ele deu um aviso. \u201c\u00c9 uma das coisas mais incr\u00edveis que j\u00e1 aconteceram na minha vida. Agora v\u00e3o ter que me engolir\u201d, gritou.<\/strong><\/h3>\n","protected":false},"excerpt":{"rendered":"<p>O craque Neymar foi o destaque do Brasil na conquista do ouro ol\u00edmpico na noite deste s\u00e1bado (20), no Maracan\u00e3. O atacante marcou o gol brasileiro no empate por 1 a 1, e converteu p\u00eanalti decisivo, que deu o t\u00edtulo ao time comandado por Rog\u00e9rio Micale. Ao fim da partida, ele celebrou a conquista. \u201cTenho [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_links_to":"","_links_to_target":""},"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/posts\/66995"}],"collection":[{"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/comments?post=66995"}],"version-history":[{"count":1,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/posts\/66995\/revisions"}],"predecessor-version":[{"id":66997,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/posts\/66995\/revisions\/66997"}],"wp:attachment":[{"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/media?parent=66995"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/categories?post=66995"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/tags?post=66995"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}