{"id":67264,"date":"2016-08-26T07:47:26","date_gmt":"2016-08-26T10:47:26","guid":{"rendered":"http:\/\/www.blogdotarugao.com.br\/v1\/?p=67264"},"modified":"2016-08-26T07:47:26","modified_gmt":"2016-08-26T10:47:26","slug":"consumo-de-tequila-pode-ajudar-a-emagrecer-aponta-estudo","status":"publish","type":"post","link":"https:\/\/www.blogdotarugao.com.br\/v1\/2016\/08\/26\/consumo-de-tequila-pode-ajudar-a-emagrecer-aponta-estudo\/","title":{"rendered":"Consumo de tequila pode ajudar a emagrecer, aponta estudo"},"content":{"rendered":"<div class=\"text-center\">\n<div class=\"box-img\"><img loading=\"lazy\" class=\"  wp-image-67265 alignleft\" src=\"http:\/\/www.blogdotarugao.com.br\/v1\/wp-content\/uploads\/2016\/08\/tq.jpg\" alt=\"tq\" width=\"584\" height=\"430\" srcset=\"https:\/\/www.blogdotarugao.com.br\/v1\/wp-content\/uploads\/2016\/08\/tq.jpg 380w, https:\/\/www.blogdotarugao.com.br\/v1\/wp-content\/uploads\/2016\/08\/tq-300x221.jpg 300w\" sizes=\"(max-width: 584px) 100vw, 584px\" \/><\/p>\n<div class=\"img-legenda\">Foto: Shutterstock<\/div>\n<\/div>\n<\/div>\n<h3 class=\"text-descricao\" style=\"text-align: justify;\">Boa not\u00edcia aos amantes da tequila: o consumo da bebida pode auxiliar na perda de peso. A novidade foi descoberta em um estudo desenvolvido pela Sociedade Americana de Qu\u00edmica, nos EUA. Os resultados mostraram que a planta do agave, com a qual a bebida \u00e9 feita, cont\u00e9m a\u00e7\u00facares com potencial de reduzir os n\u00edveis de glicose no sangue. Esse efeito poderia ajudar pessoas obesas ou diagnosticadas com diabetes tipo 2 a perderem alguns quilos. &#8220;O ado\u00e7ante natural presente na planta de agave n\u00e3o \u00e9 digerido e pode ser utilizado como uma fibra diet\u00e9tica, dado que n\u00e3o elevaria a glicose no sangue&#8221;, diz o artigo publicado pelos cientistas. A pesquisa utilizou um grupo de ratos alimentados com uma dieta padr\u00e3o. <!--more-->Um segundo grupo ingeria os mesmos alimentos, mas com acr\u00e9scimo do ado\u00e7ante de agave \u00e0 \u00e1gua. Ap\u00f3s pesagens e avalia\u00e7\u00f5es semanais do n\u00edvel de glicose dos animais, percebeu-se que aqueles que que ingeriram a \u00e1gua com agave comeram menos, perderam peso e apresentaram queda nos n\u00edveis de glicose no sangue.<\/h3>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Foto: Shutterstock Boa not\u00edcia aos amantes da tequila: o consumo da bebida pode auxiliar na perda de peso. A novidade foi descoberta em um estudo desenvolvido pela Sociedade Americana de Qu\u00edmica, nos EUA. Os resultados mostraram que a planta do agave, com a qual a bebida \u00e9 feita, cont\u00e9m a\u00e7\u00facares com potencial de reduzir os [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_links_to":"","_links_to_target":""},"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/posts\/67264"}],"collection":[{"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/comments?post=67264"}],"version-history":[{"count":1,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/posts\/67264\/revisions"}],"predecessor-version":[{"id":67266,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/posts\/67264\/revisions\/67266"}],"wp:attachment":[{"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/media?parent=67264"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/categories?post=67264"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/tags?post=67264"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}