{"id":68733,"date":"2016-10-12T14:33:20","date_gmt":"2016-10-12T17:33:20","guid":{"rendered":"http:\/\/www.blogdotarugao.com.br\/v1\/?p=68733"},"modified":"2016-10-12T14:33:20","modified_gmt":"2016-10-12T17:33:20","slug":"feto-de-quatro-meses-e-encontrado-em-lixeira-de-hospital","status":"publish","type":"post","link":"https:\/\/www.blogdotarugao.com.br\/v1\/2016\/10\/12\/feto-de-quatro-meses-e-encontrado-em-lixeira-de-hospital\/","title":{"rendered":"Feto de quatro meses \u00e9 encontrado em lixeira de hospital"},"content":{"rendered":"<h3 style=\"text-align: justify;\"><img loading=\"lazy\" class=\"aligncenter  wp-image-68734\" src=\"http:\/\/www.blogdotarugao.com.br\/v1\/wp-content\/uploads\/2016\/10\/brumado.jpg\" alt=\"brumado\" width=\"580\" height=\"427\" srcset=\"https:\/\/www.blogdotarugao.com.br\/v1\/wp-content\/uploads\/2016\/10\/brumado.jpg 380w, https:\/\/www.blogdotarugao.com.br\/v1\/wp-content\/uploads\/2016\/10\/brumado-300x221.jpg 300w\" sizes=\"(max-width: 580px) 100vw, 580px\" \/><\/h3>\n<h3 style=\"text-align: justify;\">Um feto de quatro meses foi encontrado dentro de uma lixeira no Hospital Municipal Professor Magalh\u00e3es Neto, no munic\u00edpio de Brumado, Sert\u00e3o Produtor. De acordo com informa\u00e7\u00f5es do portal G1, funcion\u00e1rios da equipe de higieniza\u00e7\u00e3o da unidade encontraram o feto no final da manh\u00e3 da \u00faltima ter\u00e7a-feira (11) quando recolhiam o lixo. Segundo a Pol\u00edcia Civil, o feto foi recolhido e levado para o Departamento de Pol\u00edcia T\u00e9cnica de Brumado ap\u00f3s uma equipe ser acionada. Ainda de acordo com a publica\u00e7\u00e3o, ainda n\u00e3o h\u00e1 informa\u00e7\u00f5es sobre a identidade da pessoa que jogou o feto na lixeira e o caso est\u00e1 sob investiga\u00e7\u00e3o.<\/h3>\n","protected":false},"excerpt":{"rendered":"<p>Um feto de quatro meses foi encontrado dentro de uma lixeira no Hospital Municipal Professor Magalh\u00e3es Neto, no munic\u00edpio de Brumado, Sert\u00e3o Produtor. De acordo com informa\u00e7\u00f5es do portal G1, funcion\u00e1rios da equipe de higieniza\u00e7\u00e3o da unidade encontraram o feto no final da manh\u00e3 da \u00faltima ter\u00e7a-feira (11) quando recolhiam o lixo. Segundo a Pol\u00edcia [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_links_to":"","_links_to_target":""},"categories":[5,6],"tags":[],"_links":{"self":[{"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/posts\/68733"}],"collection":[{"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/comments?post=68733"}],"version-history":[{"count":1,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/posts\/68733\/revisions"}],"predecessor-version":[{"id":68735,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/posts\/68733\/revisions\/68735"}],"wp:attachment":[{"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/media?parent=68733"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/categories?post=68733"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/tags?post=68733"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}