{"id":7862,"date":"2014-04-26T22:21:09","date_gmt":"2014-04-27T01:21:09","guid":{"rendered":"http:\/\/www.blogdotarugao.com.br\/v1\/?p=7862"},"modified":"2014-04-26T22:21:43","modified_gmt":"2014-04-27T01:21:43","slug":"secretario-morre-em-acidente-automobilistico","status":"publish","type":"post","link":"https:\/\/www.blogdotarugao.com.br\/v1\/2014\/04\/26\/secretario-morre-em-acidente-automobilistico\/","title":{"rendered":"Secret\u00e1rio Morre em Acidente Automobil\u00edstico na BR 407"},"content":{"rendered":"<p>Neste S\u00e1bado (26) por volta de 19:00hs, aconteceu um grave acidente automobil\u00edstico, com v\u00edtima fatal. A colis\u00e3o frontal envolvendo um caminh\u00e3o placa NYQ 2003 de Livramento de Nossa Senhora e um autom\u00f3vel Gol da secret\u00e1ria de sa\u00fade de Contendas, aconteceu\u00a0na\u00a0BR 407, KM 637, trecho entre Sussuarana e Contendas do Sincor\u00e1.<\/p>\n<p><img alt=\"\" src=\"https:\/\/fbcdn-sphotos-h-a.akamaihd.net\/hphotos-ak-prn1\/v\/t34.0-12\/10153028_555515204562308_7350468057564807652_n.jpg?oh=88cc18b77e3bfc020fb37c30a6d69ffe&amp;oe=535ECEA4&amp;__gda__=1398698755_db04bd7aba4a09c3a593f87b22673ab1\" \/><\/p>\n<p><img alt=\"\" src=\"https:\/\/fbcdn-sphotos-h-a.akamaihd.net\/hphotos-ak-prn1\/v\/t34.0-12\/1011812_555514591229036_2761581129585781757_n.jpg?oh=d9412892afcd5626bfc2a3dbc5dabaa9&amp;oe=535EB2FF&amp;__gda__=1398705726_932d526d2b241bda926d90317fb84e59\" \/><\/p>\n<p><img alt=\"\" src=\"https:\/\/fbcdn-sphotos-h-a.akamaihd.net\/hphotos-ak-prn2\/v\/t34.0-12\/1424287_555513944562434_8911097173694665259_n.jpg?oh=6b9554a0204951ad84a51fbc2e8e097e&amp;oe=535EE421&amp;__gda__=1398695281_6c04b4984bf7f535daa6d347c4da68aa\" \/><\/p>\n<p>O secret\u00e1rio de sa\u00fade da cidade de Contendas do Sincor\u00e1,\u00a0Valdir Neres de Oliveira, fazia o trajeto, Sussuarana a Contendas e o motorista do caminh\u00e3o no sentido inverso.<\/p>\n<p>O corpo de Valdir ainda encontra-se preso as ferragens, a fam\u00edlia j\u00e1 \u00a0encontra-se no local e o Corpo de Bombeiro, acaba de chegar ao local, para retirada do corpo das ferragens.<\/p>\n<div>\n<div>\n<div title=\"21:33\" data-jsid=\"message\"><img style=\"font-size: 14px; line-height: 1.5em;\" alt=\"\" src=\"https:\/\/fbcdn-sphotos-h-a.akamaihd.net\/hphotos-ak-prn2\/v\/t34.0-12\/1459896_555516027895559_4866058168466183471_n.jpg?oh=afa55d17b4fb1fc4620a3899e7c9c39e&amp;oe=535EA58D&amp;__gda__=1398701661_42ab2f426c41ea024a9ddb8c50b5ff61\" \/><\/div>\n<\/div>\n<\/div>\n<div>\n<div title=\"21:33\" data-jsid=\"message\"><\/div>\n<div title=\"21:33\" data-jsid=\"message\">N\u00e3o ser\u00e3o postadas as fotos da v\u00edtima, em respeito a dor dessa fam\u00edlia.<\/div>\n<div title=\"21:33\" data-jsid=\"message\"><strong>Por Eliomar Barreira<\/strong><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Neste S\u00e1bado (26) por volta de 19:00hs, aconteceu um grave acidente automobil\u00edstico, com v\u00edtima fatal. A colis\u00e3o frontal envolvendo um caminh\u00e3o placa NYQ 2003 de Livramento de Nossa Senhora e um autom\u00f3vel Gol da secret\u00e1ria de sa\u00fade de Contendas, aconteceu\u00a0na\u00a0BR 407, KM 637, trecho entre Sussuarana e Contendas do Sincor\u00e1. O secret\u00e1rio de sa\u00fade da [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_links_to":"","_links_to_target":""},"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/posts\/7862"}],"collection":[{"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/comments?post=7862"}],"version-history":[{"count":2,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/posts\/7862\/revisions"}],"predecessor-version":[{"id":7864,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/posts\/7862\/revisions\/7864"}],"wp:attachment":[{"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/media?parent=7862"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/categories?post=7862"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/tags?post=7862"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}