{"id":8243,"date":"2014-05-03T20:57:19","date_gmt":"2014-05-03T23:57:19","guid":{"rendered":"http:\/\/www.blogdotarugao.com.br\/v1\/?p=8243"},"modified":"2014-05-03T20:57:19","modified_gmt":"2014-05-03T23:57:19","slug":"eles-querem-um-lar-elas-querem-uma-relacao","status":"publish","type":"post","link":"https:\/\/www.blogdotarugao.com.br\/v1\/2014\/05\/03\/eles-querem-um-lar-elas-querem-uma-relacao\/","title":{"rendered":"Eles querem um lar, elas querem uma rela\u00e7\u00e3o"},"content":{"rendered":"<h2 id=\"noticia-olho\">Terapeuta explica a diferen\u00e7a entre as expectativas masculinas e femininas sobre o prop\u00f3sito do casamento<\/h2>\n<div id=\"noticia\" itemprop=\"articleBody\">\n<figure><img alt=\"\" src=\"http:\/\/i0.statig.com.br\/bancodeimagens\/3k\/es\/tz\/3kestznyzttcpiemfdto95two.jpg\" \/><figcaption><cite>Thinkstock\/Getty Images<\/cite><\/p>\n<div>Descompasso: n\u00e3o fomos preparados para as complexidades do atual projeto de casamento<\/div>\n<\/figcaption><\/figure>\n<p>Muitos dos problemas de relacionamento podem ocorrer devido \u00e0s diferen\u00e7as entre as expectativas masculinas e femininas sobre o prop\u00f3sito do casamento. E porque as expectativas podem ser opostas?<\/p>\n<p>Porque homens costumam casar em busca de um lar e mulheres em busca de uma rela\u00e7\u00e3o a dois. Duas metas que dificilmente coincidem, e que levam a desgastantes mal-entendidos e eventuais separa\u00e7\u00f5es.<\/p>\n<p>No pr\u00f3ximo artigo falaremos sobre possibilidades de ajustar metas para que voc\u00eas possam ter uma verdadeira alian\u00e7a de vida. Mas ser\u00e1 que voc\u00eas t\u00eam mesmo expectativas desalinhadas? Leia a descri\u00e7\u00e3o abaixo e veja o quanto ela coincide ou n\u00e3o com seu caso.<\/p>\n<p><strong>Homens em busca de um lar<\/strong><\/p>\n<p>Fernando, ap\u00f3s uma solteirice de farras e tendo consolidado a carreira profissional, sentiu-se pronto para casar com Lucia. Leonardo estava cansado da rotina de conquistador. Via os amigos \u00e0 sua volta casando. Decidiu-se ent\u00e3o por M\u00e1rcia. Rog\u00e9rio, sempre foi t\u00edmido, ficou com a primeira que o escolheu e o aceitou. Ricardo casou-se por paix\u00e3o sonhando com uma Pen\u00e9lope &#8220;pau para toda obra&#8221; e sexo ousado.<\/p>\n<p>Todos vislumbravam um \u201clar, doce lar\u201d. Um lugar de sossego, apoio e sexo. Queriam se estabelecer, fundar uma fam\u00edlia, ter estabilidade, descansar da rotina de conquistas e sedu\u00e7\u00e3o. Poder ter uma vida mais confort\u00e1vel, aconchegante. Uma verdadeira casa, um lar, uma fam\u00edlia. E o que esperavam suas mulheres, Lucia, M\u00e1rcia e Pen\u00e9lope dos seus casamentos?<\/p>\n<p><strong>Mulheres em busca de uma rela\u00e7\u00e3o para compartilhar a vida<\/strong><\/p>\n<p>Elas imaginavam selar com o marido um pacto de uni\u00e3o. Uma uni\u00e3o para a aventura da vida. Pensavam que usufruiriam de uma rela\u00e7\u00e3o de intimidade profunda com um homem, que dividiriam com ele seus sonhos e medos, que teriam compartilhamento, cumplicidade e compromisso. Mas construir um lar n\u00e3o era a meta delas.<\/p>\n<p>Para uma mulher, casar naturalmente implica montar um lar e, eventualmente, ter filhos e poder ser m\u00e3e com o apoio do parceiro. Entretanto, cuidar da casa, decor\u00e1-la, criar um ambiente aconchegante, apoiar e cuidar do marido e dos filhos s\u00f3 costuma valer a pena para ela se em troca houver compartilhamento, investimento e satisfa\u00e7\u00e3o na rela\u00e7\u00e3o a dois. Enfim, se ela sentir que o parceiro e ela vivem uma vida entrela\u00e7ada e n\u00e3o duas vidas paralelas, sem intimidade. Rela\u00e7\u00e3o a dois e lar s\u00e3o projetos diferentes. Como voc\u00ea ver\u00e1 a seguir.<\/p>\n<p><strong>Os sonhos e desilus\u00f5es de Lucia<\/strong><\/p>\n<p>Lucia era a mais rom\u00e2ntica, queria ter com Fernando uma rela\u00e7\u00e3o de trocas intensas. Compartilhariam os relatos sobre as miudezas do cotidiano, fariam planos e juntos explorariam a vida.<\/p>\n<p>Para ela o namoro foi uma amostra do potencial da rela\u00e7\u00e3o. Como namorado ele era um verdadeiro cavalheiro, sempre prestativo e rom\u00e2ntico. Faziam viagens, programas prazerosos, tinham sonhos constru\u00eddos ao p\u00f4r-do-sol.<\/p>\n<p>Ela achava que tudo isto era s\u00f3 uma preliminar. Achava que agora, ao casar, come\u00e7aria a grande aventura a dois! N\u00e3o haveria mais tantas dist\u00e2ncias (moradias separadas, hor\u00e1rios e compromissos individuais) que atrapalhavam o cotidiano de amor. Queria tamb\u00e9m fundar uma fam\u00edlia, criar junto com Fernando dois ou tr\u00eas filhos.<\/p>\n<p>Que decep\u00e7\u00e3o para Lucia quando ao longo do tempo foi ficando claro que Fernando n\u00e3o buscava nada disso. Em casa, Fernando agora aprecia a rotina, o sossego, sugere irem ao restaurante que fica ao lado, que \u00e9 t\u00e3o pr\u00e1tico, ou pr\u00f3ximo, ou custa menos, ou que ele j\u00e1 conhece. S\u00f3 quer ler seu jornal, ou usa o tempo livre para encontrar seus amigos homens, colegas de trabalho, etc. Eventualmente, quando parece estar de verdade com ela, s\u00f3 ele quer contar do seu dia, mas na hora de ouvi-la, n\u00e3o interage, n\u00e3o se envolve com epis\u00f3dios que a ela parecem t\u00e3o significativos, mas que para ele s\u00e3o apenas hist\u00f3rias de mulherzinha.<\/p>\n<p>Ele mal nota seu empenho em promover a gra\u00e7a e o encanto da vida a dois, n\u00e3o enxerga os enfeites e arranjos da casa que ela tanto se esmerou em providenciar. Tudo a ele parecem miudezas irrelevantes. Aos poucos, aquele namorado rom\u00e2ntico, sintonizado, emp\u00e1tico, inventivo e interessante se revela uma fraude. Foi tudo uma sedu\u00e7\u00e3o provis\u00f3ria? Mesmo o sexo que ele tanto quer, ele apenas se disp\u00f5e a faz\u00ea-lo em casa e de modo conveniente, em hor\u00e1rios que para ele s\u00e3o pr\u00e1ticos, sem grande empenho (no m\u00e1ximo as preliminares protocolares, ou palavras rom\u00e2nticas reservadas para a ocasi\u00e3o sexual, ou uma aflita busca de informa\u00e7\u00e3o sobre se ela teve orgasmo, como que para confirmar a sua compet\u00eancia de macho).<\/p>\n<div>\n<aside>\n<h3>Fa\u00e7a o teste<\/h3>\n<ul>\n<li><a href=\"http:\/\/delas.ig.com.br\/amoresexo\/2012-10-23\/teste-o-seu-amor-e-tambem-seu-melhor-amigo.html\">O seu amor \u00e9 tamb\u00e9m seu melhor amigo?<\/a><\/li>\n<\/ul>\n<\/aside>\n<\/div>\n<p>Lucia agora percebe que foi enquadrada, tornou-se parte da moldura da vida dele. Queria tanto que ele fosse mais aventuroso, que celebrassem a vida, as datas, mas ele mal se lembra. Se ele n\u00e3o fosse sempre t\u00e3o pr\u00e1tico, t\u00e3o sem gra\u00e7a. Tudo o que restou a ela \u00e9 um cotidiano tarefeiro. Mesmo o lazer \u00e9 programado, previsto e recebe tantas restri\u00e7\u00f5es de or\u00e7amento, de datas e de prazos. Ela gostaria que o trabalho, os amigos, os hobbies, o brincar com os filhos e outras atividades dele n\u00e3o estivessem sempre em primeiro lugar antes dela, e que ela n\u00e3o fosse a \u00faltima op\u00e7\u00e3o quando finalmente sobra espa\u00e7o na agenda dele.<\/p>\n<p><strong>Leia:<\/strong>\u00a0<a href=\"http:\/\/delas.ig.com.br\/colunistas\/prazeresexo\/o+sexo+tem+espaco+na+sua+agenda\/c1597185628289.html\" target=\"_self\">O sexo tem espa\u00e7o na sua agenda?<\/a><\/p>\n<p>De in\u00edcio ela tenta se fazer notar. Depois tenta falar com ele, faz\u00ea-lo entender. Explicar o que \u00e9 investir na rela\u00e7\u00e3o, ser prioridade. Mas ele n\u00e3o a entende, \u201co que ela afinal quer dele?\u201d, \u201cAfinal j\u00e1 n\u00e3o basta estarem juntos?\u201d<\/p>\n<p>Ele reclama que ela cobra demais, ou ele zomba dos pedidos dela, \u00e0s vezes ele se fecha, silencia, ou vai enrolando. Mais adiante, ela, irritada, tenta se fazer escutar de modo mais contundente, aflita. Ele ainda parece n\u00e3o entender ou ser\u00e1 que n\u00e3o est\u00e1 ligando a m\u00ednima? Ela come\u00e7a a cobrar mais, a se tornar agressiva, amarga, entra em desespero e se torna irracional, descontrolada, sem paci\u00eancia at\u00e9 com os filhos que ela tanto ama. Aos poucos ela desiste, definha, confinada ao \u201clar doce lar\u201d sua seiva secou. Parou de lutar pela rela\u00e7\u00e3o. Eventualmente ela ter\u00e1 um amante, algu\u00e9m que parece not\u00e1-la, que a escuta, que a percebe (ao menos enquanto for amante).<\/p>\n<p>Nos casais atuais \u00e9 comum mulheres se sentirem mais insatisfeitas. Em m\u00e9dia 70% dos pedidos de div\u00f3rcio partem dela. Homens, mesmo insatisfeitos, tendam a \u201cir levando\u201d por mais tempo. Muitos percebem a vida de modo compartimentalizado e v\u00e3o compensando com outras v\u00e1lvulas de escape, elas vivem de modo mais interligado.<\/p>\n<p>Mulheres tendem a se estressar com a vida dom\u00e9stica, mesmo quando o marido divide com ela tarefas de casa e a cria\u00e7\u00e3o dos filhos. Elas tendem a ser mais tensas e perfeccionistas, eles costumam ter um olhar mais superficial, complacente e relaxado. Al\u00e9m disso, quando a mulher d\u00e1 uma pausa na carreira, ela tenta investir mais ainda na qualidade da rela\u00e7\u00e3o. Mas tromba com um homem menos treinado (e desinteressado?) em como sintonizar com outra pessoa. \u00c9 prov\u00e1vel que ela se frustre com a qualidade da rela\u00e7\u00e3o.<\/p>\n<p><strong>Os sonhos e desilus\u00f5es de Fernando<\/strong><\/p>\n<p>Fernando aos poucos tamb\u00e9m se v\u00ea numa armadilha. Onde ficou a namoradinha t\u00e3o companheira? Ent\u00e3o tudo era s\u00f3 sedu\u00e7\u00e3o at\u00e9 me fisgar? Quando as mulheres se sentem seguras passam a cobrar a conta? Ela cobra tanto e coisas t\u00e3o estranhas, e est\u00e1 sempre insatisfeita. Ela reclama ou porque eu disse algo que n\u00e3o deveria ter dito ou porque n\u00e3o disse algo que deveria ter dito. \u00c9 tudo muito complicado. Ela se ofende, se ressente e faz coment\u00e1rios \u00e1cidos. Conversar com ela \u00e9 insuport\u00e1vel, ela logo se exalta, e como chora, e como grita, acusa, se p\u00f5e como v\u00edtima. Ela \u00e9 t\u00e3o carente.<\/p>\n<p>Tudo que ele queria era um lar, um lugar de sossego, e o que tem hoje? Uma mulher ressentida e impaciente que o sufoca. N\u00e3o fazem mais sexo, ou quando o fazem, ela imp\u00f5e restri\u00e7\u00f5es moralistas \u00e0s fantasias dele e se mostra estressada por miudezas da vida. Ela se queixa de que ele n\u00e3o lhe d\u00e1 aten\u00e7\u00e3o, mas quando lhe d\u00e1 aten\u00e7\u00e3o ela n\u00e3o usufrui, diz que ele \u201cn\u00e3o pensa em nada\u201d, que para ele \u201ctudo \u00e9 f\u00e1cil e simples\u201d. Virou uma chata!<\/p>\n<figure><img alt=\"\" src=\"http:\/\/i0.statig.com.br\/bancodeimagens\/5d\/ct\/a3\/5dcta39rdrr5ji9uwyeyno5fi.jpg\" \/><figcaption><cite>Thinkstock\/Getty Images<\/cite><\/p>\n<div>As expectativas masculinas e femininas sobre o prop\u00f3sito do casamento s\u00e3o diferentes<\/div>\n<\/figcaption><\/figure>\n<p>Al\u00e9m disso, ela parece n\u00e3o suportar que ele descanse ou relaxe. Ao v\u00ea-lo sentado lendo o jornal ela logo pede que se levante para resolver agora, neste momento, alguma tarefa dom\u00e9stica. Seu senso de urg\u00eancia para resolver afazeres \u00e9 insensato, hist\u00e9rico, insuport\u00e1vel.<\/p>\n<p>Ele precisa de um respiradouro para fugir deste massacre: uma amante, leve, divertida, com a qual possa exercer os dotes de namorado rom\u00e2ntico, uma mulher meiga que o valorize, que lhe d\u00ea sossego, apoio e importante: sexo \u00e0 vontade e sem tantas restri\u00e7\u00f5es (ao menos enquanto for amante).<\/p>\n<p>\u00c9 claro que h\u00e1 casais em que as coisas acontecem de modo inverso, ele quer investir na rela\u00e7\u00e3o e ela n\u00e3o prioriza a vida a dois. E em outros casos pode ocorrer que ambos coincidam no prop\u00f3sito do casamento. Mas a maioria dos casais \u00e9 parecida com Fernando e Lucia descritos acima. Qual \u00e9 seu caso?<\/p>\n<p>N\u00e3o percebemos ainda qu\u00e3o complexo \u00e9 o atual projeto de felicidade no casamento. N\u00e3o fomos preparados para tal. Ainda pensamos que talvez o amor resolva tudo, ou que com bom senso equacionaremos as coisas. As estat\u00edsticas mostram que a maioria n\u00e3o consegue fazer isso. O n\u00famero crescente de div\u00f3rcios, o incremento das queixas e insatisfa\u00e7\u00e3o matrimonial e a dificuldade dos solteiros acharem algu\u00e9m, ou dos divorciados recasarem, s\u00e3o testemunhos da dificuldade em ajustar tantas expectativas. Este ser\u00e1 o tema do pr\u00f3ximo artigo: ajustes de casal.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Terapeuta explica a diferen\u00e7a entre as expectativas masculinas e femininas sobre o prop\u00f3sito do casamento Thinkstock\/Getty Images Descompasso: n\u00e3o fomos preparados para as complexidades do atual projeto de casamento Muitos dos problemas de relacionamento podem ocorrer devido \u00e0s diferen\u00e7as entre as expectativas masculinas e femininas sobre o prop\u00f3sito do casamento. E porque as expectativas podem [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_links_to":"","_links_to_target":""},"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/posts\/8243"}],"collection":[{"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/comments?post=8243"}],"version-history":[{"count":1,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/posts\/8243\/revisions"}],"predecessor-version":[{"id":8244,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/posts\/8243\/revisions\/8244"}],"wp:attachment":[{"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/media?parent=8243"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/categories?post=8243"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/tags?post=8243"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}