{"id":8362,"date":"2014-05-06T14:48:58","date_gmt":"2014-05-06T17:48:58","guid":{"rendered":"http:\/\/www.blogdotarugao.com.br\/v1\/?p=8362"},"modified":"2014-05-06T09:07:51","modified_gmt":"2014-05-06T12:07:51","slug":"conheca-programas-gratis-para-bloquear-pornografia-no-computador","status":"publish","type":"post","link":"https:\/\/www.blogdotarugao.com.br\/v1\/2014\/05\/06\/conheca-programas-gratis-para-bloquear-pornografia-no-computador\/","title":{"rendered":"Conhe\u00e7a programas gr\u00e1tis para bloquear pornografia no computador"},"content":{"rendered":"<div id=\"texto\">\n<p>A leitora Marlene entrou em contato com o\u00a0<strong>UOL Tecnologia<\/strong>\u00a0pedindo sugest\u00f5es de programas para bloquear pornografia em seu computador. Conhe\u00e7a a seguir tr\u00eas servi\u00e7os gratuitos e um pago para impedir a exibi\u00e7\u00e3o desse tipo de conte\u00fado \u2013 a dica \u00e9 especialmente \u00fatil para pais de filhos pequenos, que utilizam o computador.<\/p>\n<p><em>Se tiver alguma d\u00favida sobre tecnologia, envie um e-mail para<a href=\"mailto:uoltecnologia@uol.com.br?subject=D%C3%9AVIDA%20DO%20LEITOR\">uoltecnologia@uol.com.br<\/a>, que ela pode ser respondida.<\/em><\/p>\n<p><strong>Norton Safety\/Family<\/strong><\/p>\n<p>A vers\u00e3o gratuita do\u00a0<a href=\"http:\/\/zip.net\/bsmTyf\" target=\"_blank\"><strong>Norton Safety\/Family<\/strong><\/a>\u00a0tem um filtro de conte\u00fado voltado especialmente para o monitoramento infantil. Ap\u00f3s um breve cadastro, o usu\u00e1rio deve preencher campos com os dados de quem deseja monitorar (essa sele\u00e7\u00e3o \u00e9 feita mediante login utilizado para acessar a m\u00e1quina). \u00c9 poss\u00edvel adicionar ou remover crian\u00e7as a qualquer momento.<\/p>\n<div>Reprodu\u00e7\u00e3o<\/p>\n<div><img alt=\"\" src=\"http:\/\/imguol.com\/c\/noticias\/2014\/04\/29\/norton-safetyfamily-1398809229389_300x200.jpg\" \/><\/div>\n<p>Norton Safety\/Family oferece supervis\u00e3o da web, monitoramento de pesquisas e alertas por e-mail<\/p><\/div>\n<p>&nbsp;<\/p>\n<p>Com o uso de abas coloridas e organizadas, o administrador tem fun\u00e7\u00f5es como supervis\u00e3o da web, monitoramento de pesquisas e alertas por e-mail. O programa tem vers\u00f5es para PC, Mac e Android.<\/p>\n<p>Ele bloqueia e filtra sites espec\u00edficos ou com determinado conte\u00fado. O bloqueio funciona a partir da escolha de palavras-chave pr\u00e9-definidas. Caso o usu\u00e1rio n\u00e3o deseje que seus filhos vejam, por exemplo, conte\u00fado relacionado a pornografia ou bebidas alco\u00f3licas, basta marcar estes itens nas palavras-chave.<\/p>\n<p>O Norton Safety tem a op\u00e7\u00e3o de monitorar as redes sociais das crian\u00e7as. O administrador consegue ver assim como os jovens usu\u00e1rios se comportam e com quem mant\u00eam contato nesse ambiente \u2013\u00a0 os dados s\u00e3o apresentados por meio de uma p\u00e1gina com as informa\u00e7\u00f5es de navega\u00e7\u00e3o.<\/p>\n<p>A op\u00e7\u00e3o &#8220;Supervis\u00e3o de Pesquisa&#8221; permite que o administrador tenha acesso \u00e0s palavras mais pesquisadas pelas crian\u00e7as. O recurso facilita a filtragem de conte\u00fado impr\u00f3prio. A op\u00e7\u00e3o &#8220;Supervis\u00e3o de Tempo&#8221; permite que os pais delimitem o tempo, hor\u00e1rios e dias da semana em que as crian\u00e7as podem usar a internet.<\/p>\n<p><strong>Kurupira Webfilter\u00a0<\/strong><\/p>\n<div>Rerprodu\u00e7\u00e3o<\/p>\n<div><img alt=\"\" src=\"http:\/\/imguol.com\/c\/noticias\/2014\/04\/29\/kurupira-webfilter-1398809130333_300x200.jpg\" \/><\/div>\n<p>O Kurupira Webfilter permite bloquear sites, programas e configura\u00e7\u00f5es<\/p><\/div>\n<p>&nbsp;<\/p>\n<p>O\u00a0<a href=\"http:\/\/www.kurupira.net\/pt\" target=\"_blank\"><strong>Kurupira Webfilter<\/strong><\/a>\u00a0\u00e9 um software que permite filtrar o ambiente online, impedindo o usu\u00e1rio de visitar sites com conte\u00fado considerado impr\u00f3prio. O programa \u00e9 dividido em tr\u00eas abas denominadas &#8220;Internet&#8221;, &#8220;Programas&#8221; e &#8220;Configura\u00e7\u00f5es&#8221;. Nelas, \u00e9 poss\u00edvel bloquear sites e filtrar o conte\u00fado de forma personalizada.<\/p>\n<p>Sempre que inicializado, o Kurupira pede a senha cadastrada no primeiro acesso. Isso impede que outras pessoas tenham acesso aos controles do programa.<\/p>\n<p>O \u00fanico problema \u00e9 que o Kurupira pode proteger at\u00e9 demais. Eventualmente, ele barra sites e arquivos sem motivo aparente algum, mesmo sem palavras-chave classificadas como impr\u00f3prias.<\/p>\n<p><strong>InterApp Control\u00a0<\/strong><\/p>\n<div>Reprodu\u00e7\u00e3o<\/p>\n<div><img alt=\"\" src=\"http:\/\/imguol.com\/c\/noticias\/2014\/04\/29\/interapp-control-1398809057268_300x200.jpg\" \/><\/div>\n<p>O InterApp Control permite que o usu\u00e1rio bloqueie e filtre conte\u00fado online ou armazenado no PC<\/p><\/div>\n<p>&nbsp;<\/p>\n<p>Outra op\u00e7\u00e3o de prote\u00e7\u00e3o \u00e9 o software\u00a0<a href=\"http:\/\/zip.net\/bnmSLX\" target=\"_blank\"><strong>InterApp Control<\/strong><\/a>. Com toda sua interface separada em abas, ele permite que o usu\u00e1rio bloqueie e filtre conte\u00fado online ou armazenado no PC.<\/p>\n<p>O programa trabalha por meio de uma sele\u00e7\u00e3o de palavras-chaves. Qualquer item no computador ou na internet que contenha os termos proibidos n\u00e3o ser\u00e1 exibido no PC. Outro recurso \u00e9 o controle de permiss\u00f5es. O administrador da m\u00e1quina pode decidir quais usu\u00e1rios ter\u00e3o o conte\u00fado restringido.<\/p>\n<p>O software tamb\u00e9m pode ser configurado para atuar somente em determinados dias ou hor\u00e1rios.<\/p>\n<p><strong>Controle dos pais<\/strong><br \/>\nO\u00a0<a href=\"http:\/\/seguranca.uol.com.br\/controle-dos-pais\/#rmcl\" target=\"_self\"><strong>UOL Controle dos Pais<\/strong><\/a>\u00a0n\u00e3o \u00e9 uma op\u00e7\u00e3o gratuita: a mensalidade custa a partir de R$ 14,90. A ferramenta voltada a computadores compartilhados com crian\u00e7as permite bloquear palavras-chave, identificar imagens de nudez, restringir por senha o acesso a conte\u00fado adulto e definir os hor\u00e1rios de acesso \u00e0 internet, entre outros recursos.<\/p>\n<p>Nos recursos mais avan\u00e7ados da ferramenta, o adulto tamb\u00e9m consegue monitorar conversas em programas de bate-papo, ser alertado quando algum dado pessoal for divulgado nas redes sociais, controlar quem manda e-mails para seu filho, filtrar conte\u00fado do YouTube e receber alerta para tentativas de acesso indevido.<\/p>\n<div>\n<div id=\"albumHTML1\"><a id=\"btVerAlbumMaior1\" title=\"Acesse o \u00c1lbum\" href=\"http:\/\/tecnologia.uol.com.br\/album\/dicas_seguranca_internet_criancas_album.jhtm#fotoNav=1\"><br \/>\n<\/a><\/p>\n<div id=\"boxFullImage1\">\n<div id=\"fullImage1\">\n<div id=\"fullImageCenter1\" align=\"center\"><img id=\"fullImageSrc1\" alt=\"\" src=\"http:\/\/te.i.uol.com.br\/album\/dicas_seguranca_internet_criancas_f_001.jpg\" border=\"0\" \/><\/p>\n<h3>Dicas para pais mostram como os filhos podem usar a internet com seguran\u00e7a<\/h3>\n<\/div>\n<\/div>\n<div id=\"fotoLegendaBox1\">\n<div id=\"fotoLegenda1\">\n<div>\n<div>A cena j\u00e1 \u00e9 mais do que comum: seu filho em frente ao computador horas a fio e voc\u00ea nem sabe muito bem o que ele est\u00e1 fazendo. A internet, al\u00e9m de fonte de divers\u00e3o para as crian\u00e7as, tamb\u00e9m \u00e9 cheia de perigos e gente mal-intencionada. Isso n\u00e3o significa que voc\u00ea deva proibir a navega\u00e7\u00e3o online, mas \u00e9 preciso ficar atento a algumas boas pr\u00e1ticas. Veja a seguir dicas para pais sobre o uso seguro da internet pelas crian\u00e7as<\/p>\n<p><i>*Com informa\u00e7\u00f5es da AVG Technologies, Safernet e Guia para Uso da Internet Respons\u00e1vel 4.0<\/i>\u00a0<em>Think Stock<\/em><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<section id=\"veja-mais-texto\">\n<h1><\/h1>\n<\/section>\n","protected":false},"excerpt":{"rendered":"<p>A leitora Marlene entrou em contato com o\u00a0UOL Tecnologia\u00a0pedindo sugest\u00f5es de programas para bloquear pornografia em seu computador. Conhe\u00e7a a seguir tr\u00eas servi\u00e7os gratuitos e um pago para impedir a exibi\u00e7\u00e3o desse tipo de conte\u00fado \u2013 a dica \u00e9 especialmente \u00fatil para pais de filhos pequenos, que utilizam o computador. Se tiver alguma d\u00favida sobre [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_links_to":"","_links_to_target":""},"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/posts\/8362"}],"collection":[{"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/comments?post=8362"}],"version-history":[{"count":1,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/posts\/8362\/revisions"}],"predecessor-version":[{"id":8363,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/posts\/8362\/revisions\/8363"}],"wp:attachment":[{"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/media?parent=8362"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/categories?post=8362"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/tags?post=8362"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}