{"id":8434,"date":"2014-05-07T08:32:44","date_gmt":"2014-05-07T11:32:44","guid":{"rendered":"http:\/\/www.blogdotarugao.com.br\/v1\/?p=8434"},"modified":"2014-05-07T08:32:44","modified_gmt":"2014-05-07T11:32:44","slug":"pm-recupera-viatura-da-policia-civil","status":"publish","type":"post","link":"https:\/\/www.blogdotarugao.com.br\/v1\/2014\/05\/07\/pm-recupera-viatura-da-policia-civil\/","title":{"rendered":"PM recupera viatura da Pol\u00edcia Civil"},"content":{"rendered":"<div><img loading=\"lazy\" alt=\"\" src=\"http:\/\/bocaonews.com.br\/ckfinder\/userfiles\/files\/PM%20recupera%20viatura%20da%20Pol%C3%ADcia%20Civil%20no%20IAPI.JPG\" width=\"560\" height=\"420\" \/><\/div>\n<div id=\"cke_pastebin\">Policiais Militares da 37\u00aa Companhia Independente de Pol\u00edcia Militar (CIPM), sob o comando do Major Carlos Humberto, recuperaram na madrugada desta quarta-feira (7), em uma localidade conhecida como Rocinha, no bairro do IAPI, emSalvador, uma viatura descaracterizada pertencente a 13\u00aa Delegacia Territorial (DT), em Cajazeiras. De acordo com informa\u00e7\u00f5es da pol\u00edcia, o carro modelo Gol, gera\u00e7\u00e3o IV, foi furtado por bandidos que retiraram o r\u00e1dio e desligaram o GPS.\u00a0A viatura foi levada para a Delegacia de Repress\u00e3o a Furtos e Roubos de Ve\u00edculos (DRFRV), no Detran.<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Policiais Militares da 37\u00aa Companhia Independente de Pol\u00edcia Militar (CIPM), sob o comando do Major Carlos Humberto, recuperaram na madrugada desta quarta-feira (7), em uma localidade conhecida como Rocinha, no bairro do IAPI, emSalvador, uma viatura descaracterizada pertencente a 13\u00aa Delegacia Territorial (DT), em Cajazeiras. De acordo com informa\u00e7\u00f5es da pol\u00edcia, o carro modelo Gol, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_links_to":"","_links_to_target":""},"categories":[1,8],"tags":[],"_links":{"self":[{"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/posts\/8434"}],"collection":[{"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/comments?post=8434"}],"version-history":[{"count":1,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/posts\/8434\/revisions"}],"predecessor-version":[{"id":8435,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/posts\/8434\/revisions\/8435"}],"wp:attachment":[{"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/media?parent=8434"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/categories?post=8434"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/tags?post=8434"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}