{"id":8469,"date":"2014-05-07T17:25:48","date_gmt":"2014-05-07T20:25:48","guid":{"rendered":"http:\/\/www.blogdotarugao.com.br\/v1\/?p=8469"},"modified":"2014-05-07T17:25:48","modified_gmt":"2014-05-07T20:25:48","slug":"um-em-cada-cinco-brasileiros-sofreu-agressao-dos-pais-na-infancia","status":"publish","type":"post","link":"https:\/\/www.blogdotarugao.com.br\/v1\/2014\/05\/07\/um-em-cada-cinco-brasileiros-sofreu-agressao-dos-pais-na-infancia\/","title":{"rendered":"Um em cada cinco brasileiros sofreu agress\u00e3o dos pais na inf\u00e2ncia"},"content":{"rendered":"<div>\n<div><img title=\"Um em cada cinco brasileiros sofreu agress\u00e3o dos pais na inf\u00e2ncia\" alt=\"Um em cada cinco brasileiros sofreu agress\u00e3o dos pais na inf\u00e2ncia\" src=\"http:\/\/www.bahianoticias.com.br\/fotos\/saude_noticias\/11599\/xIMAGEM_NOTICIA_5.jpg.pagespeed.ic.L_kFAUoHsT.jpg\" \/><\/div>\n<div><\/div>\n<\/div>\n<div>Uma pesquisa divulgada nesta quarta-feira (7) mostrou que uma em cada cinco crian\u00e7as sofreram agress\u00f5es f\u00edsicas dos pais ou cuidadores. O 2\u00ba Levantamento Nacional de \u00c1lcool e Drogas (Lenad), realizado por pesquisadores da Unifesp, buscava analisar a rela\u00e7\u00e3o entre a viol\u00eancia sofrida na inf\u00e2ncia e o desenvolvimento de depend\u00eancia qu\u00edmica na fase adulta. De acordo com os pesquisadores, enquanto na popula\u00e7\u00e3o geral 21% dizem ter sido agredidos quando eram mais novos, entre os usu\u00e1rios de coca\u00edna o \u00edndice sobre para 52%. &#8220;Sabemos que sofrer estresse precoce afeta as mesmas \u00e1reas do c\u00e9rebro relacionadas com o desenvolvimento de depend\u00eancia qu\u00edmica, portanto, ser agredido \u00e9 um fator de risco para o uso de drogas&#8221;, diz Clarice Madruga, uma das coordenadoras do estudo. Foram ouvidas 4.607 pessoas em 149 munic\u00edpios brasileiros.<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Uma pesquisa divulgada nesta quarta-feira (7) mostrou que uma em cada cinco crian\u00e7as sofreram agress\u00f5es f\u00edsicas dos pais ou cuidadores. O 2\u00ba Levantamento Nacional de \u00c1lcool e Drogas (Lenad), realizado por pesquisadores da Unifesp, buscava analisar a rela\u00e7\u00e3o entre a viol\u00eancia sofrida na inf\u00e2ncia e o desenvolvimento de depend\u00eancia qu\u00edmica na fase adulta. De acordo [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_links_to":"","_links_to_target":""},"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/posts\/8469"}],"collection":[{"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/comments?post=8469"}],"version-history":[{"count":1,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/posts\/8469\/revisions"}],"predecessor-version":[{"id":8470,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/posts\/8469\/revisions\/8470"}],"wp:attachment":[{"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/media?parent=8469"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/categories?post=8469"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/tags?post=8469"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}