{"id":8760,"date":"2014-05-12T08:29:39","date_gmt":"2014-05-12T11:29:39","guid":{"rendered":"http:\/\/www.blogdotarugao.com.br\/v1\/?p=8760"},"modified":"2014-05-12T08:29:39","modified_gmt":"2014-05-12T11:29:39","slug":"tres-pessoas-morrem-eletrocutadas","status":"publish","type":"post","link":"https:\/\/www.blogdotarugao.com.br\/v1\/2014\/05\/12\/tres-pessoas-morrem-eletrocutadas\/","title":{"rendered":"Tr\u00eas pessoas morrem eletrocutadas"},"content":{"rendered":"<div><input type=\"image\" alt=\"\" src=\"http:\/\/www.bocaonews.com.br\/ckfinder\/userfiles\/files\/3%20PESSOAS%20MORRERAM%20EL%C3%89TROCUTADAS%20EM%20S%C3%83O%20JO%C3%83O%20DO%20PARA%C3%8DSO.jpg\" \/><\/div>\n<div id=\"cke_pastebin\">Uma trag\u00e9dia aconteceu no povoado de S\u00e3o Jo\u00e3o do Para\u00edso \u00e1s margens da BR-101, no distrito de Mascote no extremo Sul da Bahia no \u00faltimo s\u00e3bado (10).\n<\/div>\n<div id=\"cke_pastebin\">Duas casas pegaram fogo na \u00a0Rua Cl\u00e9riston Andrade e tr\u00eas pessoas morreram eletrocutadas por fios que ca\u00edram da rede el\u00e9trica. O motivo do inc\u00eandio ainda \u00e9 desconhecido.<\/p>\n<p>Foto: Itapebi Acontece<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Uma trag\u00e9dia aconteceu no povoado de S\u00e3o Jo\u00e3o do Para\u00edso \u00e1s margens da BR-101, no distrito de Mascote no extremo Sul da Bahia no \u00faltimo s\u00e3bado (10). Duas casas pegaram fogo na \u00a0Rua Cl\u00e9riston Andrade e tr\u00eas pessoas morreram eletrocutadas por fios que ca\u00edram da rede el\u00e9trica. O motivo do inc\u00eandio ainda \u00e9 desconhecido. Foto: [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_links_to":"","_links_to_target":""},"categories":[6,1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/posts\/8760"}],"collection":[{"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/comments?post=8760"}],"version-history":[{"count":2,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/posts\/8760\/revisions"}],"predecessor-version":[{"id":8763,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/posts\/8760\/revisions\/8763"}],"wp:attachment":[{"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/media?parent=8760"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/categories?post=8760"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/tags?post=8760"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}