{"id":9346,"date":"2014-05-20T22:27:38","date_gmt":"2014-05-21T01:27:38","guid":{"rendered":"http:\/\/www.blogdotarugao.com.br\/v1\/?p=9346"},"modified":"2014-05-20T22:27:38","modified_gmt":"2014-05-21T01:27:38","slug":"jaques-wagner-teria-indicado-negromonte-ao-tcm-afirma-colunista","status":"publish","type":"post","link":"https:\/\/www.blogdotarugao.com.br\/v1\/2014\/05\/20\/jaques-wagner-teria-indicado-negromonte-ao-tcm-afirma-colunista\/","title":{"rendered":"Jaques Wagner teria indicado Negromonte ao TCM, afirma colunista"},"content":{"rendered":"<p>Mario Negromonte pediu, Jaques Wagner aceitou e o indicou \u00e0 cadeira do Tribunal de Contas do Munic\u00edpio (TCM). Wagner enviou a nomea\u00e7\u00e3o hoje (20) para ser publicada no Di\u00e1rio Oficial amanh\u00e3 (21). O nome de Negromonte passar\u00e1 ainda pela Assembleia Legislativa baiana.<\/p>\n<p><input type=\"image\" alt=\"\" src=\"http:\/\/www.bocaonews.com.br\/ckfinder\/userfiles\/files\/mario-negromonte_reprodu%C3%A7ao_politicosdosuldabahia.jpeg\" \/><\/p>\n<p>A afirmativa publicada pelo colunista Lauro Jardim faz refer\u00eancia ao ex-ministro da pasta de Cidades do governo Dilma que deixou o cargo no ano de 2012 por suspeitas de participa\u00e7\u00e3o de reuni\u00e3o com o lobista de uma empresa de inform\u00e1tica interessada em contratos da pasta. \u00c0 \u00e9poca Negromonte teria negado favorecimento.<\/p>\n<p>Ainda segundo Jardim, o governador Jaques Wagner justificou a iniciativa da seguinte forma: \u201ctrata-se de uma costura pol\u00edtica. Ele disse que n\u00e3o queria mais se candidatar, e eu indiquei. N\u00e3o cabe a mim fazer ju\u00edzo de valor de uma pessoa que n\u00e3o foi condenada pela Justi\u00e7a\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mario Negromonte pediu, Jaques Wagner aceitou e o indicou \u00e0 cadeira do Tribunal de Contas do Munic\u00edpio (TCM). Wagner enviou a nomea\u00e7\u00e3o hoje (20) para ser publicada no Di\u00e1rio Oficial amanh\u00e3 (21). O nome de Negromonte passar\u00e1 ainda pela Assembleia Legislativa baiana. A afirmativa publicada pelo colunista Lauro Jardim faz refer\u00eancia ao ex-ministro da pasta [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_links_to":"","_links_to_target":""},"categories":[1,7],"tags":[],"_links":{"self":[{"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/posts\/9346"}],"collection":[{"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/comments?post=9346"}],"version-history":[{"count":1,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/posts\/9346\/revisions"}],"predecessor-version":[{"id":9347,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/posts\/9346\/revisions\/9347"}],"wp:attachment":[{"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/media?parent=9346"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/categories?post=9346"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/tags?post=9346"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}