{"id":9353,"date":"2014-05-21T08:18:11","date_gmt":"2014-05-21T11:18:11","guid":{"rendered":"http:\/\/www.blogdotarugao.com.br\/v1\/?p=9353"},"modified":"2014-05-21T08:18:11","modified_gmt":"2014-05-21T11:18:11","slug":"prefeituras-de-oito-cidades-do-interior-abrem-concursos-com-salarios-de-ate-r-92-mil-confira","status":"publish","type":"post","link":"https:\/\/www.blogdotarugao.com.br\/v1\/2014\/05\/21\/prefeituras-de-oito-cidades-do-interior-abrem-concursos-com-salarios-de-ate-r-92-mil-confira\/","title":{"rendered":"Prefeituras de oito cidades do interior abrem concursos com sal\u00e1rios de at\u00e9 R$ 9,2 mil; confira"},"content":{"rendered":"<p>S\u00e3o 895 vagas para todos os n\u00edveis de escolaridade, e os sal\u00e1rios chegam aos R$ 9,2 mil<\/p>\n<div>\n<p>Um sal\u00e1rio de R$ 9,2 mil \u00e9 o suficiente para uma vida confort\u00e1vel em Salvador. Mas se voc\u00ea morar em Arataca, a 500 quil\u00f4metros da capital, pode levar uma vida de magnata com esse dinheiro. O munic\u00edpio \u00e9 um dos oito na Bahia que est\u00e3o com concursos abertos. S\u00e3o 895 vagas para todos os n\u00edveis de escolaridade, e os sal\u00e1rios chegam aos R$ 9,2 mil mencionados acima.<\/p>\n<\/div>\n<div>\n<p>O prefeito de Arataca, Ferlu Mansur, conta que l\u00e1 o aluguel de uma casa boa, de dois quartos, numa regi\u00e3o nobre, custa entre R$ 300 e R$ 400. J\u00e1 o pre\u00e7o do prato em um dos dois restaurantes da cidade fica entre de R$ 10 e R$ 15. \u201cAqui \u00e9 tudo muito barato e bom de morar. E tem um clima \u00f3timo. No Inverno chega a 18\u00b0, e no Ver\u00e3o, a uns 32\u00b0\u201d, faz a sua propaganda.<\/p>\n<p>Moradora da cidade, a comerciante Maria das Neves Sousa Silva acrescenta que o p\u00e3o de sal custa R$ 0,25, e o quilo do frango, em sua mercearia, sai a R$ 5,20. A pequena cidade de pouco mais de 5 mil habitantes n\u00e3o possui nenhuma universidade, e a maioria da popula\u00e7\u00e3o vive da produ\u00e7\u00e3o de caf\u00e9 e de cacau, ou ent\u00e3o trabalha na pr\u00f3pria prefeitura.<\/p>\n<blockquote><p>Encontrar m\u00e9dico \u00e9 dif\u00edcil em qualquer lugar, imagine aqui. Temos s\u00f3 um cubano do Mais M\u00e9dicos<br \/>\nFerlu Mansur,\u00a0prefeito de Arataca<\/p><\/blockquote>\n<p>Neste contexto, \u00e9 dif\u00edcil encontrar pessoas qualificadas para ocupar postos como o de m\u00e9dico ou psic\u00f3logo. \u201cEncontrar m\u00e9dico \u00e9 dif\u00edcil em qualquer lugar, imagine aqui. Temos um cubano do Mais M\u00e9dicos, ele est\u00e1 trabalhando bem\u201d, conta o prefeito.<\/p>\n<p>O sal\u00e1rio de R$ 9,2 mil \u00e9 justamente para o cargo de m\u00e9dico de PSF. S\u00e3o duas vagas, al\u00e9m de outras cinco para o centro de sa\u00fade, pediatria e psiquiatria, mas nestes casos, os sal\u00e1rios (e a carga hor\u00e1ria) s\u00e3o menores. O mesmo concurso tamb\u00e9m tem vagas para psic\u00f3logos, enfermeiros, assistentes sociais, dentistas e nutricionistas, entre outros.<\/p>\n<p>Cris\u00f3polis<\/p>\n<p>Outro destaque \u00e9 o concurso da prefeitura de Cris\u00f3polis, a 215 quil\u00f4metros de Salvador. S\u00e3o 91 vagas, com sal\u00e1rios de at\u00e9 R$ 8,3 mil. L\u00e1, as vagas mais rent\u00e1veis tamb\u00e9m s\u00e3o na \u00e1rea de sa\u00fade: m\u00e9dicos, t\u00e9cnicos em radiologia e psic\u00f3logos. Mas h\u00e1 oportunidades em diversas \u00e1reas, inclusive vigilante, motorista e jardineiro.<\/p>\n<p>O prefeito Ednal Alves Costa conta que alugar uma casa de dois quartos, bem localizada, custa entre R$ 300 e R$ 500 por m\u00eas. Apenas para efeito de compara\u00e7\u00e3o, o aluguel de um quarto e sala na Pituba, em Salvador, custa entre R$ 1 mil e R$ 1,5 mil. \u201cPor R$ 1,5 mil aqui, voc\u00ea pode morar em uma mans\u00e3o\u201d, compara o prefeito.<\/p>\n<p>O quilo da comida no restaurante de seu Manoel custa R$ 14, e o p\u00e3o franc\u00eas, R$ 0,20. J\u00e1 em Salvador, os pre\u00e7os variam bastante, mas n\u00e3o \u00e9 dif\u00edcil encontrar o p\u00e3o por mais de R$ 1 e o quilo da comida em torno dos R$ 50. \u00a0Por l\u00e1, a situa\u00e7\u00e3o dos moradores \u00e9 parecida com a de Arataca. Pouca gente com n\u00edvel superior, a maioria vivendo da agricultura ou de emprego na prefeitura.<\/p>\n<p>Mas se voc\u00ea n\u00e3o se encaixou nas oportunidades anteriories, n\u00e3o precisa desistir. Outras seis cidades est\u00e3o com vagas abertas para os mais diversos perfis. Os sal\u00e1rios s\u00e3o menores, \u00e9 verdade, mas pode ficar certo de que R$ 2,5 mil em Abar\u00e9 v\u00e3o render muito mais do que o mesmo valor em Salvador.<\/p>\n<p>L\u00e1, existem \u00a0vagas para advogado, bi\u00f3logo, contador, educador f\u00edsico, agr\u00f4nomo, engenheiro ambiental, fisioterapeuta, t\u00e9cnico em contabilidade, t\u00e9cnico em edifica\u00e7\u00f5es e dezenas de outros cargos. Para ver a lista completa, acesse o edital pelo endere\u00e7o indicado no mapa ao lado. Mas corra, pois as inscri\u00e7\u00f5es terminam hoje.<\/p>\n<p>Tanha\u00e7u \u00e9 a cidade que oferece mais vagas: 207, com sal\u00e1rio de at\u00e9 R$ 2,2 mil. Os cargos em aberto s\u00e3o de arquiteto, engenheiro civil, procurador municipal, professor, agente administrativo, ajudante de biblioteca, auxiliar administrativo, operador de m\u00e1quinas leves e semipesadas, entre outros.<\/p>\n<p>Guarda municipal<\/p>\n<p>No munic\u00edpio de Umburanas, todas as vagas s\u00e3o para guarda municipal, com sal\u00e1rio de R$ 724. Ibiassuc\u00ea contrata assistente social, fonoaudi\u00f3logo, nutricionista, psic\u00f3logo, pedagogo, professor, agente administrativo, t\u00e9cnico de enfermagem, t\u00e9cnico de laborat\u00f3rio, t\u00e9cnico em radiologia, entre outros.<\/p>\n<p>Em Anguera, as vagas s\u00e3o para auxiliar e assistente administrativo, assistente de programas sociais, eletricista, tratorista, guarda municipal, agente de tributos, t\u00e9cnico de sa\u00fade bucal e outros.<\/p>\n<p>J\u00e1 a prefeitura de Rio de Contas tem vagas de at\u00e9 R$ 2,8 mil \u00a0para engenheiro civil e agr\u00f4nomo, t\u00e9cnico em licenciamento ambiental e em fiscaliza\u00e7\u00e3o ambiental, agente de sa\u00fade e \u00a0de endemias, etc. Veja os editais completos nos endere\u00e7os abaixo.<\/p>\n<table summary=\"\">\n<thead>\n<tr>\n<th scope=\"col\"><img loading=\"lazy\" alt=\"\" src=\"http:\/\/w2.c24hsttc.net\/uploads\/RTEmagicC_vagas_interior_mapa.jpg.jpg\" width=\"620\" height=\"683\" \/><\/th>\n<\/tr>\n<\/thead>\n<\/table>\n<\/div>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>S\u00e3o 895 vagas para todos os n\u00edveis de escolaridade, e os sal\u00e1rios chegam aos R$ 9,2 mil Um sal\u00e1rio de R$ 9,2 mil \u00e9 o suficiente para uma vida confort\u00e1vel em Salvador. Mas se voc\u00ea morar em Arataca, a 500 quil\u00f4metros da capital, pode levar uma vida de magnata com esse dinheiro. O munic\u00edpio \u00e9 [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_links_to":"","_links_to_target":""},"categories":[20,1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/posts\/9353"}],"collection":[{"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/comments?post=9353"}],"version-history":[{"count":1,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/posts\/9353\/revisions"}],"predecessor-version":[{"id":9354,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/posts\/9353\/revisions\/9354"}],"wp:attachment":[{"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/media?parent=9353"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/categories?post=9353"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/tags?post=9353"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}