{"id":9905,"date":"2014-05-29T12:54:25","date_gmt":"2014-05-29T15:54:25","guid":{"rendered":"http:\/\/www.blogdotarugao.com.br\/v1\/?p=9905"},"modified":"2014-05-29T12:54:25","modified_gmt":"2014-05-29T15:54:25","slug":"dentista-brasileira-e-morta-a-facadas-em-lisboa","status":"publish","type":"post","link":"https:\/\/www.blogdotarugao.com.br\/v1\/2014\/05\/29\/dentista-brasileira-e-morta-a-facadas-em-lisboa\/","title":{"rendered":"Dentista brasileira \u00e9 morta a facadas em Lisboa"},"content":{"rendered":"<div id=\"geral\">\n<section id=\"principal\"><\/section>\n<section id=\"conteudo\" itemprop=\"articleBody\">\n<h2 id=\"noticia-olho\">O principal suspeito pelo crime \u00e9 o marido dela, que n\u00e3o teria aceitado o pedido de div\u00f3rcio; ele foi preso em flagrante<\/h2>\n<div id=\"noticia\" itemprop=\"articleBody\">\n<figure><img alt=\"\" src=\"http:\/\/i0.statig.com.br\/bancodeimagens\/8m\/c9\/br\/8mc9bri1lg94km694zr772s4k.jpg\" \/><figcaption><cite>Reprodu\u00e7\u00e3o\/Correio da Manh\u00e3<\/cite><\/p>\n<div>Luana Camargo foi assassinada pelo marido na cl\u00ednica onde trabalhava, em Lisboa<\/div>\n<\/figcaption><\/figure>\n<p>A dentista brasileira Luana Pinheiro Golim Camargo,\u00a0de 28 anos, foi encontrada morta a facadas dentro de seu consult\u00f3rio em Lisboa, Portugal, na quarta-feira (28). O principal suspeito pelo assassinato \u00e9 o marido da dentista, que j\u00e1 foi preso.<\/p>\n<p>Segundo o jornal portugu\u00eas Correio da Manh\u00e3, o crime aconteceu por volta das 10h (6h no hor\u00e1rio de Bras\u00edlia).<\/p>\n<p>Marcos Camargo, 40 anos, teria entrado no consult\u00f3rio e se trancado com ela na sala de atendimento de Luana, onde a esfaqueou pelo menos cinco vezes.<\/p>\n<p>Depois, Camargo teria sa\u00eddo do local e esperado a pol\u00edcia enquanto tomava um caf\u00e9 a poucos metros do consult\u00f3rio. Ainda de acordo com o jornal, Marcos n\u00e3o aceitava o pedido de div\u00f3rcio feito pela dentista.<\/p>\n<div id=\"galleria\" data-render-gallery=\"nulltrue\">\n<div>\n<div>\n<div><img alt=\"\" src=\"http:\/\/i0.statig.com.br\/bancodeimagens\/6y\/ls\/8o\/6yls8o0ridybvda71rwfws954.jpg\" \/><\/div>\n<div><img alt=\"\" src=\"http:\/\/i0.statig.com.br\/bancodeimagens\/ae\/tq\/jo\/aetqjoxtkpnwwjkj8psttx49u.jpg\" \/><\/div>\n<\/div>\n<div><\/div>\n<\/div>\n<div>\n<div>\n<div>Luana era natural de Caiubu, cidade a 558 km de S\u00e3o Paulo, e morava em Portugal desde 2006, mesmo ano em que se casou com Camargo. A fam\u00edlia aguarda o traslado do corpo.<\/div>\n<\/div>\n<\/div>\n<\/div>\n<p>*Com Correio da Manh\u00e3<\/p>\n<p>&nbsp;<\/p>\n<\/div>\n<\/section>\n<div id=\"extra-content\">\n<div>\n<div id=\"thoth-recommendation-area\"><\/div>\n<div id=\"thoth-recommendation-area\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>O principal suspeito pelo crime \u00e9 o marido dela, que n\u00e3o teria aceitado o pedido de div\u00f3rcio; ele foi preso em flagrante Reprodu\u00e7\u00e3o\/Correio da Manh\u00e3 Luana Camargo foi assassinada pelo marido na cl\u00ednica onde trabalhava, em Lisboa A dentista brasileira Luana Pinheiro Golim Camargo,\u00a0de 28 anos, foi encontrada morta a facadas dentro de seu consult\u00f3rio [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_links_to":"","_links_to_target":""},"categories":[17,1,8],"tags":[],"_links":{"self":[{"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/posts\/9905"}],"collection":[{"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/comments?post=9905"}],"version-history":[{"count":1,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/posts\/9905\/revisions"}],"predecessor-version":[{"id":9906,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/posts\/9905\/revisions\/9906"}],"wp:attachment":[{"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/media?parent=9905"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/categories?post=9905"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.blogdotarugao.com.br\/v1\/wp-json\/wp\/v2\/tags?post=9905"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}